{"id":8707,"date":"2021-09-08T02:09:42","date_gmt":"2021-09-07T23:09:42","guid":{"rendered":"https:\/\/super-news.info\/pt\/branqueamento-de-capitais-um-problema-duas-solucoes\/"},"modified":"2021-09-08T02:09:45","modified_gmt":"2021-09-07T23:09:45","slug":"branqueamento-de-capitais-um-problema-duas-solucoes","status":"publish","type":"post","link":"https:\/\/super-news.info\/pt\/branqueamento-de-capitais-um-problema-duas-solucoes\/","title":{"rendered":"Branqueamento de capitais: um problema, duas solu\u00e7\u00f5es"},"content":{"rendered":"<p>\n            Um dos temas recorrentes em \u00e9pocas de campanha eleitoral \u00e9 o do financiamento dos partidos. Afinal, al\u00e9m de contarem com a subven\u00e7\u00e3o estatal prevista na lei, como \u00e9 que os partidos financiam as suas campanhas? Quem s\u00e3o os principais doadores? De onde vem o dinheiro? Recentemente, a diplomata Ana Gomes abordou o tema no Twitter, concretamente a dificuldade de identificar as doa\u00e7\u00f5es recebidas pelos partidos, sobretudo quando s\u00e3o utilizados como meio de pagamento as refer\u00eancias multibanco e o MBWay.As quest\u00f5es s\u00e3o pertinentes, uma vez que todos concordamos que conhecer a origem dos financiamentos contribui para uma maior transpar\u00eancia e ajuda a cimentar a confian\u00e7a dos cidad\u00e3os no sistema pol\u00edtico.Mas n\u00e3o \u00e9 apenas na pol\u00edtica que a transpar\u00eancia emerge como um pilar essencial para o bom funcionamento do sistema. Tamb\u00e9m no mundo empresarial e financeiro, a confian\u00e7a alcan\u00e7a-se pela ado\u00e7\u00e3o de pr\u00e1ticas e processos clarificadores e transparentes. S\u00f3 atrav\u00e9s do conhecimento da origem dos fluxos de dinheiro e de uma maior partilha de informa\u00e7\u00e3o conseguiremos debelar os problemas relacionados com o branqueamento de capitais ou o financiamento ao terrorismo \u2013 que surgem como amea\u00e7as crescentes \u00e0 democracia moderna.Para combater estes problemas precisamos das ferramentas adequadas. E \u00e9 aqui que esbarramos contra um muro que urge derrubar. Apesar da lei n\u00ba83\/2017 definir um exaustivo conjunto de medidas e obriga\u00e7\u00f5es de combate ao branqueamento de capitais e de termos uma regula\u00e7\u00e3o forte e exigente, os instrumentos que as institui\u00e7\u00f5es financeiras t\u00eam ao seu dispor para ajudar a identificar e a combater os fluxos de dinheiro il\u00edcitos s\u00e3o arcaicos. \u00c9 como se estiv\u00e9ssemos a enfrentar um inimigo sofisticado usando uma simples espada de madeira.<\/p>\n<p>        PUB \u2022 CONTINUE A LER A SEGUIR<\/p>\n<p>        Num contexto pautado por r\u00e1pidas transforma\u00e7\u00f5es e pela crescente sofistica\u00e7\u00e3o dos esquemas usados em burlas e opera\u00e7\u00f5es de branqueamento de capitais \u00e9, pois, crucial dotar as institui\u00e7\u00f5es dos instrumentos adequados para fazer cumprir a lei. E para isso n\u00e3o \u00e9 necess\u00e1rio \u201cinventar a roda\u201d, basta implementar duas simples medidas.Em primeiro lugar, considero fundamental definir como regra a disponibiliza\u00e7\u00e3o da informa\u00e7\u00e3o relativa ao IBAN e ao n\u00famero de identifica\u00e7\u00e3o fiscal (NIF) do ordenante e do destinat\u00e1rio de qualquer movimento financeiro. Esta quest\u00e3o \u00e9 particularmente importante, uma vez que a maioria das transa\u00e7\u00f5es em Portugal tem por base refer\u00eancias multibanco, que dificultam a identifica\u00e7\u00e3o dos benefici\u00e1rios destas opera\u00e7\u00f5es. O mesmo acontece com as transa\u00e7\u00f5es feitas atrav\u00e9s do sistema MBWay. Com o acesso a estes elementos (IBAN E NIF), o sistema financeiro conseguiria identificar mais rapidamente as opera\u00e7\u00f5es suspeitas de lavagem de dinheiro.Em segundo lugar, a realiza\u00e7\u00e3o de um match entre um IBAN e o NIF do destinat\u00e1rio de uma transfer\u00eancia banc\u00e1ria \u00e9 tamb\u00e9m uma forma de conferir uma maior seguran\u00e7a nas transa\u00e7\u00f5es financeiras. Desta forma, garantimos que ao fazer uma transfer\u00eancia estamos a entregar o dinheiro \u00e0 pessoa\/entidade certa. Este servi\u00e7o j\u00e1 \u00e9 utilizado pela Autoridade Tribut\u00e1ria e seria interessante disponibiliz\u00e1-lo de uma forma mais abrangente em Portugal, pois \u00e9 um instrumento importante no combate a burlas e ataques cibern\u00e9ticos.Estes s\u00e3o apenas dois exemplos de medidas simples que permitiriam acabar com a opacidade verificada em algumas tipologias de movimentos financeiros, proteger os consumidores e empresas de burlas e esquemas fraudulentos, detetar opera\u00e7\u00f5es suspeitas de branqueamento de capitais e, em \u00faltima inst\u00e2ncia, fomentar a confian\u00e7a dos cidad\u00e3os.Sim: \u00e9 certo que a implementa\u00e7\u00e3o destas medidas implica um investimento na adapta\u00e7\u00e3o dos sistemas de reporte financeiro. Sim: vai levar tempo para que estes instrumentos estejam operacionais. Mas parece-me incontorn\u00e1vel come\u00e7armos j\u00e1 hoje a trabalhar no desenvolvimento de solu\u00e7\u00f5es que melhorem a transpar\u00eancia do sistema financeiro e protejam os cidad\u00e3os.<\/p>\n<p>\tReceba um alerta sempre que Sebasti\u00e3o Lancastre publique um novo artigo.<br \/>\n\t\tSeguir<\/p>\n<p>\n<!--noindex--><br \/>\n<a href=\"https:\/\/observador.pt\/opiniao\/branqueamento-de-capitais-um-problema-duas-solucoes\/\" rel=\"nofollow\">Source link <\/a><br \/>\n<!--\/noindex--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um dos temas recorrentes em \u00e9pocas de campanha eleitoral \u00e9 o do financiamento dos partidos. Afinal, al\u00e9m de contarem com a subven\u00e7\u00e3o estatal prevista na lei, como \u00e9 que os partidos financiam as suas campanhas? Quem s\u00e3o os principais doadores? De onde vem o dinheiro? Recentemente, a diplomata Ana Gomes abordou o tema no Twitter, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":8708,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-8707","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-financeiras"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Branqueamento de capitais: um problema, duas solu\u00e7\u00f5es - Super News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/super-news.info\/pt\/branqueamento-de-capitais-um-problema-duas-solucoes\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Branqueamento de capitais: um problema, duas solu\u00e7\u00f5es - Super News\" \/>\n<meta property=\"og:description\" content=\"Um dos temas recorrentes em \u00e9pocas de campanha eleitoral \u00e9 o do financiamento dos partidos. Afinal, al\u00e9m de contarem com a subven\u00e7\u00e3o estatal prevista na lei, como \u00e9 que os partidos financiam as suas campanhas? Quem s\u00e3o os principais doadores? De onde vem o dinheiro? Recentemente, a diplomata Ana Gomes abordou o tema no Twitter, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/super-news.info\/pt\/branqueamento-de-capitais-um-problema-duas-solucoes\/\" \/>\n<meta property=\"og:site_name\" content=\"Super News\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-07T23:09:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-07T23:09:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/super-news.info\/pt\/wp-content\/uploads\/sites\/2\/2021\/09\/Branqueamento-de-capitais-um-problema-duas-solucoes.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"467\" \/>\n\t<meta property=\"og:image:height\" content=\"467\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"super-news\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"super-news\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/super-news.info\\\/pt\\\/branqueamento-de-capitais-um-problema-duas-solucoes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/pt\\\/branqueamento-de-capitais-um-problema-duas-solucoes\\\/\"},\"author\":{\"name\":\"super-news\",\"@id\":\"https:\\\/\\\/super-news.info\\\/pt\\\/#\\\/schema\\\/person\\\/2d4068cb2f39cd10008c2fce578a7356\"},\"headline\":\"Branqueamento de capitais: um problema, duas solu\u00e7\u00f5es\",\"datePublished\":\"2021-09-07T23:09:42+00:00\",\"dateModified\":\"2021-09-07T23:09:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/pt\\\/branqueamento-de-capitais-um-problema-duas-solucoes\\\/\"},\"wordCount\":681,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/pt\\\/branqueamento-de-capitais-um-problema-duas-solucoes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/super-news.info\\\/pt\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/09\\\/Branqueamento-de-capitais-um-problema-duas-solucoes.jpg\",\"articleSection\":[\"NOT\u00cdCIAS FINANCEIRAS\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/super-news.info\\\/pt\\\/branqueamento-de-capitais-um-problema-duas-solucoes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/super-news.info\\\/pt\\\/branqueamento-de-capitais-um-problema-duas-solucoes\\\/\",\"url\":\"https:\\\/\\\/super-news.info\\\/pt\\\/branqueamento-de-capitais-um-problema-duas-solucoes\\\/\",\"name\":\"Branqueamento de capitais: um problema, duas solu\u00e7\u00f5es - Super News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/pt\\\/branqueamento-de-capitais-um-problema-duas-solucoes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/pt\\\/branqueamento-de-capitais-um-problema-duas-solucoes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/super-news.info\\\/pt\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/09\\\/Branqueamento-de-capitais-um-problema-duas-solucoes.jpg\",\"datePublished\":\"2021-09-07T23:09:42+00:00\",\"dateModified\":\"2021-09-07T23:09:45+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/pt\\\/#\\\/schema\\\/person\\\/2d4068cb2f39cd10008c2fce578a7356\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/pt\\\/branqueamento-de-capitais-um-problema-duas-solucoes\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/super-news.info\\\/pt\\\/branqueamento-de-capitais-um-problema-duas-solucoes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/super-news.info\\\/pt\\\/branqueamento-de-capitais-um-problema-duas-solucoes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/super-news.info\\\/pt\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/09\\\/Branqueamento-de-capitais-um-problema-duas-solucoes.jpg\",\"contentUrl\":\"https:\\\/\\\/super-news.info\\\/pt\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/09\\\/Branqueamento-de-capitais-um-problema-duas-solucoes.jpg\",\"width\":467,\"height\":467,\"caption\":\"Branqueamento de capitais: um problema, duas solu\u00e7\u00f5es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/super-news.info\\\/pt\\\/branqueamento-de-capitais-um-problema-duas-solucoes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430\",\"item\":\"https:\\\/\\\/super-news.info\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Branqueamento de capitais: um problema, duas solu\u00e7\u00f5es\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/super-news.info\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/super-news.info\\\/pt\\\/\",\"name\":\"Super News\",\"description\":\"Super News Portugal\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/super-news.info\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/super-news.info\\\/pt\\\/#\\\/schema\\\/person\\\/2d4068cb2f39cd10008c2fce578a7356\",\"name\":\"super-news\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g\",\"caption\":\"super-news\"},\"url\":\"https:\\\/\\\/super-news.info\\\/pt\\\/author\\\/pt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Branqueamento de capitais: um problema, duas solu\u00e7\u00f5es - Super News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/super-news.info\/pt\/branqueamento-de-capitais-um-problema-duas-solucoes\/","og_locale":"pt_PT","og_type":"article","og_title":"Branqueamento de capitais: um problema, duas solu\u00e7\u00f5es - Super News","og_description":"Um dos temas recorrentes em \u00e9pocas de campanha eleitoral \u00e9 o do financiamento dos partidos. Afinal, al\u00e9m de contarem com a subven\u00e7\u00e3o estatal prevista na lei, como \u00e9 que os partidos financiam as suas campanhas? Quem s\u00e3o os principais doadores? De onde vem o dinheiro? Recentemente, a diplomata Ana Gomes abordou o tema no Twitter, [&hellip;]","og_url":"https:\/\/super-news.info\/pt\/branqueamento-de-capitais-um-problema-duas-solucoes\/","og_site_name":"Super News","article_published_time":"2021-09-07T23:09:42+00:00","article_modified_time":"2021-09-07T23:09:45+00:00","og_image":[{"width":467,"height":467,"url":"https:\/\/super-news.info\/pt\/wp-content\/uploads\/sites\/2\/2021\/09\/Branqueamento-de-capitais-um-problema-duas-solucoes.jpg","type":"image\/jpeg"}],"author":"super-news","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"super-news","Tempo estimado de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/super-news.info\/pt\/branqueamento-de-capitais-um-problema-duas-solucoes\/#article","isPartOf":{"@id":"https:\/\/super-news.info\/pt\/branqueamento-de-capitais-um-problema-duas-solucoes\/"},"author":{"name":"super-news","@id":"https:\/\/super-news.info\/pt\/#\/schema\/person\/2d4068cb2f39cd10008c2fce578a7356"},"headline":"Branqueamento de capitais: um problema, duas solu\u00e7\u00f5es","datePublished":"2021-09-07T23:09:42+00:00","dateModified":"2021-09-07T23:09:45+00:00","mainEntityOfPage":{"@id":"https:\/\/super-news.info\/pt\/branqueamento-de-capitais-um-problema-duas-solucoes\/"},"wordCount":681,"commentCount":0,"image":{"@id":"https:\/\/super-news.info\/pt\/branqueamento-de-capitais-um-problema-duas-solucoes\/#primaryimage"},"thumbnailUrl":"https:\/\/super-news.info\/pt\/wp-content\/uploads\/sites\/2\/2021\/09\/Branqueamento-de-capitais-um-problema-duas-solucoes.jpg","articleSection":["NOT\u00cdCIAS FINANCEIRAS"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/super-news.info\/pt\/branqueamento-de-capitais-um-problema-duas-solucoes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/super-news.info\/pt\/branqueamento-de-capitais-um-problema-duas-solucoes\/","url":"https:\/\/super-news.info\/pt\/branqueamento-de-capitais-um-problema-duas-solucoes\/","name":"Branqueamento de capitais: um problema, duas solu\u00e7\u00f5es - Super News","isPartOf":{"@id":"https:\/\/super-news.info\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/super-news.info\/pt\/branqueamento-de-capitais-um-problema-duas-solucoes\/#primaryimage"},"image":{"@id":"https:\/\/super-news.info\/pt\/branqueamento-de-capitais-um-problema-duas-solucoes\/#primaryimage"},"thumbnailUrl":"https:\/\/super-news.info\/pt\/wp-content\/uploads\/sites\/2\/2021\/09\/Branqueamento-de-capitais-um-problema-duas-solucoes.jpg","datePublished":"2021-09-07T23:09:42+00:00","dateModified":"2021-09-07T23:09:45+00:00","author":{"@id":"https:\/\/super-news.info\/pt\/#\/schema\/person\/2d4068cb2f39cd10008c2fce578a7356"},"breadcrumb":{"@id":"https:\/\/super-news.info\/pt\/branqueamento-de-capitais-um-problema-duas-solucoes\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/super-news.info\/pt\/branqueamento-de-capitais-um-problema-duas-solucoes\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/super-news.info\/pt\/branqueamento-de-capitais-um-problema-duas-solucoes\/#primaryimage","url":"https:\/\/super-news.info\/pt\/wp-content\/uploads\/sites\/2\/2021\/09\/Branqueamento-de-capitais-um-problema-duas-solucoes.jpg","contentUrl":"https:\/\/super-news.info\/pt\/wp-content\/uploads\/sites\/2\/2021\/09\/Branqueamento-de-capitais-um-problema-duas-solucoes.jpg","width":467,"height":467,"caption":"Branqueamento de capitais: um problema, duas solu\u00e7\u00f5es"},{"@type":"BreadcrumbList","@id":"https:\/\/super-news.info\/pt\/branqueamento-de-capitais-um-problema-duas-solucoes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430","item":"https:\/\/super-news.info\/pt\/"},{"@type":"ListItem","position":2,"name":"Branqueamento de capitais: um problema, duas solu\u00e7\u00f5es"}]},{"@type":"WebSite","@id":"https:\/\/super-news.info\/pt\/#website","url":"https:\/\/super-news.info\/pt\/","name":"Super News","description":"Super News Portugal","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/super-news.info\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/super-news.info\/pt\/#\/schema\/person\/2d4068cb2f39cd10008c2fce578a7356","name":"super-news","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g","caption":"super-news"},"url":"https:\/\/super-news.info\/pt\/author\/pt\/"}]}},"_links":{"self":[{"href":"https:\/\/super-news.info\/pt\/wp-json\/wp\/v2\/posts\/8707","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/super-news.info\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/super-news.info\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/super-news.info\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/super-news.info\/pt\/wp-json\/wp\/v2\/comments?post=8707"}],"version-history":[{"count":1,"href":"https:\/\/super-news.info\/pt\/wp-json\/wp\/v2\/posts\/8707\/revisions"}],"predecessor-version":[{"id":8709,"href":"https:\/\/super-news.info\/pt\/wp-json\/wp\/v2\/posts\/8707\/revisions\/8709"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/super-news.info\/pt\/wp-json\/wp\/v2\/media\/8708"}],"wp:attachment":[{"href":"https:\/\/super-news.info\/pt\/wp-json\/wp\/v2\/media?parent=8707"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/super-news.info\/pt\/wp-json\/wp\/v2\/categories?post=8707"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/super-news.info\/pt\/wp-json\/wp\/v2\/tags?post=8707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}