{"id":5035,"date":"2020-09-19T14:45:25","date_gmt":"2020-09-19T11:45:25","guid":{"rendered":"https:\/\/super-news.info\/pt\/pev-questiona-governo-sobre-atraso-da-atualizacao-de-pensoes-por-acidente-de-trabalho-observador\/"},"modified":"2020-09-19T14:45:27","modified_gmt":"2020-09-19T11:45:27","slug":"pev-questiona-governo-sobre-atraso-da-atualizacao-de-pensoes-por-acidente-de-trabalho-observador","status":"publish","type":"post","link":"https:\/\/super-news.info\/pt\/pev-questiona-governo-sobre-atraso-da-atualizacao-de-pensoes-por-acidente-de-trabalho-observador\/","title":{"rendered":"PEV questiona Governo sobre atraso da atualiza\u00e7\u00e3o de pens\u00f5es por acidente de trabalho \u2013 Observador"},"content":{"rendered":"<p><\/p>\n<p>            O Partido Ecologista \u201cOs Verdes\u201d (PEV) questionou este s\u00e1bado o Governo, atrav\u00e9s do parlamento, sobre o atraso na atualiza\u00e7\u00e3o das pens\u00f5es por acidente de trabalho, considerando que n\u00e3o h\u00e1 \u201craz\u00f5es atend\u00edveis\u201d para isso.<\/p>\n<p>Numa pergunta enviada aos Minist\u00e9rios das Finan\u00e7as e do Trabalho, Solidariedade e Seguran\u00e7a Social, a deputada do PEV Mariana Silva alega que n\u00e3o existem \u201craz\u00f5es atend\u00edveis\u201d para a falta de publica\u00e7\u00e3o da portaria de atualiza\u00e7\u00e3o destas pens\u00f5es para 2020.Para os Verdes, \u201cimporta que esta situa\u00e7\u00e3o seja resolvida o mais rapidamente poss\u00edvel, a fim de evitar os atrasos que se t\u00eam verificado nos \u00faltimos anos nesta mat\u00e9ria, com s\u00e9rios preju\u00edzos para os pensionistas afetados\u201d.Estas pens\u00f5es \u201ct\u00eam uma natureza compensat\u00f3ria ou indemnizat\u00f3ria dos danos sofridos no trabalho e por causa do trabalho\u201d e cabe \u201c\u00e0 entidade patronal ao servi\u00e7o da qual o trabalhador teve um acidente de trabalho a responsabilidade pela repara\u00e7\u00e3o e pelos encargos decorrentes de acidente de trabalho, bem como pela manuten\u00e7\u00e3o no posto de trabalho ap\u00f3s o acidente\u201d, ainda segundo o PEV.Segundo a lei, argumenta a deputada Mariana Silva, a entidade empregadora \u201c\u00e9 obrigada a transferir a responsabilidade\u201d para \u201centidades legalmente autorizadas a realizar o seguro de acidentes de trabalho\u201d.O PEV pergunta aos dois minist\u00e9rios por que motivo n\u00e3o foi ainda publicada a atualiza\u00e7\u00e3o das pens\u00f5es por acidente de trabalho para 2020 e quando prev\u00ea faz\u00ea-lo.<\/p>\n<p>Em 2019, a portaria foi publicada logo a 17 de janeiro, com um aumento de 1,6% relativamente ao ano anterior.Segundo dados da Autoridade para as Condi\u00e7\u00f5es de Trabalho (ACT), em 2018 morreram 131 pessoas (mais 12 do que no ano anterior) e 337 (menos 45) ficaram feridas com gravidade em acidentes laborais.Entre 2014 e 2018, a ACT registou 663 v\u00edtimas mortais e mais de 1.700 feridos graves.<\/p>\n<p>\n<!--noindex--><br \/>\n<a href=\"https:\/\/observador.pt\/2020\/09\/19\/pev-questiona-governo-sobre-atraso-da-atualizacao-de-pensoes-por-acidente-de-trabalho\/\" rel=\"nofollow\">Source link <\/a><br \/>\n<!--\/noindex--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Partido Ecologista \u201cOs Verdes\u201d (PEV) questionou este s\u00e1bado o Governo, atrav\u00e9s do parlamento, sobre o atraso na atualiza\u00e7\u00e3o das pens\u00f5es por acidente de trabalho, considerando que n\u00e3o h\u00e1 \u201craz\u00f5es atend\u00edveis\u201d para isso. Numa pergunta enviada aos Minist\u00e9rios das Finan\u00e7as e do Trabalho, Solidariedade e Seguran\u00e7a Social, a deputada do PEV Mariana Silva alega que [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":5036,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-5035","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-financeiras"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PEV questiona Governo sobre atraso da atualiza\u00e7\u00e3o de pens\u00f5es por acidente de trabalho \u2013 Observador - Super News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/super-news.info\/pt\/pev-questiona-governo-sobre-atraso-da-atualizacao-de-pensoes-por-acidente-de-trabalho-observador\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PEV questiona Governo sobre atraso da atualiza\u00e7\u00e3o de pens\u00f5es por acidente de trabalho \u2013 Observador - Super News\" \/>\n<meta property=\"og:description\" content=\"O Partido Ecologista \u201cOs Verdes\u201d (PEV) questionou este s\u00e1bado o Governo, atrav\u00e9s do parlamento, sobre o atraso na atualiza\u00e7\u00e3o das pens\u00f5es por acidente de trabalho, considerando que n\u00e3o h\u00e1 \u201craz\u00f5es atend\u00edveis\u201d para isso. Numa pergunta enviada aos Minist\u00e9rios das Finan\u00e7as e do Trabalho, Solidariedade e Seguran\u00e7a Social, a deputada do PEV Mariana Silva alega que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/super-news.info\/pt\/pev-questiona-governo-sobre-atraso-da-atualizacao-de-pensoes-por-acidente-de-trabalho-observador\/\" \/>\n<meta property=\"og:site_name\" content=\"Super News\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-19T11:45:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-19T11:45:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/super-news.info\/pt\/wp-content\/uploads\/sites\/2\/2020\/09\/PEV-questiona-Governo-sobre-atraso-da-atualiza-o-de-pens-es-por.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"770\" \/>\n\t<meta property=\"og:image:height\" content=\"433\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"super-news\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"super-news\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/super-news.info\\\/pt\\\/pev-questiona-governo-sobre-atraso-da-atualizacao-de-pensoes-por-acidente-de-trabalho-observador\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/pt\\\/pev-questiona-governo-sobre-atraso-da-atualizacao-de-pensoes-por-acidente-de-trabalho-observador\\\/\"},\"author\":{\"name\":\"super-news\",\"@id\":\"https:\\\/\\\/super-news.info\\\/pt\\\/#\\\/schema\\\/person\\\/2d4068cb2f39cd10008c2fce578a7356\"},\"headline\":\"PEV questiona Governo sobre atraso da atualiza\u00e7\u00e3o de pens\u00f5es por acidente de trabalho \u2013 Observador\",\"datePublished\":\"2020-09-19T11:45:25+00:00\",\"dateModified\":\"2020-09-19T11:45:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/pt\\\/pev-questiona-governo-sobre-atraso-da-atualizacao-de-pensoes-por-acidente-de-trabalho-observador\\\/\"},\"wordCount\":332,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/pt\\\/pev-questiona-governo-sobre-atraso-da-atualizacao-de-pensoes-por-acidente-de-trabalho-observador\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/super-news.info\\\/pt\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/09\\\/PEV-questiona-Governo-sobre-atraso-da-atualiza-o-de-pens-es-por.jpg\",\"articleSection\":[\"NOT\u00cdCIAS FINANCEIRAS\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/super-news.info\\\/pt\\\/pev-questiona-governo-sobre-atraso-da-atualizacao-de-pensoes-por-acidente-de-trabalho-observador\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/super-news.info\\\/pt\\\/pev-questiona-governo-sobre-atraso-da-atualizacao-de-pensoes-por-acidente-de-trabalho-observador\\\/\",\"url\":\"https:\\\/\\\/super-news.info\\\/pt\\\/pev-questiona-governo-sobre-atraso-da-atualizacao-de-pensoes-por-acidente-de-trabalho-observador\\\/\",\"name\":\"PEV questiona Governo sobre atraso da atualiza\u00e7\u00e3o de pens\u00f5es por acidente de trabalho \u2013 Observador - Super News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/pt\\\/pev-questiona-governo-sobre-atraso-da-atualizacao-de-pensoes-por-acidente-de-trabalho-observador\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/pt\\\/pev-questiona-governo-sobre-atraso-da-atualizacao-de-pensoes-por-acidente-de-trabalho-observador\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/super-news.info\\\/pt\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/09\\\/PEV-questiona-Governo-sobre-atraso-da-atualiza-o-de-pens-es-por.jpg\",\"datePublished\":\"2020-09-19T11:45:25+00:00\",\"dateModified\":\"2020-09-19T11:45:27+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/pt\\\/#\\\/schema\\\/person\\\/2d4068cb2f39cd10008c2fce578a7356\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/pt\\\/pev-questiona-governo-sobre-atraso-da-atualizacao-de-pensoes-por-acidente-de-trabalho-observador\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/super-news.info\\\/pt\\\/pev-questiona-governo-sobre-atraso-da-atualizacao-de-pensoes-por-acidente-de-trabalho-observador\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/super-news.info\\\/pt\\\/pev-questiona-governo-sobre-atraso-da-atualizacao-de-pensoes-por-acidente-de-trabalho-observador\\\/#primaryimage\",\"url\":\"https:\\\/\\\/super-news.info\\\/pt\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/09\\\/PEV-questiona-Governo-sobre-atraso-da-atualiza-o-de-pens-es-por.jpg\",\"contentUrl\":\"https:\\\/\\\/super-news.info\\\/pt\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/09\\\/PEV-questiona-Governo-sobre-atraso-da-atualiza-o-de-pens-es-por.jpg\",\"width\":770,\"height\":433,\"caption\":\"PEV questiona Governo sobre atraso da atualiza\u00e7\u00e3o de pens\u00f5es por acidente de trabalho \u2013 Observador\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/super-news.info\\\/pt\\\/pev-questiona-governo-sobre-atraso-da-atualizacao-de-pensoes-por-acidente-de-trabalho-observador\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430\",\"item\":\"https:\\\/\\\/super-news.info\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PEV questiona Governo sobre atraso da atualiza\u00e7\u00e3o de pens\u00f5es por acidente de trabalho \u2013 Observador\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/super-news.info\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/super-news.info\\\/pt\\\/\",\"name\":\"Super News\",\"description\":\"Super News Portugal\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/super-news.info\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/super-news.info\\\/pt\\\/#\\\/schema\\\/person\\\/2d4068cb2f39cd10008c2fce578a7356\",\"name\":\"super-news\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g\",\"caption\":\"super-news\"},\"url\":\"https:\\\/\\\/super-news.info\\\/pt\\\/author\\\/pt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PEV questiona Governo sobre atraso da atualiza\u00e7\u00e3o de pens\u00f5es por acidente de trabalho \u2013 Observador - Super News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/super-news.info\/pt\/pev-questiona-governo-sobre-atraso-da-atualizacao-de-pensoes-por-acidente-de-trabalho-observador\/","og_locale":"pt_PT","og_type":"article","og_title":"PEV questiona Governo sobre atraso da atualiza\u00e7\u00e3o de pens\u00f5es por acidente de trabalho \u2013 Observador - Super News","og_description":"O Partido Ecologista \u201cOs Verdes\u201d (PEV) questionou este s\u00e1bado o Governo, atrav\u00e9s do parlamento, sobre o atraso na atualiza\u00e7\u00e3o das pens\u00f5es por acidente de trabalho, considerando que n\u00e3o h\u00e1 \u201craz\u00f5es atend\u00edveis\u201d para isso. Numa pergunta enviada aos Minist\u00e9rios das Finan\u00e7as e do Trabalho, Solidariedade e Seguran\u00e7a Social, a deputada do PEV Mariana Silva alega que [&hellip;]","og_url":"https:\/\/super-news.info\/pt\/pev-questiona-governo-sobre-atraso-da-atualizacao-de-pensoes-por-acidente-de-trabalho-observador\/","og_site_name":"Super News","article_published_time":"2020-09-19T11:45:25+00:00","article_modified_time":"2020-09-19T11:45:27+00:00","og_image":[{"width":770,"height":433,"url":"https:\/\/super-news.info\/pt\/wp-content\/uploads\/sites\/2\/2020\/09\/PEV-questiona-Governo-sobre-atraso-da-atualiza-o-de-pens-es-por.jpg","type":"image\/jpeg"}],"author":"super-news","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"super-news","Tempo estimado de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/super-news.info\/pt\/pev-questiona-governo-sobre-atraso-da-atualizacao-de-pensoes-por-acidente-de-trabalho-observador\/#article","isPartOf":{"@id":"https:\/\/super-news.info\/pt\/pev-questiona-governo-sobre-atraso-da-atualizacao-de-pensoes-por-acidente-de-trabalho-observador\/"},"author":{"name":"super-news","@id":"https:\/\/super-news.info\/pt\/#\/schema\/person\/2d4068cb2f39cd10008c2fce578a7356"},"headline":"PEV questiona Governo sobre atraso da atualiza\u00e7\u00e3o de pens\u00f5es por acidente de trabalho \u2013 Observador","datePublished":"2020-09-19T11:45:25+00:00","dateModified":"2020-09-19T11:45:27+00:00","mainEntityOfPage":{"@id":"https:\/\/super-news.info\/pt\/pev-questiona-governo-sobre-atraso-da-atualizacao-de-pensoes-por-acidente-de-trabalho-observador\/"},"wordCount":332,"commentCount":0,"image":{"@id":"https:\/\/super-news.info\/pt\/pev-questiona-governo-sobre-atraso-da-atualizacao-de-pensoes-por-acidente-de-trabalho-observador\/#primaryimage"},"thumbnailUrl":"https:\/\/super-news.info\/pt\/wp-content\/uploads\/sites\/2\/2020\/09\/PEV-questiona-Governo-sobre-atraso-da-atualiza-o-de-pens-es-por.jpg","articleSection":["NOT\u00cdCIAS FINANCEIRAS"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/super-news.info\/pt\/pev-questiona-governo-sobre-atraso-da-atualizacao-de-pensoes-por-acidente-de-trabalho-observador\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/super-news.info\/pt\/pev-questiona-governo-sobre-atraso-da-atualizacao-de-pensoes-por-acidente-de-trabalho-observador\/","url":"https:\/\/super-news.info\/pt\/pev-questiona-governo-sobre-atraso-da-atualizacao-de-pensoes-por-acidente-de-trabalho-observador\/","name":"PEV questiona Governo sobre atraso da atualiza\u00e7\u00e3o de pens\u00f5es por acidente de trabalho \u2013 Observador - Super News","isPartOf":{"@id":"https:\/\/super-news.info\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/super-news.info\/pt\/pev-questiona-governo-sobre-atraso-da-atualizacao-de-pensoes-por-acidente-de-trabalho-observador\/#primaryimage"},"image":{"@id":"https:\/\/super-news.info\/pt\/pev-questiona-governo-sobre-atraso-da-atualizacao-de-pensoes-por-acidente-de-trabalho-observador\/#primaryimage"},"thumbnailUrl":"https:\/\/super-news.info\/pt\/wp-content\/uploads\/sites\/2\/2020\/09\/PEV-questiona-Governo-sobre-atraso-da-atualiza-o-de-pens-es-por.jpg","datePublished":"2020-09-19T11:45:25+00:00","dateModified":"2020-09-19T11:45:27+00:00","author":{"@id":"https:\/\/super-news.info\/pt\/#\/schema\/person\/2d4068cb2f39cd10008c2fce578a7356"},"breadcrumb":{"@id":"https:\/\/super-news.info\/pt\/pev-questiona-governo-sobre-atraso-da-atualizacao-de-pensoes-por-acidente-de-trabalho-observador\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/super-news.info\/pt\/pev-questiona-governo-sobre-atraso-da-atualizacao-de-pensoes-por-acidente-de-trabalho-observador\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/super-news.info\/pt\/pev-questiona-governo-sobre-atraso-da-atualizacao-de-pensoes-por-acidente-de-trabalho-observador\/#primaryimage","url":"https:\/\/super-news.info\/pt\/wp-content\/uploads\/sites\/2\/2020\/09\/PEV-questiona-Governo-sobre-atraso-da-atualiza-o-de-pens-es-por.jpg","contentUrl":"https:\/\/super-news.info\/pt\/wp-content\/uploads\/sites\/2\/2020\/09\/PEV-questiona-Governo-sobre-atraso-da-atualiza-o-de-pens-es-por.jpg","width":770,"height":433,"caption":"PEV questiona Governo sobre atraso da atualiza\u00e7\u00e3o de pens\u00f5es por acidente de trabalho \u2013 Observador"},{"@type":"BreadcrumbList","@id":"https:\/\/super-news.info\/pt\/pev-questiona-governo-sobre-atraso-da-atualizacao-de-pensoes-por-acidente-de-trabalho-observador\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430","item":"https:\/\/super-news.info\/pt\/"},{"@type":"ListItem","position":2,"name":"PEV questiona Governo sobre atraso da atualiza\u00e7\u00e3o de pens\u00f5es por acidente de trabalho \u2013 Observador"}]},{"@type":"WebSite","@id":"https:\/\/super-news.info\/pt\/#website","url":"https:\/\/super-news.info\/pt\/","name":"Super News","description":"Super News Portugal","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/super-news.info\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/super-news.info\/pt\/#\/schema\/person\/2d4068cb2f39cd10008c2fce578a7356","name":"super-news","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g","caption":"super-news"},"url":"https:\/\/super-news.info\/pt\/author\/pt\/"}]}},"_links":{"self":[{"href":"https:\/\/super-news.info\/pt\/wp-json\/wp\/v2\/posts\/5035","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/super-news.info\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/super-news.info\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/super-news.info\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/super-news.info\/pt\/wp-json\/wp\/v2\/comments?post=5035"}],"version-history":[{"count":1,"href":"https:\/\/super-news.info\/pt\/wp-json\/wp\/v2\/posts\/5035\/revisions"}],"predecessor-version":[{"id":5037,"href":"https:\/\/super-news.info\/pt\/wp-json\/wp\/v2\/posts\/5035\/revisions\/5037"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/super-news.info\/pt\/wp-json\/wp\/v2\/media\/5036"}],"wp:attachment":[{"href":"https:\/\/super-news.info\/pt\/wp-json\/wp\/v2\/media?parent=5035"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/super-news.info\/pt\/wp-json\/wp\/v2\/categories?post=5035"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/super-news.info\/pt\/wp-json\/wp\/v2\/tags?post=5035"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}