{"id":4980,"date":"2020-08-26T05:21:24","date_gmt":"2020-08-26T02:21:24","guid":{"rendered":"https:\/\/super-news.info\/pt\/portugal-nao-aguenta-outro-confinamento-observador\/"},"modified":"2020-08-26T05:21:25","modified_gmt":"2020-08-26T02:21:25","slug":"portugal-nao-aguenta-outro-confinamento-observador","status":"publish","type":"post","link":"https:\/\/super-news.info\/pt\/portugal-nao-aguenta-outro-confinamento-observador\/","title":{"rendered":"Portugal n\u00e3o aguenta outro confinamento \u2013 Observador"},"content":{"rendered":"<p><\/p>\n<p>            Ainda se pondera se teremos outro confinamento no Outono, como se a decis\u00e3o fosse entre economia e sa\u00fade, ou sequer poss\u00edvel. Como se s\u00f3 a sa\u00fade dissesse respeito \u00e0s pessoas e a economia \u00e0s grandes empresas. No entanto, n\u00e3o s\u00f3 a economia \u00e9 a ess\u00eancia da vida das pessoas, porque reflecte as suas decis\u00f5es no dia-a-dia, como o confinamento da \u00faltima Primavera as prejudicou. Mais: ao dificultar o acesso aos cuidados de sa\u00fade, o confinamento poder\u00e1 estar na origem de um aumento recorde do n\u00famero de \u00f3bitos por outras causas que n\u00e3o as derivadas da Covid-19. Ou seja, um novo confinamento em nome da sa\u00fade, n\u00e3o s\u00f3 nos ser\u00e1 nocivo f\u00edsica e mentalmente, como prejudicar\u00e1 ainda mais, econ\u00f3mica e financeiramente, os cidad\u00e3os e as fam\u00edlias, com o aumento do fosso entre os que t\u00eam trabalho garantido e os que o perderam. Entre os alunos que t\u00eam acesso a boas escolas e os que se ficam a acompanh\u00e1-la pela televis\u00e3o. Entre os que t\u00eam acesso a bons m\u00e9dicos e os que se p\u00f5em \u00e0 janela a v\u00ea-los passar.<\/p>\n<p>Ainda h\u00e1 quem espere por uma recupera\u00e7\u00e3o da economia em V. Uma vit\u00f3ria sobre o v\u00edrus, qual reviravolta. Uma recupera\u00e7\u00e3o, j\u00e1 de si dif\u00edcil, mas que poder\u00e1 ser problem\u00e1tica se houver outro confinamento. Problem\u00e1tica porque para qualquer recupera\u00e7\u00e3o econ\u00f3mica \u00e9 preciso investir e para se investir \u00e9 preciso capital e este n\u00e3o existe. N\u00e3o o t\u00eam as fam\u00edlias que n\u00e3o poupam, nem as empresas que vivem a cr\u00e9dito, menos ainda os bancos, que deles o melhor \u00e9 nem falar. Fora o que os bancos centrais despejam na economia, o dinheiro n\u00e3o se encontra, t\u00e3o escondido que est\u00e1 no meio da d\u00edvida. H\u00e1 um certo exagero nisto, mas que reflecte uma verdade que \u00e9 a falta de meios financeiros para darmos a volta por cima; para que tenhamos a dita e t\u00e3o desejada recupera\u00e7\u00e3o em V.H\u00e1 tamb\u00e9m ainda quem acredite, que esta crise \u00e9 diferente da de 2011 porque ningu\u00e9m a provocou. Que resulta de um v\u00edrus, de um acontecimento totalmente aleat\u00f3rio, de cariz natural e n\u00e3o humano. Mas tal n\u00e3o \u00e9 verdade. A pandemia s\u00f3 acentuou a crise da d\u00edvida, cujos sintomas graves experiment\u00e1mos h\u00e1 nove anos. Ali\u00e1s, uma crise da d\u00edvida que nos estagna desde o in\u00edcio do s\u00e9culo.Vamos ficar-nos por Portugal para percebermos melhor as dificuldades que atravessaremos nos anos mais pr\u00f3ximos. \u00c9 prov\u00e1vel, que com a pandemia haja perto de 500 mil desempregados no nosso pa\u00eds. Representam 5% da totalidade da popula\u00e7\u00e3o portuguesa; cerca de 10% da popula\u00e7\u00e3o activa. S\u00e3o pessoas que v\u00e3o precisar de receber subs\u00eddio de desemprego pago por um Estado com uma d\u00edvida p\u00fablica crescente, que se aproxima dos 135% do PIB. S\u00e3o pessoas que deixaram de pagar impostos, de forma que o Estado vai perder receitas. S\u00e3o cidad\u00e3os que n\u00e3o v\u00e3o investir, n\u00e3o v\u00e3o gastar, n\u00e3o v\u00e3o poupar e, caso haja outro confinamento, n\u00e3o poder\u00e3o sair \u00e0 rua para procurar emprego. Mas acima de tudo, s\u00e3o pessoas que o Estado s\u00f3 pode ajudar se hipotecarmos ainda mais a vida das crian\u00e7as e dos que ainda n\u00e3o nasceram. Portugueses, esses, que ou ser\u00e3o como n\u00f3s e tamb\u00e9m n\u00e3o v\u00e3o cuidar do futuro ou, se o fizerem, sentir\u00e3o por n\u00f3s um desprezo triste, mas salutar.Depois temos as muitas empresas que fecharam. Estas eram como pequenos pelot\u00f5es de mulheres e homens que trabalhavam, criavam riqueza, recebiam os seus ordenados e vencimentos e levavam dinheiro para casa. Muitas das empresas que fecharam eram pequenos neg\u00f3cios que permitiam um n\u00edvel de desemprego relativamente baixo, embora fosse um trabalho prec\u00e1rio e de baixo rendimento. De fonte de riqueza, essas empresas tornaram-se em fonte de problemas. Para os trabalhadores que perderam o emprego e para os empres\u00e1rios que, al\u00e9m de ficarem sem o seu ganha-p\u00e3o, se afundam em burocracia e d\u00edvida.H\u00e1 ainda quem aguarde pelos milh\u00f5es de Bruxelas, como se esses fundos n\u00e3o fossem para projectos espec\u00edficos e a conta-gotas. Como se esses fundos, que o pa\u00eds precisa com urg\u00eancia, n\u00e3o acabem por distorcer ainda mais a economia, j\u00e1 que o seu destino \u00e9 decidido centralmente e n\u00e3o de acordo com a procura dos consumidores.<\/p>\n<p>Com menos receitas e mais despesa o Estado vai ter mais dificuldade para cumprir as suas fun\u00e7\u00f5es na justi\u00e7a, na sa\u00fade e na educa\u00e7\u00e3o. Se durante o confinamento, as listas de espera aumentaram e as consultas foram suspensas, o SNS n\u00e3o tem condi\u00e7\u00f5es para recuperar os meses perdidos. Pior: com menos dinheiro \u00e9 bem prov\u00e1vel que a degrada\u00e7\u00e3o do SNS (fruto das cativa\u00e7\u00f5es a que os governos socialistas, com o apoio do BE e do PCP, nos habituaram nos \u00faltimos anos) se venha acentuar. Se antes de Mar\u00e7o 2020, os tribunais levavam anos a proferir as suas senten\u00e7as, a situa\u00e7\u00e3o delicada em que a justi\u00e7a portuguesa se encontra n\u00e3o melhorou s\u00f3 porque o Governo deixou de se preocupar com o assunto.Esta \u00e9 a situa\u00e7\u00e3o em Agosto antes de um poss\u00edvel novo confinamento, que, a acontecer, agravar\u00e1 ainda mais a situa\u00e7\u00e3o econ\u00f3mica, financeira, social, pol\u00edtica e educativa do pa\u00eds. A nossa margem \u00e9 muito pequena, porque temos uma das maiores d\u00edvidas do mundo (que Marcelo n\u00e3o se deu ao trabalho de referir quando nos dizia os maiores em qualquer coisa in\u00f3cua e sem interesse ). Uma margem t\u00e3o pequena, que leva a que me pergunte como Ant\u00f3nio Costa tenciona completar os tr\u00eas longos anos que ainda tem de legislatura. Me levam a questionar, como j\u00e1 fiz, se Marcelo, um pol\u00edtico h\u00e1bil e esperto, pondera mesmo candidatar-se. Na verdade, se o fizer, vai encontrar um pa\u00eds muito diferente do de 2015, menos prop\u00edcio a festas e palmadinhas nas costas, mais irritado, mais pobre, mais doente, mais triste (logo ele, que nos queria alegrar), menos educado e menos pronto a aceitar que se passe uma esponja por cima da corrup\u00e7\u00e3o, do compadrio e dos variad\u00edssimos esquemas atrav\u00e9s dos quais o PS vai estendendo a sua rede.Durante cinco anos, o pa\u00eds foi governado com fanfarronice. Com o alto patroc\u00ednio das mais altas figuras do Estado (Presidente da Rep\u00fablica, Primeiro-Ministro e presidente da Assembleia da Rep\u00fablica) fez-se de conta que o problema que nos caiu no colo em 2011 se resolveu com um excedente or\u00e7amental vago e vol\u00favel, para n\u00e3o dizer pior. Perdemos tempo e agora acusa-se um v\u00edrus de um mal que j\u00e1 existia: d\u00edvida, m\u00e1 gest\u00e3o p\u00fablica, maus governantes, m\u00e1s decis\u00f5es, p\u00e9ssimas estrat\u00e9gias. Pouco ou nada de virtudes pol\u00edticas e humanas, como Ant\u00f3nio Costa nos mostrou, em Outubro de 2019, no Terreiro do Pa\u00e7o e em off ao Expresso, ainda h\u00e1 dias. Pouco mais que um pesadelo, que exigir\u00e1 o melhor de cada um de n\u00f3s. Que nos eleve a n\u00edveis de excel\u00eancia que tempos normais n\u00e3o permitiriam. Valha-nos isso, porque de cobardes n\u00e3o temos nada, \u00e9 para isso que c\u00e1 estamos.<\/p>\n<p>\n<!--noindex--><br \/>\n<a href=\"https:\/\/observador.pt\/opiniao\/portugal-nao-aguenta-outro-confinamento\/\" rel=\"nofollow\">Source link <\/a><br \/>\n<!--\/noindex--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ainda se pondera se teremos outro confinamento no Outono, como se a decis\u00e3o fosse entre economia e sa\u00fade, ou sequer poss\u00edvel. Como se s\u00f3 a sa\u00fade dissesse respeito \u00e0s pessoas e a economia \u00e0s grandes empresas. No entanto, n\u00e3o s\u00f3 a economia \u00e9 a ess\u00eancia da vida das pessoas, porque reflecte as suas decis\u00f5es no [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":4981,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4980","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-financeiras"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Portugal n\u00e3o aguenta outro confinamento \u2013 Observador - Super News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/super-news.info\/pt\/portugal-nao-aguenta-outro-confinamento-observador\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Portugal n\u00e3o aguenta outro confinamento \u2013 Observador - Super News\" \/>\n<meta property=\"og:description\" content=\"Ainda se pondera se teremos outro confinamento no Outono, como se a decis\u00e3o fosse entre economia e sa\u00fade, ou sequer poss\u00edvel. Como se s\u00f3 a sa\u00fade dissesse respeito \u00e0s pessoas e a economia \u00e0s grandes empresas. No entanto, n\u00e3o s\u00f3 a economia \u00e9 a ess\u00eancia da vida das pessoas, porque reflecte as suas decis\u00f5es no [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/super-news.info\/pt\/portugal-nao-aguenta-outro-confinamento-observador\/\" \/>\n<meta property=\"og:site_name\" content=\"Super News\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-26T02:21:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-26T02:21:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/super-news.info\/pt\/wp-content\/uploads\/sites\/2\/2020\/08\/Portugal-n-o-aguenta-outro-confinamento-Observador.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"467\" \/>\n\t<meta property=\"og:image:height\" content=\"467\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"super-news\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"super-news\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/super-news.info\\\/pt\\\/portugal-nao-aguenta-outro-confinamento-observador\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/pt\\\/portugal-nao-aguenta-outro-confinamento-observador\\\/\"},\"author\":{\"name\":\"super-news\",\"@id\":\"https:\\\/\\\/super-news.info\\\/pt\\\/#\\\/schema\\\/person\\\/2d4068cb2f39cd10008c2fce578a7356\"},\"headline\":\"Portugal n\u00e3o aguenta outro confinamento \u2013 Observador\",\"datePublished\":\"2020-08-26T02:21:24+00:00\",\"dateModified\":\"2020-08-26T02:21:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/pt\\\/portugal-nao-aguenta-outro-confinamento-observador\\\/\"},\"wordCount\":1269,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/pt\\\/portugal-nao-aguenta-outro-confinamento-observador\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/super-news.info\\\/pt\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/08\\\/Portugal-n-o-aguenta-outro-confinamento-Observador.jpg\",\"articleSection\":[\"NOT\u00cdCIAS FINANCEIRAS\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/super-news.info\\\/pt\\\/portugal-nao-aguenta-outro-confinamento-observador\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/super-news.info\\\/pt\\\/portugal-nao-aguenta-outro-confinamento-observador\\\/\",\"url\":\"https:\\\/\\\/super-news.info\\\/pt\\\/portugal-nao-aguenta-outro-confinamento-observador\\\/\",\"name\":\"Portugal n\u00e3o aguenta outro confinamento \u2013 Observador - Super News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/pt\\\/portugal-nao-aguenta-outro-confinamento-observador\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/pt\\\/portugal-nao-aguenta-outro-confinamento-observador\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/super-news.info\\\/pt\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/08\\\/Portugal-n-o-aguenta-outro-confinamento-Observador.jpg\",\"datePublished\":\"2020-08-26T02:21:24+00:00\",\"dateModified\":\"2020-08-26T02:21:25+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/pt\\\/#\\\/schema\\\/person\\\/2d4068cb2f39cd10008c2fce578a7356\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/pt\\\/portugal-nao-aguenta-outro-confinamento-observador\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/super-news.info\\\/pt\\\/portugal-nao-aguenta-outro-confinamento-observador\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/super-news.info\\\/pt\\\/portugal-nao-aguenta-outro-confinamento-observador\\\/#primaryimage\",\"url\":\"https:\\\/\\\/super-news.info\\\/pt\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/08\\\/Portugal-n-o-aguenta-outro-confinamento-Observador.jpg\",\"contentUrl\":\"https:\\\/\\\/super-news.info\\\/pt\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/08\\\/Portugal-n-o-aguenta-outro-confinamento-Observador.jpg\",\"width\":467,\"height\":467,\"caption\":\"Portugal n\u00e3o aguenta outro confinamento \u2013 Observador\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/super-news.info\\\/pt\\\/portugal-nao-aguenta-outro-confinamento-observador\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430\",\"item\":\"https:\\\/\\\/super-news.info\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Portugal n\u00e3o aguenta outro confinamento \u2013 Observador\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/super-news.info\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/super-news.info\\\/pt\\\/\",\"name\":\"Super News\",\"description\":\"Super News Portugal\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/super-news.info\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/super-news.info\\\/pt\\\/#\\\/schema\\\/person\\\/2d4068cb2f39cd10008c2fce578a7356\",\"name\":\"super-news\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g\",\"caption\":\"super-news\"},\"url\":\"https:\\\/\\\/super-news.info\\\/pt\\\/author\\\/pt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Portugal n\u00e3o aguenta outro confinamento \u2013 Observador - Super News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/super-news.info\/pt\/portugal-nao-aguenta-outro-confinamento-observador\/","og_locale":"pt_PT","og_type":"article","og_title":"Portugal n\u00e3o aguenta outro confinamento \u2013 Observador - Super News","og_description":"Ainda se pondera se teremos outro confinamento no Outono, como se a decis\u00e3o fosse entre economia e sa\u00fade, ou sequer poss\u00edvel. Como se s\u00f3 a sa\u00fade dissesse respeito \u00e0s pessoas e a economia \u00e0s grandes empresas. No entanto, n\u00e3o s\u00f3 a economia \u00e9 a ess\u00eancia da vida das pessoas, porque reflecte as suas decis\u00f5es no [&hellip;]","og_url":"https:\/\/super-news.info\/pt\/portugal-nao-aguenta-outro-confinamento-observador\/","og_site_name":"Super News","article_published_time":"2020-08-26T02:21:24+00:00","article_modified_time":"2020-08-26T02:21:25+00:00","og_image":[{"width":467,"height":467,"url":"https:\/\/super-news.info\/pt\/wp-content\/uploads\/sites\/2\/2020\/08\/Portugal-n-o-aguenta-outro-confinamento-Observador.jpg","type":"image\/jpeg"}],"author":"super-news","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"super-news","Tempo estimado de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/super-news.info\/pt\/portugal-nao-aguenta-outro-confinamento-observador\/#article","isPartOf":{"@id":"https:\/\/super-news.info\/pt\/portugal-nao-aguenta-outro-confinamento-observador\/"},"author":{"name":"super-news","@id":"https:\/\/super-news.info\/pt\/#\/schema\/person\/2d4068cb2f39cd10008c2fce578a7356"},"headline":"Portugal n\u00e3o aguenta outro confinamento \u2013 Observador","datePublished":"2020-08-26T02:21:24+00:00","dateModified":"2020-08-26T02:21:25+00:00","mainEntityOfPage":{"@id":"https:\/\/super-news.info\/pt\/portugal-nao-aguenta-outro-confinamento-observador\/"},"wordCount":1269,"commentCount":0,"image":{"@id":"https:\/\/super-news.info\/pt\/portugal-nao-aguenta-outro-confinamento-observador\/#primaryimage"},"thumbnailUrl":"https:\/\/super-news.info\/pt\/wp-content\/uploads\/sites\/2\/2020\/08\/Portugal-n-o-aguenta-outro-confinamento-Observador.jpg","articleSection":["NOT\u00cdCIAS FINANCEIRAS"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/super-news.info\/pt\/portugal-nao-aguenta-outro-confinamento-observador\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/super-news.info\/pt\/portugal-nao-aguenta-outro-confinamento-observador\/","url":"https:\/\/super-news.info\/pt\/portugal-nao-aguenta-outro-confinamento-observador\/","name":"Portugal n\u00e3o aguenta outro confinamento \u2013 Observador - Super News","isPartOf":{"@id":"https:\/\/super-news.info\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/super-news.info\/pt\/portugal-nao-aguenta-outro-confinamento-observador\/#primaryimage"},"image":{"@id":"https:\/\/super-news.info\/pt\/portugal-nao-aguenta-outro-confinamento-observador\/#primaryimage"},"thumbnailUrl":"https:\/\/super-news.info\/pt\/wp-content\/uploads\/sites\/2\/2020\/08\/Portugal-n-o-aguenta-outro-confinamento-Observador.jpg","datePublished":"2020-08-26T02:21:24+00:00","dateModified":"2020-08-26T02:21:25+00:00","author":{"@id":"https:\/\/super-news.info\/pt\/#\/schema\/person\/2d4068cb2f39cd10008c2fce578a7356"},"breadcrumb":{"@id":"https:\/\/super-news.info\/pt\/portugal-nao-aguenta-outro-confinamento-observador\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/super-news.info\/pt\/portugal-nao-aguenta-outro-confinamento-observador\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/super-news.info\/pt\/portugal-nao-aguenta-outro-confinamento-observador\/#primaryimage","url":"https:\/\/super-news.info\/pt\/wp-content\/uploads\/sites\/2\/2020\/08\/Portugal-n-o-aguenta-outro-confinamento-Observador.jpg","contentUrl":"https:\/\/super-news.info\/pt\/wp-content\/uploads\/sites\/2\/2020\/08\/Portugal-n-o-aguenta-outro-confinamento-Observador.jpg","width":467,"height":467,"caption":"Portugal n\u00e3o aguenta outro confinamento \u2013 Observador"},{"@type":"BreadcrumbList","@id":"https:\/\/super-news.info\/pt\/portugal-nao-aguenta-outro-confinamento-observador\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430","item":"https:\/\/super-news.info\/pt\/"},{"@type":"ListItem","position":2,"name":"Portugal n\u00e3o aguenta outro confinamento \u2013 Observador"}]},{"@type":"WebSite","@id":"https:\/\/super-news.info\/pt\/#website","url":"https:\/\/super-news.info\/pt\/","name":"Super News","description":"Super News Portugal","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/super-news.info\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/super-news.info\/pt\/#\/schema\/person\/2d4068cb2f39cd10008c2fce578a7356","name":"super-news","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g","caption":"super-news"},"url":"https:\/\/super-news.info\/pt\/author\/pt\/"}]}},"_links":{"self":[{"href":"https:\/\/super-news.info\/pt\/wp-json\/wp\/v2\/posts\/4980","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/super-news.info\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/super-news.info\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/super-news.info\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/super-news.info\/pt\/wp-json\/wp\/v2\/comments?post=4980"}],"version-history":[{"count":1,"href":"https:\/\/super-news.info\/pt\/wp-json\/wp\/v2\/posts\/4980\/revisions"}],"predecessor-version":[{"id":4982,"href":"https:\/\/super-news.info\/pt\/wp-json\/wp\/v2\/posts\/4980\/revisions\/4982"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/super-news.info\/pt\/wp-json\/wp\/v2\/media\/4981"}],"wp:attachment":[{"href":"https:\/\/super-news.info\/pt\/wp-json\/wp\/v2\/media?parent=4980"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/super-news.info\/pt\/wp-json\/wp\/v2\/categories?post=4980"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/super-news.info\/pt\/wp-json\/wp\/v2\/tags?post=4980"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}