{"id":318,"date":"2019-04-13T12:29:12","date_gmt":"2019-04-13T09:29:12","guid":{"rendered":"https:\/\/super-news.info\/pt\/ha-musicas-que-ficam-na-cabeca-e-as-marcas-o-jornal-economico\/"},"modified":"2019-04-13T12:29:13","modified_gmt":"2019-04-13T09:29:13","slug":"ha-musicas-que-ficam-na-cabeca-e-as-marcas-o-jornal-economico","status":"publish","type":"post","link":"https:\/\/super-news.info\/pt\/ha-musicas-que-ficam-na-cabeca-e-as-marcas-o-jornal-economico\/","title":{"rendered":"H\u00e1 m\u00fasicas que ficam na cabe\u00e7a. E as marcas? \u2013 O Jornal Econ\u00f3mico"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div>\n<p>Tr\u00eas em cada quatro consumidores dizem que a m\u00fasica tem o poder de provocar mudan\u00e7a e as marcas reconhecem esta capacidade junto da audi\u00eancia. Mas, saber como us\u00e1-la de forma poderosa, \u00e9 uma coisa diferente. Os dados do Havas Group s\u00e3o claros: 73% dos inquiridos afirmam que as parcerias de marcas com m\u00fasicos ajudam \u00e0 notoriedade de marca; j\u00e1 70% acredita que a m\u00fasica faz as empresas distinguirem-se dos seus concorrentes.<\/p>\n<p>A verdade \u00e9 que, quando pensamos em determinadas marcas, h\u00e1 an\u00fancios que come\u00e7amos automaticamente a cantarolar. H\u00e1 m\u00fasicas que transformam marcas em \u00edcones e marcas que tornam m\u00fasicas ic\u00f3nicas.<\/p>\n<p>Atualmente, com cada vez mais marcas a comunicar e menos aten\u00e7\u00e3o centralizada dos consumidores, como \u00e9 que a m\u00fasica \u2013 como mais um meio \u2013 se distingue num horizonte de informa\u00e7\u00e3o t\u00e3o fragmentado? Conseguir\u00e1 a voz de uma marca ser ouvida entre todo o ru\u00eddo atual ou necessita de \u201ccantar\u201d mais alto pela voz de algu\u00e9m treinado para o efeito?<\/p>\n<p>N\u00e3o h\u00e1 uma resposta simples, mas, na realidade, existem m\u00fasicos que s\u00e3o eles mesmos marcas. Profissionais que s\u00e3o talentosos criadores de conte\u00fado e que influenciam o p\u00fablico. Repare-se que alguns dos pontos de dor partilhados por marcas e m\u00fasicos podem resumir-se \u00e0 procura de relev\u00e2ncia e angaria\u00e7\u00e3o de novas audi\u00eancias, oportunidade de produ\u00e7\u00e3o e desenvolvimento de produto e escalabilidade mantendo a autenticidade. H\u00e1 um claro paralelo entre estes pontos e aquilo a que podemos chamar de oportunidades comuns: influ\u00eancia, cria\u00e7\u00e3o e colabora\u00e7\u00e3o.<\/p>\n<p>Nos \u00faltimos tempos, o uso do termo influenciador tornou-se confuso e excessivo. Em alguns casos, tornou-se at\u00e9 uma palavra feia! Mas vemos a audi\u00eancia a redefinir este espa\u00e7o e a devolver o seu significado \u00e0s origens da influ\u00eancia. A ind\u00fastria da comunica\u00e7\u00e3o e da publicidade tem vindo a evoluir para colocar contadores de hist\u00f3rias reais, com talento, paix\u00e3o e autoridade no centro da mensagem.<\/p>\n<p>A m\u00fasica como ferramenta abre in\u00fameras portas para as marcas. Embora seja muito comum utilizar-se melodias como um ve\u00edculo para complementar hist\u00f3rias em an\u00fancios digitais e televisivos, atualmente esta rela\u00e7\u00e3o estreita revela-se nos mais diversos formatos, com colabora\u00e7\u00f5es onde a m\u00fasica (e a rela\u00e7\u00e3o com m\u00fasicos) surge como um elemento-chave das diretrizes da marca.<\/p>\n<p>Alguns desses exemplos passam por desenvolver intera\u00e7\u00f5es para dispositivos m\u00f3veis, conte\u00fados experimentais, formatos inesperados de DOOH (Digital Out of Home), conte\u00fado na loja ou integrado na intera\u00e7\u00e3o do site, e a lista continua! O som d\u00e1 \u00e0s experi\u00eancias digitais um toque humano. Mas o \u00e1udio \u00e9 muito mais do que um meio, \u00e9 personalidade e identidade.<\/p>\n<p>O crescente uso da voz, seja nas pesquisas, nas mensagens que enviamos, no nosso relacionamento com dispositivos de voz ou no crescente consumo de podcasts, torna-se cada vez mais evidente que o relacionamento entre marcas e audi\u00eancias est\u00e1 tamb\u00e9m ele a mudar para uma maior exposi\u00e7\u00e3o de personalidade de ambas as partes.<\/p>\n<p>Ao contr\u00e1rio da codifica\u00e7\u00e3o da mensagem escrita, a voz transmite um n\u00famero incr\u00edvel de informa\u00e7\u00e3o muito para al\u00e9m da mensagem verbal: desde idade, g\u00e9nero, personalidade, estado de esp\u00edrito, origem geogr\u00e1fica e social e at\u00e9 a posi\u00e7\u00e3o em que o corpo se encontra. Com tantas vari\u00e1veis a trabalhar, no campo que volta a ser o mais natural para a audi\u00eancia, as marcas precisam de trabalhar rapidamente para encontrar sua pr\u00f3pria voz e para compreender a voz dos seus consumidores.<\/p>\n<p>Entre m\u00fasica, voz e a relacionamento, ser\u00e1 este o regresso do <em>jingle<\/em>?<\/p>\n<\/div>\n<p><script>\/*<![CDATA[*\/function facebookInit(){var js=document.createElement('script');js.src='https:\/\/connect.facebook.net\/pt_PT\/sdk.js#xfbml=1&#038;version=v3.1&#038;appId=1708066812789184&#038;autoLogAppEvents=1';return document.body.appendChild(js);}\nwindow.onscroll=function(){var rect=document.getElementsByClassName('je-post-content')[0].getBoundingClientRect();if(rect.bottom<window.innerHeight){facebookInit();window.onscroll=null;}}\/*]]>*\/<\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/jornaleconomico.sapo.pt\/noticias\/ha-musicas-que-ficam-na-cabeca-e-as-marcas-433171\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Tr\u00eas em cada quatro consumidores dizem que a m\u00fasica tem o poder de provocar mudan\u00e7a e as marcas reconhecem esta capacidade junto da audi\u00eancia. Mas, saber como us\u00e1-la de forma poderosa, \u00e9 uma coisa diferente. Os dados do Havas Group s\u00e3o claros: 73% dos inquiridos afirmam que as parcerias de marcas com m\u00fasicos ajudam [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":319,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-318","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-financeiras"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>H\u00e1 m\u00fasicas que ficam na cabe\u00e7a. E as marcas? \u2013 O Jornal Econ\u00f3mico - Super News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/super-news.info\/pt\/ha-musicas-que-ficam-na-cabeca-e-as-marcas-o-jornal-economico\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"H\u00e1 m\u00fasicas que ficam na cabe\u00e7a. E as marcas? \u2013 O Jornal Econ\u00f3mico - Super News\" \/>\n<meta property=\"og:description\" content=\"[ad_1] Tr\u00eas em cada quatro consumidores dizem que a m\u00fasica tem o poder de provocar mudan\u00e7a e as marcas reconhecem esta capacidade junto da audi\u00eancia. Mas, saber como us\u00e1-la de forma poderosa, \u00e9 uma coisa diferente. Os dados do Havas Group s\u00e3o claros: 73% dos inquiridos afirmam que as parcerias de marcas com m\u00fasicos ajudam [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/super-news.info\/pt\/ha-musicas-que-ficam-na-cabeca-e-as-marcas-o-jornal-economico\/\" \/>\n<meta property=\"og:site_name\" content=\"Super News\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-13T09:29:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-04-13T09:29:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/super-news.info\/pt\/wp-content\/uploads\/sites\/2\/2019\/04\/H\u00e1-m\u00fasicas-que-ficam-na-cabe\u00e7a.-E-as-marcas-\u2013.png\" \/>\n\t<meta property=\"og:image:width\" content=\"200\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"super-news\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"super-news\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/super-news.info\\\/pt\\\/ha-musicas-que-ficam-na-cabeca-e-as-marcas-o-jornal-economico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/pt\\\/ha-musicas-que-ficam-na-cabeca-e-as-marcas-o-jornal-economico\\\/\"},\"author\":{\"name\":\"super-news\",\"@id\":\"https:\\\/\\\/super-news.info\\\/pt\\\/#\\\/schema\\\/person\\\/2d4068cb2f39cd10008c2fce578a7356\"},\"headline\":\"H\u00e1 m\u00fasicas que ficam na cabe\u00e7a. E as marcas? \u2013 O Jornal Econ\u00f3mico\",\"datePublished\":\"2019-04-13T09:29:12+00:00\",\"dateModified\":\"2019-04-13T09:29:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/pt\\\/ha-musicas-que-ficam-na-cabeca-e-as-marcas-o-jornal-economico\\\/\"},\"wordCount\":639,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/pt\\\/ha-musicas-que-ficam-na-cabeca-e-as-marcas-o-jornal-economico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/super-news.info\\\/pt\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/04\\\/H\u00e1-m\u00fasicas-que-ficam-na-cabe\u00e7a.-E-as-marcas-\u2013.png\",\"articleSection\":[\"NOT\u00cdCIAS FINANCEIRAS\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/super-news.info\\\/pt\\\/ha-musicas-que-ficam-na-cabeca-e-as-marcas-o-jornal-economico\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/super-news.info\\\/pt\\\/ha-musicas-que-ficam-na-cabeca-e-as-marcas-o-jornal-economico\\\/\",\"url\":\"https:\\\/\\\/super-news.info\\\/pt\\\/ha-musicas-que-ficam-na-cabeca-e-as-marcas-o-jornal-economico\\\/\",\"name\":\"H\u00e1 m\u00fasicas que ficam na cabe\u00e7a. E as marcas? \u2013 O Jornal Econ\u00f3mico - Super News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/pt\\\/ha-musicas-que-ficam-na-cabeca-e-as-marcas-o-jornal-economico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/pt\\\/ha-musicas-que-ficam-na-cabeca-e-as-marcas-o-jornal-economico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/super-news.info\\\/pt\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/04\\\/H\u00e1-m\u00fasicas-que-ficam-na-cabe\u00e7a.-E-as-marcas-\u2013.png\",\"datePublished\":\"2019-04-13T09:29:12+00:00\",\"dateModified\":\"2019-04-13T09:29:13+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/pt\\\/#\\\/schema\\\/person\\\/2d4068cb2f39cd10008c2fce578a7356\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/pt\\\/ha-musicas-que-ficam-na-cabeca-e-as-marcas-o-jornal-economico\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/super-news.info\\\/pt\\\/ha-musicas-que-ficam-na-cabeca-e-as-marcas-o-jornal-economico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/super-news.info\\\/pt\\\/ha-musicas-que-ficam-na-cabeca-e-as-marcas-o-jornal-economico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/super-news.info\\\/pt\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/04\\\/H\u00e1-m\u00fasicas-que-ficam-na-cabe\u00e7a.-E-as-marcas-\u2013.png\",\"contentUrl\":\"https:\\\/\\\/super-news.info\\\/pt\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/04\\\/H\u00e1-m\u00fasicas-que-ficam-na-cabe\u00e7a.-E-as-marcas-\u2013.png\",\"width\":200,\"height\":200,\"caption\":\"H\u00e1 m\u00fasicas que ficam na cabe\u00e7a. E as marcas? \u2013 O Jornal Econ\u00f3mico\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/super-news.info\\\/pt\\\/ha-musicas-que-ficam-na-cabeca-e-as-marcas-o-jornal-economico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430\",\"item\":\"https:\\\/\\\/super-news.info\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"H\u00e1 m\u00fasicas que ficam na cabe\u00e7a. E as marcas? \u2013 O Jornal Econ\u00f3mico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/super-news.info\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/super-news.info\\\/pt\\\/\",\"name\":\"Super News\",\"description\":\"Super News Portugal\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/super-news.info\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/super-news.info\\\/pt\\\/#\\\/schema\\\/person\\\/2d4068cb2f39cd10008c2fce578a7356\",\"name\":\"super-news\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g\",\"caption\":\"super-news\"},\"url\":\"https:\\\/\\\/super-news.info\\\/pt\\\/author\\\/pt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"H\u00e1 m\u00fasicas que ficam na cabe\u00e7a. E as marcas? \u2013 O Jornal Econ\u00f3mico - Super News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/super-news.info\/pt\/ha-musicas-que-ficam-na-cabeca-e-as-marcas-o-jornal-economico\/","og_locale":"pt_PT","og_type":"article","og_title":"H\u00e1 m\u00fasicas que ficam na cabe\u00e7a. E as marcas? \u2013 O Jornal Econ\u00f3mico - Super News","og_description":"[ad_1] Tr\u00eas em cada quatro consumidores dizem que a m\u00fasica tem o poder de provocar mudan\u00e7a e as marcas reconhecem esta capacidade junto da audi\u00eancia. Mas, saber como us\u00e1-la de forma poderosa, \u00e9 uma coisa diferente. Os dados do Havas Group s\u00e3o claros: 73% dos inquiridos afirmam que as parcerias de marcas com m\u00fasicos ajudam [&hellip;]","og_url":"https:\/\/super-news.info\/pt\/ha-musicas-que-ficam-na-cabeca-e-as-marcas-o-jornal-economico\/","og_site_name":"Super News","article_published_time":"2019-04-13T09:29:12+00:00","article_modified_time":"2019-04-13T09:29:13+00:00","og_image":[{"width":200,"height":200,"url":"https:\/\/super-news.info\/pt\/wp-content\/uploads\/sites\/2\/2019\/04\/H\u00e1-m\u00fasicas-que-ficam-na-cabe\u00e7a.-E-as-marcas-\u2013.png","type":"image\/png"}],"author":"super-news","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"super-news","Tempo estimado de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/super-news.info\/pt\/ha-musicas-que-ficam-na-cabeca-e-as-marcas-o-jornal-economico\/#article","isPartOf":{"@id":"https:\/\/super-news.info\/pt\/ha-musicas-que-ficam-na-cabeca-e-as-marcas-o-jornal-economico\/"},"author":{"name":"super-news","@id":"https:\/\/super-news.info\/pt\/#\/schema\/person\/2d4068cb2f39cd10008c2fce578a7356"},"headline":"H\u00e1 m\u00fasicas que ficam na cabe\u00e7a. E as marcas? \u2013 O Jornal Econ\u00f3mico","datePublished":"2019-04-13T09:29:12+00:00","dateModified":"2019-04-13T09:29:13+00:00","mainEntityOfPage":{"@id":"https:\/\/super-news.info\/pt\/ha-musicas-que-ficam-na-cabeca-e-as-marcas-o-jornal-economico\/"},"wordCount":639,"commentCount":0,"image":{"@id":"https:\/\/super-news.info\/pt\/ha-musicas-que-ficam-na-cabeca-e-as-marcas-o-jornal-economico\/#primaryimage"},"thumbnailUrl":"https:\/\/super-news.info\/pt\/wp-content\/uploads\/sites\/2\/2019\/04\/H\u00e1-m\u00fasicas-que-ficam-na-cabe\u00e7a.-E-as-marcas-\u2013.png","articleSection":["NOT\u00cdCIAS FINANCEIRAS"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/super-news.info\/pt\/ha-musicas-que-ficam-na-cabeca-e-as-marcas-o-jornal-economico\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/super-news.info\/pt\/ha-musicas-que-ficam-na-cabeca-e-as-marcas-o-jornal-economico\/","url":"https:\/\/super-news.info\/pt\/ha-musicas-que-ficam-na-cabeca-e-as-marcas-o-jornal-economico\/","name":"H\u00e1 m\u00fasicas que ficam na cabe\u00e7a. E as marcas? \u2013 O Jornal Econ\u00f3mico - Super News","isPartOf":{"@id":"https:\/\/super-news.info\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/super-news.info\/pt\/ha-musicas-que-ficam-na-cabeca-e-as-marcas-o-jornal-economico\/#primaryimage"},"image":{"@id":"https:\/\/super-news.info\/pt\/ha-musicas-que-ficam-na-cabeca-e-as-marcas-o-jornal-economico\/#primaryimage"},"thumbnailUrl":"https:\/\/super-news.info\/pt\/wp-content\/uploads\/sites\/2\/2019\/04\/H\u00e1-m\u00fasicas-que-ficam-na-cabe\u00e7a.-E-as-marcas-\u2013.png","datePublished":"2019-04-13T09:29:12+00:00","dateModified":"2019-04-13T09:29:13+00:00","author":{"@id":"https:\/\/super-news.info\/pt\/#\/schema\/person\/2d4068cb2f39cd10008c2fce578a7356"},"breadcrumb":{"@id":"https:\/\/super-news.info\/pt\/ha-musicas-que-ficam-na-cabeca-e-as-marcas-o-jornal-economico\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/super-news.info\/pt\/ha-musicas-que-ficam-na-cabeca-e-as-marcas-o-jornal-economico\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/super-news.info\/pt\/ha-musicas-que-ficam-na-cabeca-e-as-marcas-o-jornal-economico\/#primaryimage","url":"https:\/\/super-news.info\/pt\/wp-content\/uploads\/sites\/2\/2019\/04\/H\u00e1-m\u00fasicas-que-ficam-na-cabe\u00e7a.-E-as-marcas-\u2013.png","contentUrl":"https:\/\/super-news.info\/pt\/wp-content\/uploads\/sites\/2\/2019\/04\/H\u00e1-m\u00fasicas-que-ficam-na-cabe\u00e7a.-E-as-marcas-\u2013.png","width":200,"height":200,"caption":"H\u00e1 m\u00fasicas que ficam na cabe\u00e7a. E as marcas? \u2013 O Jornal Econ\u00f3mico"},{"@type":"BreadcrumbList","@id":"https:\/\/super-news.info\/pt\/ha-musicas-que-ficam-na-cabeca-e-as-marcas-o-jornal-economico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430","item":"https:\/\/super-news.info\/pt\/"},{"@type":"ListItem","position":2,"name":"H\u00e1 m\u00fasicas que ficam na cabe\u00e7a. E as marcas? \u2013 O Jornal Econ\u00f3mico"}]},{"@type":"WebSite","@id":"https:\/\/super-news.info\/pt\/#website","url":"https:\/\/super-news.info\/pt\/","name":"Super News","description":"Super News Portugal","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/super-news.info\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/super-news.info\/pt\/#\/schema\/person\/2d4068cb2f39cd10008c2fce578a7356","name":"super-news","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g","caption":"super-news"},"url":"https:\/\/super-news.info\/pt\/author\/pt\/"}]}},"_links":{"self":[{"href":"https:\/\/super-news.info\/pt\/wp-json\/wp\/v2\/posts\/318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/super-news.info\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/super-news.info\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/super-news.info\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/super-news.info\/pt\/wp-json\/wp\/v2\/comments?post=318"}],"version-history":[{"count":1,"href":"https:\/\/super-news.info\/pt\/wp-json\/wp\/v2\/posts\/318\/revisions"}],"predecessor-version":[{"id":320,"href":"https:\/\/super-news.info\/pt\/wp-json\/wp\/v2\/posts\/318\/revisions\/320"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/super-news.info\/pt\/wp-json\/wp\/v2\/media\/319"}],"wp:attachment":[{"href":"https:\/\/super-news.info\/pt\/wp-json\/wp\/v2\/media?parent=318"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/super-news.info\/pt\/wp-json\/wp\/v2\/categories?post=318"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/super-news.info\/pt\/wp-json\/wp\/v2\/tags?post=318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}