{"id":2094,"date":"2019-07-08T13:46:56","date_gmt":"2019-07-08T13:46:56","guid":{"rendered":"https:\/\/super-news.info\/mx\/por-que-este-telefono-de-20-dolares-es-una-gran-innovacion\/"},"modified":"2019-07-08T13:46:57","modified_gmt":"2019-07-08T13:46:57","slug":"por-que-este-telefono-de-20-dolares-es-una-gran-innovacion","status":"publish","type":"post","link":"https:\/\/super-news.info\/mx\/por-que-este-telefono-de-20-dolares-es-una-gran-innovacion\/","title":{"rendered":"\u00bfPor qu\u00e9 este tel\u00e9fono de 20 d\u00f3lares es una gran innovaci\u00f3n?"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<p class=\"paragraph\" data-count=\"712\" data-wrap=\"113\">Hace pocos a\u00f1os, la eterna b\u00fasqueda corporativa de los \u201cpr\u00f3ximos mil millones de usuarios de internet\u201d parec\u00eda lejana. Las tecnol\u00f3gicas pon\u00edan el conocimiento humano en los bolsillos de los pobres del mundo, mientras invert\u00edan dinero publicitario de grandes multinacionales que pagaban para llegar a ellos. Pero en estos d\u00edas, los costos de este modelo de negocio son claros. Se ha culpado a las apps de redes sociales de avivar un genocidio en Myanmar, linchamientos en India e interferencia electoral en el mundo. Tambi\u00e9n han contribuido a una agobiante adicci\u00f3n a nuestras rectangulares dosis de dopamina. \u00bfRealmente creemos que 50 por ciento de la humanidad sin conexi\u00f3n a internet estar\u00eda mejor de tenerla? <\/p>\n<p class=\"paragraph\" data-count=\"224\" data-wrap=\"36\">Pues s\u00ed. Un mayor acceso a internet se relaciona con una mejor atenci\u00f3n m\u00e9dica, educaci\u00f3n, igualdad de g\u00e9nero, desarrollo econ\u00f3mico y otros objetivos a los que los organismos no lucrativos bien financiados no logran llegar. <\/p>\n<p class=\"paragraph\" data-count=\"435\" data-wrap=\"76\">Aumentar en 10 por ciento el uso de internet m\u00f3vil de un pa\u00eds se relaciona con un aumento de 2 puntos porcentuales del PIB y los canales electr\u00f3nicos tambi\u00e9n han demostrado ser capaces de hacer que los gobiernos sean m\u00e1s responsivos a las denuncias civiles. Sin embargo, las mujeres y personas que viven en \u00e1reas rurales se quedan rezagadas en el uso de internet, lo que limita su acceso a servicios, bancos y oportunidades laborales. <\/p>\n<div class=\"image__block \">\n<figure><\/figure>\n<p><span class=\"element__footer\"><\/span><span class=\"element__credit\"><\/span><\/div>\n<p class=\"paragraph\" data-count=\"0\" data-wrap=\"1\">\n<p class=\"paragraph\" data-count=\"606\" data-wrap=\"104\">En ning\u00fan lugar es m\u00e1s evidente que en \u00c1frica que, con menos de 25 por ciento, tiene una de las poblaciones con menos acceso a internet. El s\u00e9quito de 800 millones de personas desconectadas en los 54 pa\u00edses del continente crece m\u00e1s r\u00e1pido que la mayor\u00eda, pero los ingresos son menores y una mayor parte de la poblaci\u00f3n vive en \u00e1reas rurales que son dif\u00edciles de cablear para tener acceso a internet o, de hecho, electricidad. Sin embargo, ahora un pu\u00f1ado de proveedores de telefon\u00eda intentan impulsar el acceso a internet a mercados africanos dise\u00f1ando modelos con un ojo puesto en las prioridades rurales.<\/p>\n<p class=\"paragraph\" data-count=\"480\" data-wrap=\"78\">Dos de los operadores de telefon\u00eda m\u00f3vil m\u00e1s grandes en \u00c1frica, MTN de Sud\u00e1frica y Orange SA de Francia, comenzaron a vender cuasi smartphones de 20 d\u00f3lares. Antes, los m\u00e1s baratos eran de 40, lejos del alcance de muchos. Estos dispositivos, con cerebro smartphone en el cuerpo de celular de tiendita de 1990, son empoderados con software de KaiOS Technologies Ltd., un producto chino que recogi\u00f3 las piezas de un esfuerzo fallido para producir dispositivos baratos para internet.<\/p>\n<p class=\"paragraph\" data-count=\"543\" data-wrap=\"88\">La mayor\u00eda de las compa\u00f1\u00edas buscan fabricar dispositivos conectados a internet m\u00e1s poderosos y capaces, pero KaiOS se fue por otro camino. Reconsider\u00f3 todo para mantener las capacidades de los smartphones, pero reduciendo el costo y alargando la vida de bater\u00eda. MTN dijo en un comunicado que sus tel\u00e9fonos KaiOS est\u00e1n dise\u00f1ados para tumbar muros a los beneficios de internet. Bertrand Gouze, vicepresidente de la operaci\u00f3n de Orange en \u00c1frica y el Medio Oriente, dice que los dispositivos KaiOS son una alternativa a los tel\u00e9fonos m\u00e1s caros. <\/p>\n<p class=\"paragraph\" data-count=\"649\" data-wrap=\"113\">El cuerpo del tel\u00e9fono KaiOS es muy b\u00e1sico. No tiene pantalla t\u00e1ctil, que tiende a ser el componente m\u00e1s caro de un smartphone y consume mucha bater\u00eda. Los modelos que Orange vende (nombrados Sanza como el instrumento musical com\u00fanmente hallado en el centro y oriente de \u00c1frica) tienen una pantalla menos de la mitad del tama\u00f1o del iPhone m\u00e1s nuevo que se controla con un teclado. Las teclas est\u00e1n hechas de pl\u00e1stico barato. En Nigeria, Ruanda y otros pa\u00edses en donde MTN reci\u00e9n comenz\u00f3 a vender tel\u00e9fonos KaiOS, est\u00e1n dise\u00f1ados para redes 3G, porque la cobertura 4G no llega a dos terceras partes de los 230 millones de clientes regionales de MTN. <\/p>\n<p class=\"paragraph\" data-count=\"646\" data-wrap=\"114\">Para ahorrar dinero, KaiOS tambi\u00e9n redujo la memoria a una cuarta parte o menos que el smartphone Android m\u00e1s econ\u00f3mico. Eso significa que los tel\u00e9fonos solo hacen una cosa a la vez, nada de brincar de tu grupo de chat para buscar cosas en la web. Para algunos modelos KaiOS, Qualcomm Inc. rehizo una versi\u00f3n m\u00e1s vieja de su procesador, el cerebro del tel\u00e9fono, a un costo estimado de como 3 d\u00f3lares comparado con la versi\u00f3n de aproximadamente 50 d\u00f3lares hallada en los smartphones de gama alta. En total, los tel\u00e9fonos con poder KaiOS se hacen de diversas partes con un valor de 15 d\u00f3lares, calcula Wayne Lam, analista con la investigadora IHS. <\/p>\n<p class=\"paragraph\" data-count=\"141\" data-wrap=\"26\">Los materiales de los tel\u00e9fonos que le siguen en precio cuestan el doble, y los mejores iPhone de Apple llegan a 390 d\u00f3lares en componentes. <\/p>\n<p class=\"paragraph\" data-count=\"557\" data-wrap=\"97\">Eso no significa que no sean capaces los tel\u00e9fonos abaratados. Todos los ahorros producen un dispositivo que usa tan poco poder, afirma Orange, que puede durar hasta cinco d\u00edas con una carga. La falta de pantalla t\u00e1ctil tambi\u00e9n hace m\u00e1s valiosos los comandos de voz, as\u00ed que hay un bot\u00f3n gigante al centro de la pantalla que activa la versi\u00f3n de Google Assistant adaptada para mercados locales. Google invirti\u00f3 22 millones de d\u00f3lares el a\u00f1o pasado en KaiOS y contribuy\u00f3 a una nueva ronda de financiamiento de 50 millones de d\u00f3lares anunciada el 22 de mayo. <\/p>\n<p class=\"paragraph\" data-count=\"596\" data-wrap=\"91\">Con alta y baja tecnolog\u00eda, los proveedores de internet invierten en hacer que la conexi\u00f3n sea posible en condiciones adversas. BRCK, de Nairobi, construye computadoras con partes baratas disponibles para transmitir conectividad desde torres de celulares rurales con poder solar y que sirvan como lugares con Wi-Fi disponible en los camiones llamados matatus. Para asegurar que las m\u00e1quinas sobrevivan tanto a las grandes expansiones como la posibilidad de ser manguereadas por los conductores de los matatus, BRCK alberga las computadoras en cajas de aluminio que las protegen de los elementos. <\/p>\n<p class=\"paragraph\" data-count=\"498\" data-wrap=\"82\">Un problema que no han solucionado los operados son los costos elevados de los datos m\u00f3viles. Cada gigabyte cuesta el promedio de una gran rebanada del ingreso mensual africano, como 9 por ciento comparado con menos de 0.5 por ciento en Estados Unidos, seg\u00fan la Alianza por un Internet Accesible, una coalici\u00f3n de empresas, gobiernos y grupos de defensa. Facebook desarroll\u00f3 un software especial para operadores m\u00f3viles que regala en un intento por reducir costos para que se consuma su contenido. <\/p>\n<p class=\"paragraph\" data-count=\"494\" data-wrap=\"81\">La empresa de investigaci\u00f3n de mercado Strategy espera que las ventas de tel\u00e9fonos con poder KaiOS suban 50 por ciento este a\u00f1o, convirti\u00e9ndose en el sistema operativo que m\u00e1s crece en el mundo. La mayor\u00eda de ese crecimiento probablemente venga de India, en donde la multimillonaria direcci\u00f3n de conglomerados Reliance Industries Ltd. invierte decenas de miles de millones de d\u00f3lares para construir a nivel nacional una red de internet m\u00f3vil de la nada y subsidiar en gran parte los tel\u00e9fonos. <\/p>\n<p class=\"paragraph\" data-count=\"663\" data-wrap=\"108\">Como en India y el resto del mundo, \u00c1frica no puede ignorar los peligrosos inconvenientes del internet, sobre todo su capacidad de propagar discurso de odio e informaci\u00f3n falsa. Pero como la energ\u00eda y transporte, el acceso a internet se ha convertido en un componente b\u00e1sico de la infraestructura, desarrollo econ\u00f3mico y empoderamiento social, tanto que los gobiernos autoritarios en parte del continente lo han intentado bloquear. La creciente expansi\u00f3n de KaiOS es un recordatorio de que la mayor\u00eda de las innovaciones m\u00e1s importantes no siempre son los autos aut\u00f3nomos, los aviones sin pilotos o los barcos sin marineros. A veces es un tel\u00e9fono de 20 d\u00f3lares. <\/p>\n<p class=\"paragraph\" data-count=\"0\" data-wrap=\"1\">\n<p>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.elfinanciero.com.mx\/rss\/bloomberg-businessweek\/por-que-este-telefono-de-20-dolares-es-una-gran-innovacion\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Hace pocos a\u00f1os, la eterna b\u00fasqueda corporativa de los \u201cpr\u00f3ximos mil millones de usuarios de internet\u201d parec\u00eda lejana. Las tecnol\u00f3gicas pon\u00edan el conocimiento humano en los bolsillos de los pobres del mundo, mientras invert\u00edan dinero publicitario de grandes multinacionales que pagaban para llegar a ellos. Pero en estos d\u00edas, los costos de este modelo [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":2095,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2094","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-financieras"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfPor qu\u00e9 este tel\u00e9fono de 20 d\u00f3lares es una gran innovaci\u00f3n? - Super News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/super-news.info\/mx\/por-que-este-telefono-de-20-dolares-es-una-gran-innovacion\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfPor qu\u00e9 este tel\u00e9fono de 20 d\u00f3lares es una gran innovaci\u00f3n? - Super News\" \/>\n<meta property=\"og:description\" content=\"[ad_1] Hace pocos a\u00f1os, la eterna b\u00fasqueda corporativa de los \u201cpr\u00f3ximos mil millones de usuarios de internet\u201d parec\u00eda lejana. Las tecnol\u00f3gicas pon\u00edan el conocimiento humano en los bolsillos de los pobres del mundo, mientras invert\u00edan dinero publicitario de grandes multinacionales que pagaban para llegar a ellos. Pero en estos d\u00edas, los costos de este modelo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/super-news.info\/mx\/por-que-este-telefono-de-20-dolares-es-una-gran-innovacion\/\" \/>\n<meta property=\"og:site_name\" content=\"Super News\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-08T13:46:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-07-08T13:46:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/super-news.info\/mx\/wp-content\/uploads\/sites\/8\/2019\/07\/\u00bfPor-qu\u00e9-este-tel\u00e9fono-de-20-d\u00f3lares-es-una-gran.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1417\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"mx\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mx\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/super-news.info\\\/mx\\\/por-que-este-telefono-de-20-dolares-es-una-gran-innovacion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/mx\\\/por-que-este-telefono-de-20-dolares-es-una-gran-innovacion\\\/\"},\"author\":{\"name\":\"mx\",\"@id\":\"https:\\\/\\\/super-news.info\\\/mx\\\/#\\\/schema\\\/person\\\/74b71ca3d407439fd57da2d9c89449ca\"},\"headline\":\"\u00bfPor qu\u00e9 este tel\u00e9fono de 20 d\u00f3lares es una gran innovaci\u00f3n?\",\"datePublished\":\"2019-07-08T13:46:56+00:00\",\"dateModified\":\"2019-07-08T13:46:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/mx\\\/por-que-este-telefono-de-20-dolares-es-una-gran-innovacion\\\/\"},\"wordCount\":1307,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/mx\\\/por-que-este-telefono-de-20-dolares-es-una-gran-innovacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/super-news.info\\\/mx\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2019\\\/07\\\/\u00bfPor-qu\u00e9-este-tel\u00e9fono-de-20-d\u00f3lares-es-una-gran.png\",\"articleSection\":[\"NOTICIAS FINANCIERAS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/super-news.info\\\/mx\\\/por-que-este-telefono-de-20-dolares-es-una-gran-innovacion\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/super-news.info\\\/mx\\\/por-que-este-telefono-de-20-dolares-es-una-gran-innovacion\\\/\",\"url\":\"https:\\\/\\\/super-news.info\\\/mx\\\/por-que-este-telefono-de-20-dolares-es-una-gran-innovacion\\\/\",\"name\":\"\u00bfPor qu\u00e9 este tel\u00e9fono de 20 d\u00f3lares es una gran innovaci\u00f3n? - Super News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/mx\\\/por-que-este-telefono-de-20-dolares-es-una-gran-innovacion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/mx\\\/por-que-este-telefono-de-20-dolares-es-una-gran-innovacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/super-news.info\\\/mx\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2019\\\/07\\\/\u00bfPor-qu\u00e9-este-tel\u00e9fono-de-20-d\u00f3lares-es-una-gran.png\",\"datePublished\":\"2019-07-08T13:46:56+00:00\",\"dateModified\":\"2019-07-08T13:46:57+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/mx\\\/#\\\/schema\\\/person\\\/74b71ca3d407439fd57da2d9c89449ca\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/mx\\\/por-que-este-telefono-de-20-dolares-es-una-gran-innovacion\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/super-news.info\\\/mx\\\/por-que-este-telefono-de-20-dolares-es-una-gran-innovacion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/super-news.info\\\/mx\\\/por-que-este-telefono-de-20-dolares-es-una-gran-innovacion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/super-news.info\\\/mx\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2019\\\/07\\\/\u00bfPor-qu\u00e9-este-tel\u00e9fono-de-20-d\u00f3lares-es-una-gran.png\",\"contentUrl\":\"https:\\\/\\\/super-news.info\\\/mx\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2019\\\/07\\\/\u00bfPor-qu\u00e9-este-tel\u00e9fono-de-20-d\u00f3lares-es-una-gran.png\",\"width\":1200,\"height\":1417,\"caption\":\"\u00bfPor qu\u00e9 este tel\u00e9fono de 20 d\u00f3lares es una gran innovaci\u00f3n?\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/super-news.info\\\/mx\\\/por-que-este-telefono-de-20-dolares-es-una-gran-innovacion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/super-news.info\\\/mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfPor qu\u00e9 este tel\u00e9fono de 20 d\u00f3lares es una gran innovaci\u00f3n?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/super-news.info\\\/mx\\\/#website\",\"url\":\"https:\\\/\\\/super-news.info\\\/mx\\\/\",\"name\":\"Super News\",\"description\":\"Super News Mexico\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/super-news.info\\\/mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/super-news.info\\\/mx\\\/#\\\/schema\\\/person\\\/74b71ca3d407439fd57da2d9c89449ca\",\"name\":\"mx\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6374ac65ff69c362a0ae1303d73d69dcd9bd198d62d9861f054a69aaf82c017b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6374ac65ff69c362a0ae1303d73d69dcd9bd198d62d9861f054a69aaf82c017b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6374ac65ff69c362a0ae1303d73d69dcd9bd198d62d9861f054a69aaf82c017b?s=96&d=mm&r=g\",\"caption\":\"mx\"},\"url\":\"https:\\\/\\\/super-news.info\\\/mx\\\/author\\\/mx\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfPor qu\u00e9 este tel\u00e9fono de 20 d\u00f3lares es una gran innovaci\u00f3n? - Super News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/super-news.info\/mx\/por-que-este-telefono-de-20-dolares-es-una-gran-innovacion\/","og_locale":"es_MX","og_type":"article","og_title":"\u00bfPor qu\u00e9 este tel\u00e9fono de 20 d\u00f3lares es una gran innovaci\u00f3n? - Super News","og_description":"[ad_1] Hace pocos a\u00f1os, la eterna b\u00fasqueda corporativa de los \u201cpr\u00f3ximos mil millones de usuarios de internet\u201d parec\u00eda lejana. Las tecnol\u00f3gicas pon\u00edan el conocimiento humano en los bolsillos de los pobres del mundo, mientras invert\u00edan dinero publicitario de grandes multinacionales que pagaban para llegar a ellos. Pero en estos d\u00edas, los costos de este modelo [&hellip;]","og_url":"https:\/\/super-news.info\/mx\/por-que-este-telefono-de-20-dolares-es-una-gran-innovacion\/","og_site_name":"Super News","article_published_time":"2019-07-08T13:46:56+00:00","article_modified_time":"2019-07-08T13:46:57+00:00","og_image":[{"width":1200,"height":1417,"url":"https:\/\/super-news.info\/mx\/wp-content\/uploads\/sites\/8\/2019\/07\/\u00bfPor-qu\u00e9-este-tel\u00e9fono-de-20-d\u00f3lares-es-una-gran.png","type":"image\/png"}],"author":"mx","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"mx","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/super-news.info\/mx\/por-que-este-telefono-de-20-dolares-es-una-gran-innovacion\/#article","isPartOf":{"@id":"https:\/\/super-news.info\/mx\/por-que-este-telefono-de-20-dolares-es-una-gran-innovacion\/"},"author":{"name":"mx","@id":"https:\/\/super-news.info\/mx\/#\/schema\/person\/74b71ca3d407439fd57da2d9c89449ca"},"headline":"\u00bfPor qu\u00e9 este tel\u00e9fono de 20 d\u00f3lares es una gran innovaci\u00f3n?","datePublished":"2019-07-08T13:46:56+00:00","dateModified":"2019-07-08T13:46:57+00:00","mainEntityOfPage":{"@id":"https:\/\/super-news.info\/mx\/por-que-este-telefono-de-20-dolares-es-una-gran-innovacion\/"},"wordCount":1307,"commentCount":0,"image":{"@id":"https:\/\/super-news.info\/mx\/por-que-este-telefono-de-20-dolares-es-una-gran-innovacion\/#primaryimage"},"thumbnailUrl":"https:\/\/super-news.info\/mx\/wp-content\/uploads\/sites\/8\/2019\/07\/\u00bfPor-qu\u00e9-este-tel\u00e9fono-de-20-d\u00f3lares-es-una-gran.png","articleSection":["NOTICIAS FINANCIERAS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/super-news.info\/mx\/por-que-este-telefono-de-20-dolares-es-una-gran-innovacion\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/super-news.info\/mx\/por-que-este-telefono-de-20-dolares-es-una-gran-innovacion\/","url":"https:\/\/super-news.info\/mx\/por-que-este-telefono-de-20-dolares-es-una-gran-innovacion\/","name":"\u00bfPor qu\u00e9 este tel\u00e9fono de 20 d\u00f3lares es una gran innovaci\u00f3n? - Super News","isPartOf":{"@id":"https:\/\/super-news.info\/mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/super-news.info\/mx\/por-que-este-telefono-de-20-dolares-es-una-gran-innovacion\/#primaryimage"},"image":{"@id":"https:\/\/super-news.info\/mx\/por-que-este-telefono-de-20-dolares-es-una-gran-innovacion\/#primaryimage"},"thumbnailUrl":"https:\/\/super-news.info\/mx\/wp-content\/uploads\/sites\/8\/2019\/07\/\u00bfPor-qu\u00e9-este-tel\u00e9fono-de-20-d\u00f3lares-es-una-gran.png","datePublished":"2019-07-08T13:46:56+00:00","dateModified":"2019-07-08T13:46:57+00:00","author":{"@id":"https:\/\/super-news.info\/mx\/#\/schema\/person\/74b71ca3d407439fd57da2d9c89449ca"},"breadcrumb":{"@id":"https:\/\/super-news.info\/mx\/por-que-este-telefono-de-20-dolares-es-una-gran-innovacion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/super-news.info\/mx\/por-que-este-telefono-de-20-dolares-es-una-gran-innovacion\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/super-news.info\/mx\/por-que-este-telefono-de-20-dolares-es-una-gran-innovacion\/#primaryimage","url":"https:\/\/super-news.info\/mx\/wp-content\/uploads\/sites\/8\/2019\/07\/\u00bfPor-qu\u00e9-este-tel\u00e9fono-de-20-d\u00f3lares-es-una-gran.png","contentUrl":"https:\/\/super-news.info\/mx\/wp-content\/uploads\/sites\/8\/2019\/07\/\u00bfPor-qu\u00e9-este-tel\u00e9fono-de-20-d\u00f3lares-es-una-gran.png","width":1200,"height":1417,"caption":"\u00bfPor qu\u00e9 este tel\u00e9fono de 20 d\u00f3lares es una gran innovaci\u00f3n?"},{"@type":"BreadcrumbList","@id":"https:\/\/super-news.info\/mx\/por-que-este-telefono-de-20-dolares-es-una-gran-innovacion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/super-news.info\/mx\/"},{"@type":"ListItem","position":2,"name":"\u00bfPor qu\u00e9 este tel\u00e9fono de 20 d\u00f3lares es una gran innovaci\u00f3n?"}]},{"@type":"WebSite","@id":"https:\/\/super-news.info\/mx\/#website","url":"https:\/\/super-news.info\/mx\/","name":"Super News","description":"Super News Mexico","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/super-news.info\/mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/super-news.info\/mx\/#\/schema\/person\/74b71ca3d407439fd57da2d9c89449ca","name":"mx","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6374ac65ff69c362a0ae1303d73d69dcd9bd198d62d9861f054a69aaf82c017b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6374ac65ff69c362a0ae1303d73d69dcd9bd198d62d9861f054a69aaf82c017b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6374ac65ff69c362a0ae1303d73d69dcd9bd198d62d9861f054a69aaf82c017b?s=96&d=mm&r=g","caption":"mx"},"url":"https:\/\/super-news.info\/mx\/author\/mx\/"}]}},"_links":{"self":[{"href":"https:\/\/super-news.info\/mx\/wp-json\/wp\/v2\/posts\/2094","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/super-news.info\/mx\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/super-news.info\/mx\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/super-news.info\/mx\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/super-news.info\/mx\/wp-json\/wp\/v2\/comments?post=2094"}],"version-history":[{"count":1,"href":"https:\/\/super-news.info\/mx\/wp-json\/wp\/v2\/posts\/2094\/revisions"}],"predecessor-version":[{"id":2096,"href":"https:\/\/super-news.info\/mx\/wp-json\/wp\/v2\/posts\/2094\/revisions\/2096"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/super-news.info\/mx\/wp-json\/wp\/v2\/media\/2095"}],"wp:attachment":[{"href":"https:\/\/super-news.info\/mx\/wp-json\/wp\/v2\/media?parent=2094"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/super-news.info\/mx\/wp-json\/wp\/v2\/categories?post=2094"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/super-news.info\/mx\/wp-json\/wp\/v2\/tags?post=2094"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}