{"id":1952,"date":"2020-12-11T04:37:04","date_gmt":"2020-12-11T04:37:04","guid":{"rendered":"https:\/\/super-news.info\/it\/carrello-di-whatsapp-nuova-funzione-whatsapp-business\/"},"modified":"2020-12-11T04:37:07","modified_gmt":"2020-12-11T04:37:07","slug":"carrello-di-whatsapp-nuova-funzione-whatsapp-business","status":"publish","type":"post","link":"https:\/\/super-news.info\/it\/carrello-di-whatsapp-nuova-funzione-whatsapp-business\/","title":{"rendered":"Carrello di WhatsApp: nuova funzione WhatsApp Business"},"content":{"rendered":"<p>    Dopo l\u2019ideazione e la diffusione del tasto shopping e dopo i nuovi sticker in collaborazione col l\u2019OMS, WhatsApp continua\u00a0 a far parlare di s\u00e9 con l\u2019originale funzione carrello. Ma a cosa serve e come funziona questa nuova opzione? I vantaggi offerti dalla funzione carrello di whatsapp Acquistare e vendere i propri articoli online diventer\u00e0 ancora pi\u00f9 facile sia per i consumatori, sia per i negozianti, grazie alle due recenti opzioni introdotte dal team WhatsApp: il tasto shopping e la funzione carrello. Dal blog ufficiale dell\u2019azienda \u00e8 possibile infatti apprendere che \u00abWhatsApp sta diventando sempre pi\u00f9 simile a un punto vendita, dove i proprietari di piccole attivit\u00e0 possono gestire gli ordini e fornire informazioni sui prodotti o servizi in vendita. Grazie ai cataloghi, i clienti possono controllare la disponibilit\u00e0 dei prodotti e le aziende possono organizzare le chat in base ai singoli articoli\u00bb. Proprio in questo contesto si colloca il lancio, a novembre 2020, del tasto shopping di WhatsApp che consente di iniziare una conversazione con un brand , un\u2019azienda o con un qualsiasi account business che venda prodotti o servizi semplicemente cliccando sull\u2019icona a forma di negozio. Si aggiunge a questa utilissima opzione un\u2019altra novit\u00e0: la funzione carrello. Questa funzione rafforza ulteriormente il legame diretto tra consumatori e negozianti, in quanto le azioni da compiere per l\u2019acquisto dei prodotti sono state notevolmente facilitate. Essa si inserisce perfettamente tra i servizi offerti da WhatsApp Business (disponibili sia per Android che per iPhone): i titolari delle attivit\u00e0 commerciali possono, infatti, creare e gestire un profilo della propria attivit\u00e0, caricare un catalogo di prodotti e, adesso, usufruire dei vantaggi offerti dalla funzione carrello di WhatsApp. Come usare la nuova funzione di whatsapp Si \u00e8 parlato dei vantaggi offerti dalla nuova funzione a consumatori e negozianti. Come funziona per\u00f2 nella pratica la funzione carrello di WhatsApp? Passare dal guardare l\u2019articolo desiderato sul display di uno smartphone o di un computer a stringerlo tra le proprie mani diviene facilissimo: a partire dall\u20198 dicembre 2020 \u00e8 possibile infatti visualizzare il catalogo virtuale (precedentemente caricato su un profilo business dal gestore del singolo brand o negozio), scegliere i prodotti da acquistare (e verificarne l\u2019effettiva disponibilit\u00e0), cliccare su \u201caggiungi al carrello\u201d e inviare l\u2019ordine all\u2019attivit\u00e0 (anche contemporaneamente di pi\u00f9 prodotti) grazie a un semplice messaggio.    \u00a9 RIPRODUZIONE RISERVATA E&#8217; vietata la ripubblicazione integrale dei contenuti<br \/>\n<br \/>\n<!--noindex--><br \/>\n<a href=\"https:\/\/www.insidemarketing.it\/nasce-la-nuova-funzione-carrello-di-whatsapp\/\" rel=\"nofollow\">Source link <\/a><br \/>\n<!--\/noindex--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dopo l\u2019ideazione e la diffusione del tasto shopping e dopo i nuovi sticker in collaborazione col l\u2019OMS, WhatsApp continua\u00a0 a far parlare di s\u00e9 con l\u2019originale funzione carrello. Ma a cosa serve e come funziona questa nuova opzione? I vantaggi offerti dalla funzione carrello di whatsapp Acquistare e vendere i propri articoli online diventer\u00e0 ancora [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1953,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1952","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novita-di-marketing-digitale"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Carrello di WhatsApp: nuova funzione WhatsApp Business - Super News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/super-news.info\/it\/carrello-di-whatsapp-nuova-funzione-whatsapp-business\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carrello di WhatsApp: nuova funzione WhatsApp Business - Super News\" \/>\n<meta property=\"og:description\" content=\"Dopo l\u2019ideazione e la diffusione del tasto shopping e dopo i nuovi sticker in collaborazione col l\u2019OMS, WhatsApp continua\u00a0 a far parlare di s\u00e9 con l\u2019originale funzione carrello. Ma a cosa serve e come funziona questa nuova opzione? I vantaggi offerti dalla funzione carrello di whatsapp Acquistare e vendere i propri articoli online diventer\u00e0 ancora [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/super-news.info\/it\/carrello-di-whatsapp-nuova-funzione-whatsapp-business\/\" \/>\n<meta property=\"og:site_name\" content=\"Super News\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-11T04:37:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-11T04:37:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/super-news.info\/it\/wp-content\/uploads\/sites\/9\/2020\/12\/Carrello-di-WhatsApp-nuova-funzione-WhatsApp-Business.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1300\" \/>\n\t<meta property=\"og:image:height\" content=\"867\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"super-news\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"super-news\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/carrello-di-whatsapp-nuova-funzione-whatsapp-business\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/carrello-di-whatsapp-nuova-funzione-whatsapp-business\\\/\"},\"author\":{\"name\":\"super-news\",\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/#\\\/schema\\\/person\\\/2d4068cb2f39cd10008c2fce578a7356\"},\"headline\":\"Carrello di WhatsApp: nuova funzione WhatsApp Business\",\"datePublished\":\"2020-12-11T04:37:04+00:00\",\"dateModified\":\"2020-12-11T04:37:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/carrello-di-whatsapp-nuova-funzione-whatsapp-business\\\/\"},\"wordCount\":401,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/carrello-di-whatsapp-nuova-funzione-whatsapp-business\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/super-news.info\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2020\\\/12\\\/Carrello-di-WhatsApp-nuova-funzione-WhatsApp-Business.jpg\",\"articleSection\":[\"NOVIT\u00c0 DI MARKETING DIGITALE\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/super-news.info\\\/it\\\/carrello-di-whatsapp-nuova-funzione-whatsapp-business\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/carrello-di-whatsapp-nuova-funzione-whatsapp-business\\\/\",\"url\":\"https:\\\/\\\/super-news.info\\\/it\\\/carrello-di-whatsapp-nuova-funzione-whatsapp-business\\\/\",\"name\":\"Carrello di WhatsApp: nuova funzione WhatsApp Business - Super News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/carrello-di-whatsapp-nuova-funzione-whatsapp-business\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/carrello-di-whatsapp-nuova-funzione-whatsapp-business\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/super-news.info\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2020\\\/12\\\/Carrello-di-WhatsApp-nuova-funzione-WhatsApp-Business.jpg\",\"datePublished\":\"2020-12-11T04:37:04+00:00\",\"dateModified\":\"2020-12-11T04:37:07+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/#\\\/schema\\\/person\\\/2d4068cb2f39cd10008c2fce578a7356\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/carrello-di-whatsapp-nuova-funzione-whatsapp-business\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/super-news.info\\\/it\\\/carrello-di-whatsapp-nuova-funzione-whatsapp-business\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/carrello-di-whatsapp-nuova-funzione-whatsapp-business\\\/#primaryimage\",\"url\":\"https:\\\/\\\/super-news.info\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2020\\\/12\\\/Carrello-di-WhatsApp-nuova-funzione-WhatsApp-Business.jpg\",\"contentUrl\":\"https:\\\/\\\/super-news.info\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2020\\\/12\\\/Carrello-di-WhatsApp-nuova-funzione-WhatsApp-Business.jpg\",\"width\":1300,\"height\":867,\"caption\":\"Carrello di WhatsApp: nuova funzione WhatsApp Business\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/carrello-di-whatsapp-nuova-funzione-whatsapp-business\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/super-news.info\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Carrello di WhatsApp: nuova funzione WhatsApp Business\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/super-news.info\\\/it\\\/\",\"name\":\"Super News\",\"description\":\"Super News from Italy\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/super-news.info\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/#\\\/schema\\\/person\\\/2d4068cb2f39cd10008c2fce578a7356\",\"name\":\"super-news\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g\",\"caption\":\"super-news\"},\"url\":\"https:\\\/\\\/super-news.info\\\/it\\\/author\\\/pt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Carrello di WhatsApp: nuova funzione WhatsApp Business - Super News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/super-news.info\/it\/carrello-di-whatsapp-nuova-funzione-whatsapp-business\/","og_locale":"it_IT","og_type":"article","og_title":"Carrello di WhatsApp: nuova funzione WhatsApp Business - Super News","og_description":"Dopo l\u2019ideazione e la diffusione del tasto shopping e dopo i nuovi sticker in collaborazione col l\u2019OMS, WhatsApp continua\u00a0 a far parlare di s\u00e9 con l\u2019originale funzione carrello. Ma a cosa serve e come funziona questa nuova opzione? I vantaggi offerti dalla funzione carrello di whatsapp Acquistare e vendere i propri articoli online diventer\u00e0 ancora [&hellip;]","og_url":"https:\/\/super-news.info\/it\/carrello-di-whatsapp-nuova-funzione-whatsapp-business\/","og_site_name":"Super News","article_published_time":"2020-12-11T04:37:04+00:00","article_modified_time":"2020-12-11T04:37:07+00:00","og_image":[{"width":1300,"height":867,"url":"https:\/\/super-news.info\/it\/wp-content\/uploads\/sites\/9\/2020\/12\/Carrello-di-WhatsApp-nuova-funzione-WhatsApp-Business.jpg","type":"image\/jpeg"}],"author":"super-news","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"super-news","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/super-news.info\/it\/carrello-di-whatsapp-nuova-funzione-whatsapp-business\/#article","isPartOf":{"@id":"https:\/\/super-news.info\/it\/carrello-di-whatsapp-nuova-funzione-whatsapp-business\/"},"author":{"name":"super-news","@id":"https:\/\/super-news.info\/it\/#\/schema\/person\/2d4068cb2f39cd10008c2fce578a7356"},"headline":"Carrello di WhatsApp: nuova funzione WhatsApp Business","datePublished":"2020-12-11T04:37:04+00:00","dateModified":"2020-12-11T04:37:07+00:00","mainEntityOfPage":{"@id":"https:\/\/super-news.info\/it\/carrello-di-whatsapp-nuova-funzione-whatsapp-business\/"},"wordCount":401,"commentCount":0,"image":{"@id":"https:\/\/super-news.info\/it\/carrello-di-whatsapp-nuova-funzione-whatsapp-business\/#primaryimage"},"thumbnailUrl":"https:\/\/super-news.info\/it\/wp-content\/uploads\/sites\/9\/2020\/12\/Carrello-di-WhatsApp-nuova-funzione-WhatsApp-Business.jpg","articleSection":["NOVIT\u00c0 DI MARKETING DIGITALE"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/super-news.info\/it\/carrello-di-whatsapp-nuova-funzione-whatsapp-business\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/super-news.info\/it\/carrello-di-whatsapp-nuova-funzione-whatsapp-business\/","url":"https:\/\/super-news.info\/it\/carrello-di-whatsapp-nuova-funzione-whatsapp-business\/","name":"Carrello di WhatsApp: nuova funzione WhatsApp Business - Super News","isPartOf":{"@id":"https:\/\/super-news.info\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/super-news.info\/it\/carrello-di-whatsapp-nuova-funzione-whatsapp-business\/#primaryimage"},"image":{"@id":"https:\/\/super-news.info\/it\/carrello-di-whatsapp-nuova-funzione-whatsapp-business\/#primaryimage"},"thumbnailUrl":"https:\/\/super-news.info\/it\/wp-content\/uploads\/sites\/9\/2020\/12\/Carrello-di-WhatsApp-nuova-funzione-WhatsApp-Business.jpg","datePublished":"2020-12-11T04:37:04+00:00","dateModified":"2020-12-11T04:37:07+00:00","author":{"@id":"https:\/\/super-news.info\/it\/#\/schema\/person\/2d4068cb2f39cd10008c2fce578a7356"},"breadcrumb":{"@id":"https:\/\/super-news.info\/it\/carrello-di-whatsapp-nuova-funzione-whatsapp-business\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/super-news.info\/it\/carrello-di-whatsapp-nuova-funzione-whatsapp-business\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/super-news.info\/it\/carrello-di-whatsapp-nuova-funzione-whatsapp-business\/#primaryimage","url":"https:\/\/super-news.info\/it\/wp-content\/uploads\/sites\/9\/2020\/12\/Carrello-di-WhatsApp-nuova-funzione-WhatsApp-Business.jpg","contentUrl":"https:\/\/super-news.info\/it\/wp-content\/uploads\/sites\/9\/2020\/12\/Carrello-di-WhatsApp-nuova-funzione-WhatsApp-Business.jpg","width":1300,"height":867,"caption":"Carrello di WhatsApp: nuova funzione WhatsApp Business"},{"@type":"BreadcrumbList","@id":"https:\/\/super-news.info\/it\/carrello-di-whatsapp-nuova-funzione-whatsapp-business\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/super-news.info\/it\/"},{"@type":"ListItem","position":2,"name":"Carrello di WhatsApp: nuova funzione WhatsApp Business"}]},{"@type":"WebSite","@id":"https:\/\/super-news.info\/it\/#website","url":"https:\/\/super-news.info\/it\/","name":"Super News","description":"Super News from Italy","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/super-news.info\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/super-news.info\/it\/#\/schema\/person\/2d4068cb2f39cd10008c2fce578a7356","name":"super-news","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g","caption":"super-news"},"url":"https:\/\/super-news.info\/it\/author\/pt\/"}]}},"_links":{"self":[{"href":"https:\/\/super-news.info\/it\/wp-json\/wp\/v2\/posts\/1952","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/super-news.info\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/super-news.info\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/super-news.info\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/super-news.info\/it\/wp-json\/wp\/v2\/comments?post=1952"}],"version-history":[{"count":1,"href":"https:\/\/super-news.info\/it\/wp-json\/wp\/v2\/posts\/1952\/revisions"}],"predecessor-version":[{"id":1954,"href":"https:\/\/super-news.info\/it\/wp-json\/wp\/v2\/posts\/1952\/revisions\/1954"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/super-news.info\/it\/wp-json\/wp\/v2\/media\/1953"}],"wp:attachment":[{"href":"https:\/\/super-news.info\/it\/wp-json\/wp\/v2\/media?parent=1952"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/super-news.info\/it\/wp-json\/wp\/v2\/categories?post=1952"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/super-news.info\/it\/wp-json\/wp\/v2\/tags?post=1952"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}