{"id":1512,"date":"2020-10-06T04:21:44","date_gmt":"2020-10-06T04:21:44","guid":{"rendered":"https:\/\/super-news.info\/it\/cina-economia-si-salva-dal-covid-pil-2-e-prepara-la-dual-circulation\/"},"modified":"2020-10-06T04:21:46","modified_gmt":"2020-10-06T04:21:46","slug":"cina-economia-si-salva-dal-covid-pil-2-e-prepara-la-dual-circulation","status":"publish","type":"post","link":"https:\/\/super-news.info\/it\/cina-economia-si-salva-dal-covid-pil-2-e-prepara-la-dual-circulation\/","title":{"rendered":"Cina, economia si salva dal Covid (Pil +2%) e prepara la dual circulation"},"content":{"rendered":"<p>Cina, economia si salva dal Covid (Pil +2%) e prepara la dual circulation<br \/>\nSorprese in arrivo per l\u2019economia della Cina. Nonostante i problemi legati alla diffusione del Covid-19 e le tensioni commerciali con gli Stati Uniti, Pechino si appresta a chiudere il 2020 con una crescita dell\u2019economia del 2% (rivisto al rialzo dal precedente +1%) secondo l\u2019ultimo \u201cAsia Pacific Economic Update\u201d della Banca Mondiale.<br \/>\nUn risultato per\u00f2 nettamente inferiore alla previsioni di inizio anno che stimavano per il Paese una crescita nell\u2019ordine del 6%.\u00a0 In base all\u2019analisi della World Bank, Pechino ha controllato l\u2019emergenza, con un focus sul mercato domestico e il rilancio delle esportazioni. Una strategia che il presidente cinese Xi Jinping ha definito dual circulation: sviluppo globale e aumento dei consumi interni.<br \/>\nCina si salva dal Covid ma Far East in recessione<br \/>\nCome evidenziato da Lorenzo Riccardi, economista Belt Road Institute di Shanghai University, nonostante i risultati attesi per la Cina il forte impatto economico e sociale causato dall\u2019emergenza sanitaria ha colpito tutta la regione del Far East. In base ai dati forniti dalla Banca Mondiale, la crescita regionale nel 2020 sar\u00e0 pari allo 0,9%: tale valore \u00e8 il pi\u00f9 basso degli ultimi cinquant\u2019anni e deve essere considerato con attenzione.\u00a0 A fronte del progresso atteso per Pechino il resto della regione entrer\u00e0 in recessione, con una contrazione di circa il 3,5%.Le uniche economie della regione oltre alla Cina che conseguiranno una crescita sono Vietnam (+2,8%) e Myanmar (+0,5%), mentre le isole del Pacifico, in particolar modo Fiji, subiranno un pesante contraccolpo.<br \/>\nSecondo Riccardi nei Paesi del Far East vi \u00e8 stata una contrazione al livello delle attivit\u00e0 economiche e industriali con una drastica riduzione del volume degli scambi commerciali e dei viaggi internazionali, impattando in particolar modo sui Paesi in cui il turismo rappresenta un\u2019importante fonte di reddito.<br \/>\nPer il 2021 le stime di Banca Mondiale tornano positive per tutta la regione: la crescita attesa di Pechino per il prossimo anno \u00e8 infatti pari al 7,9%, mentre lo sviluppo complessivo delle altre economie dell\u2019area rimbalzer\u00e0 al 5,1%. Gli scambi commerciali aumenteranno con la progressiva riapertura delle attivit\u00e0 economiche, mentre il recupero dei flussi turistici richieder\u00e0 un periodo di tempo superiore. Malaysia (6,3%), Myanmar (5,9%), Mongolia (5,6%) e Filippine (5,3%) seguono la crescita di Cina e Vietnam nel 2021.<br \/>\nLa Cina si prepara alla deglobalizzazione<br \/>\nNonostante la crescita registrata nel corso del 2020 il governo cinese sta studiando una fase di sviluppo per il Paese definita strategia della dual circulation (doppia circolazione), domestica e straniera.<br \/>\nCome ricorda Silvia Guizzo, economista di Intesa Sanpaolo questo nuovo approccio \u00e8 stato descritto in via generale nelle Due Sessioni dal presidente Xi Jinping a maggio, e ulteriormente elaborata nei mesi estivi negli interventi di diversi esponenti politici.<br \/>\nIl presidente aveva sottolineato l\u2019urgenza della costruzione di \u201cun sistema completo di consumo domestico\u201d, una forte promozione dell\u2019innovazione in campo scientifico e tecnologico, ma allo stesso tempo una continua e maggiore apertura del mercato agli investitori stranieri.Pertanto secondo Intesa Sanpaolo la strategia della doppia circolazione, che appare sempre pi\u00f9 necessaria in vista di un possibile decoupling e dell\u2019innalzamento delle tensioni con gli Usa, e non solo, si annuncia il leitmotiv del XIV\u00b0 piano quinquennale (2021-2025) che verr\u00e0 presentato in autunno nella quinta sessione plenaria del Comitato Centrale del Partito comunista cinese.<br \/>\n<br \/>\n<!--noindex--><br \/>\n<a href=\"https:\/\/www.wallstreetitalia.com\/cina-economia-si-salva-dal-covid-pil-2-e-prepara-la-dual-circulation\/\" rel=\"nofollow\">Source link <\/a><br \/>\n<!--\/noindex--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cina, economia si salva dal Covid (Pil +2%) e prepara la dual circulation Sorprese in arrivo per l\u2019economia della Cina. Nonostante i problemi legati alla diffusione del Covid-19 e le tensioni commerciali con gli Stati Uniti, Pechino si appresta a chiudere il 2020 con una crescita dell\u2019economia del 2% (rivisto al rialzo dal precedente +1%) [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1513,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1512","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-finanziarie"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cina, economia si salva dal Covid (Pil +2%) e prepara la dual circulation - Super News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/super-news.info\/it\/cina-economia-si-salva-dal-covid-pil-2-e-prepara-la-dual-circulation\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cina, economia si salva dal Covid (Pil +2%) e prepara la dual circulation - Super News\" \/>\n<meta property=\"og:description\" content=\"Cina, economia si salva dal Covid (Pil +2%) e prepara la dual circulation Sorprese in arrivo per l\u2019economia della Cina. Nonostante i problemi legati alla diffusione del Covid-19 e le tensioni commerciali con gli Stati Uniti, Pechino si appresta a chiudere il 2020 con una crescita dell\u2019economia del 2% (rivisto al rialzo dal precedente +1%) [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/super-news.info\/it\/cina-economia-si-salva-dal-covid-pil-2-e-prepara-la-dual-circulation\/\" \/>\n<meta property=\"og:site_name\" content=\"Super News\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-06T04:21:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-06T04:21:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/super-news.info\/it\/wp-content\/uploads\/sites\/9\/2020\/10\/Cina-economia-si-salva-dal-Covid-Pil-2-e-prepara.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"710\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"super-news\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"super-news\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/cina-economia-si-salva-dal-covid-pil-2-e-prepara-la-dual-circulation\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/cina-economia-si-salva-dal-covid-pil-2-e-prepara-la-dual-circulation\\\/\"},\"author\":{\"name\":\"super-news\",\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/#\\\/schema\\\/person\\\/2d4068cb2f39cd10008c2fce578a7356\"},\"headline\":\"Cina, economia si salva dal Covid (Pil +2%) e prepara la dual circulation\",\"datePublished\":\"2020-10-06T04:21:44+00:00\",\"dateModified\":\"2020-10-06T04:21:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/cina-economia-si-salva-dal-covid-pil-2-e-prepara-la-dual-circulation\\\/\"},\"wordCount\":551,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/cina-economia-si-salva-dal-covid-pil-2-e-prepara-la-dual-circulation\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/super-news.info\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2020\\\/10\\\/Cina-economia-si-salva-dal-Covid-Pil-2-e-prepara.jpg\",\"articleSection\":[\"NOTIZIE FINANZIARIE\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/super-news.info\\\/it\\\/cina-economia-si-salva-dal-covid-pil-2-e-prepara-la-dual-circulation\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/cina-economia-si-salva-dal-covid-pil-2-e-prepara-la-dual-circulation\\\/\",\"url\":\"https:\\\/\\\/super-news.info\\\/it\\\/cina-economia-si-salva-dal-covid-pil-2-e-prepara-la-dual-circulation\\\/\",\"name\":\"Cina, economia si salva dal Covid (Pil +2%) e prepara la dual circulation - Super News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/cina-economia-si-salva-dal-covid-pil-2-e-prepara-la-dual-circulation\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/cina-economia-si-salva-dal-covid-pil-2-e-prepara-la-dual-circulation\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/super-news.info\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2020\\\/10\\\/Cina-economia-si-salva-dal-Covid-Pil-2-e-prepara.jpg\",\"datePublished\":\"2020-10-06T04:21:44+00:00\",\"dateModified\":\"2020-10-06T04:21:46+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/#\\\/schema\\\/person\\\/2d4068cb2f39cd10008c2fce578a7356\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/cina-economia-si-salva-dal-covid-pil-2-e-prepara-la-dual-circulation\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/super-news.info\\\/it\\\/cina-economia-si-salva-dal-covid-pil-2-e-prepara-la-dual-circulation\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/cina-economia-si-salva-dal-covid-pil-2-e-prepara-la-dual-circulation\\\/#primaryimage\",\"url\":\"https:\\\/\\\/super-news.info\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2020\\\/10\\\/Cina-economia-si-salva-dal-Covid-Pil-2-e-prepara.jpg\",\"contentUrl\":\"https:\\\/\\\/super-news.info\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2020\\\/10\\\/Cina-economia-si-salva-dal-Covid-Pil-2-e-prepara.jpg\",\"width\":1024,\"height\":710,\"caption\":\"Cina, economia si salva dal Covid (Pil +2%) e prepara la dual circulation\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/cina-economia-si-salva-dal-covid-pil-2-e-prepara-la-dual-circulation\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/super-news.info\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cina, economia si salva dal Covid (Pil +2%) e prepara la dual circulation\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/super-news.info\\\/it\\\/\",\"name\":\"Super News\",\"description\":\"Super News from Italy\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/super-news.info\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/#\\\/schema\\\/person\\\/2d4068cb2f39cd10008c2fce578a7356\",\"name\":\"super-news\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g\",\"caption\":\"super-news\"},\"url\":\"https:\\\/\\\/super-news.info\\\/it\\\/author\\\/pt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cina, economia si salva dal Covid (Pil +2%) e prepara la dual circulation - Super News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/super-news.info\/it\/cina-economia-si-salva-dal-covid-pil-2-e-prepara-la-dual-circulation\/","og_locale":"it_IT","og_type":"article","og_title":"Cina, economia si salva dal Covid (Pil +2%) e prepara la dual circulation - Super News","og_description":"Cina, economia si salva dal Covid (Pil +2%) e prepara la dual circulation Sorprese in arrivo per l\u2019economia della Cina. Nonostante i problemi legati alla diffusione del Covid-19 e le tensioni commerciali con gli Stati Uniti, Pechino si appresta a chiudere il 2020 con una crescita dell\u2019economia del 2% (rivisto al rialzo dal precedente +1%) [&hellip;]","og_url":"https:\/\/super-news.info\/it\/cina-economia-si-salva-dal-covid-pil-2-e-prepara-la-dual-circulation\/","og_site_name":"Super News","article_published_time":"2020-10-06T04:21:44+00:00","article_modified_time":"2020-10-06T04:21:46+00:00","og_image":[{"width":1024,"height":710,"url":"https:\/\/super-news.info\/it\/wp-content\/uploads\/sites\/9\/2020\/10\/Cina-economia-si-salva-dal-Covid-Pil-2-e-prepara.jpg","type":"image\/jpeg"}],"author":"super-news","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"super-news","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/super-news.info\/it\/cina-economia-si-salva-dal-covid-pil-2-e-prepara-la-dual-circulation\/#article","isPartOf":{"@id":"https:\/\/super-news.info\/it\/cina-economia-si-salva-dal-covid-pil-2-e-prepara-la-dual-circulation\/"},"author":{"name":"super-news","@id":"https:\/\/super-news.info\/it\/#\/schema\/person\/2d4068cb2f39cd10008c2fce578a7356"},"headline":"Cina, economia si salva dal Covid (Pil +2%) e prepara la dual circulation","datePublished":"2020-10-06T04:21:44+00:00","dateModified":"2020-10-06T04:21:46+00:00","mainEntityOfPage":{"@id":"https:\/\/super-news.info\/it\/cina-economia-si-salva-dal-covid-pil-2-e-prepara-la-dual-circulation\/"},"wordCount":551,"commentCount":0,"image":{"@id":"https:\/\/super-news.info\/it\/cina-economia-si-salva-dal-covid-pil-2-e-prepara-la-dual-circulation\/#primaryimage"},"thumbnailUrl":"https:\/\/super-news.info\/it\/wp-content\/uploads\/sites\/9\/2020\/10\/Cina-economia-si-salva-dal-Covid-Pil-2-e-prepara.jpg","articleSection":["NOTIZIE FINANZIARIE"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/super-news.info\/it\/cina-economia-si-salva-dal-covid-pil-2-e-prepara-la-dual-circulation\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/super-news.info\/it\/cina-economia-si-salva-dal-covid-pil-2-e-prepara-la-dual-circulation\/","url":"https:\/\/super-news.info\/it\/cina-economia-si-salva-dal-covid-pil-2-e-prepara-la-dual-circulation\/","name":"Cina, economia si salva dal Covid (Pil +2%) e prepara la dual circulation - Super News","isPartOf":{"@id":"https:\/\/super-news.info\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/super-news.info\/it\/cina-economia-si-salva-dal-covid-pil-2-e-prepara-la-dual-circulation\/#primaryimage"},"image":{"@id":"https:\/\/super-news.info\/it\/cina-economia-si-salva-dal-covid-pil-2-e-prepara-la-dual-circulation\/#primaryimage"},"thumbnailUrl":"https:\/\/super-news.info\/it\/wp-content\/uploads\/sites\/9\/2020\/10\/Cina-economia-si-salva-dal-Covid-Pil-2-e-prepara.jpg","datePublished":"2020-10-06T04:21:44+00:00","dateModified":"2020-10-06T04:21:46+00:00","author":{"@id":"https:\/\/super-news.info\/it\/#\/schema\/person\/2d4068cb2f39cd10008c2fce578a7356"},"breadcrumb":{"@id":"https:\/\/super-news.info\/it\/cina-economia-si-salva-dal-covid-pil-2-e-prepara-la-dual-circulation\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/super-news.info\/it\/cina-economia-si-salva-dal-covid-pil-2-e-prepara-la-dual-circulation\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/super-news.info\/it\/cina-economia-si-salva-dal-covid-pil-2-e-prepara-la-dual-circulation\/#primaryimage","url":"https:\/\/super-news.info\/it\/wp-content\/uploads\/sites\/9\/2020\/10\/Cina-economia-si-salva-dal-Covid-Pil-2-e-prepara.jpg","contentUrl":"https:\/\/super-news.info\/it\/wp-content\/uploads\/sites\/9\/2020\/10\/Cina-economia-si-salva-dal-Covid-Pil-2-e-prepara.jpg","width":1024,"height":710,"caption":"Cina, economia si salva dal Covid (Pil +2%) e prepara la dual circulation"},{"@type":"BreadcrumbList","@id":"https:\/\/super-news.info\/it\/cina-economia-si-salva-dal-covid-pil-2-e-prepara-la-dual-circulation\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/super-news.info\/it\/"},{"@type":"ListItem","position":2,"name":"Cina, economia si salva dal Covid (Pil +2%) e prepara la dual circulation"}]},{"@type":"WebSite","@id":"https:\/\/super-news.info\/it\/#website","url":"https:\/\/super-news.info\/it\/","name":"Super News","description":"Super News from Italy","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/super-news.info\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/super-news.info\/it\/#\/schema\/person\/2d4068cb2f39cd10008c2fce578a7356","name":"super-news","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g","caption":"super-news"},"url":"https:\/\/super-news.info\/it\/author\/pt\/"}]}},"_links":{"self":[{"href":"https:\/\/super-news.info\/it\/wp-json\/wp\/v2\/posts\/1512","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/super-news.info\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/super-news.info\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/super-news.info\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/super-news.info\/it\/wp-json\/wp\/v2\/comments?post=1512"}],"version-history":[{"count":1,"href":"https:\/\/super-news.info\/it\/wp-json\/wp\/v2\/posts\/1512\/revisions"}],"predecessor-version":[{"id":1514,"href":"https:\/\/super-news.info\/it\/wp-json\/wp\/v2\/posts\/1512\/revisions\/1514"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/super-news.info\/it\/wp-json\/wp\/v2\/media\/1513"}],"wp:attachment":[{"href":"https:\/\/super-news.info\/it\/wp-json\/wp\/v2\/media?parent=1512"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/super-news.info\/it\/wp-json\/wp\/v2\/categories?post=1512"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/super-news.info\/it\/wp-json\/wp\/v2\/tags?post=1512"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}