{"id":1490,"date":"2020-09-24T15:36:28","date_gmt":"2020-09-24T15:36:28","guid":{"rendered":"https:\/\/super-news.info\/it\/in-cina-dilaga-il-trading-online-quotazioni-di-borsa-record-per-i-broker\/"},"modified":"2020-09-24T15:36:30","modified_gmt":"2020-09-24T15:36:30","slug":"in-cina-dilaga-il-trading-online-quotazioni-di-borsa-record-per-i-broker","status":"publish","type":"post","link":"https:\/\/super-news.info\/it\/in-cina-dilaga-il-trading-online-quotazioni-di-borsa-record-per-i-broker\/","title":{"rendered":"In Cina dilaga il trading online, quotazioni di Borsa record per i broker"},"content":{"rendered":"<p>La febbre del trading non ha contagiato solo gli Stati Uniti: anche in Cina il recupero dei mercati azionari, unito al calo dei tassi d\u2019interesse ha spinto sempre pi\u00f9 risparmiatori a buttarsi sulle piattaforme.Non solo: ha anche messo il turbo alle valutazioni delle varie societ\u00e0 cinesi attive nel business del trading.<br \/>\nBoom del trading in Cina, il caso East Money<br \/>\nEast Money, una societ\u00e0 di trading online ben nota in patria, ha registrato una performance da inizio anno pari all\u201980%, la migliore di tutto il listino del Dragone (CSI 300). Grazie a questo exploit, la capitalizzazione di mercato \u00e8 salita a 30,6 miliardi di dollari. Come ha notato il Financial Times, si tratta di un livello superiore alla capitalizzazione di Credit Suisse.<br \/>\nIl rapporto prezzi\/utili di East Money, poi, rivela quanto la societ\u00e0 sia divenuta costosa: il ratio \u00e8 di 69 contro quello di 14 che registra Charles Schwab, una societ\u00e0 americana attiva nello stesso business.<br \/>\nL\u2019intero settore sta impazzendo\u201d, ha dichiarato al Ft Hao Hong, capo della ricerca e capo strategist presso la societ\u00e0 di intermediazione mobiliare Bocom International, \u201ctutte le societ\u00e0 di intermediazione pi\u00f9 costose sono in Cina\u201d.<br \/>\nNel grafico in basso \u00e8 possibile osservare come, dietro al caso East Money ci siano numerosi altri intermediari le cui performance di Borsa si sono rivelate assai generose.<\/p>\n<p>La corsa dei risparmiatori cinesi verso il trading, in un periodo di grande incertezza economica, sarebbe stata anche un tentativo di cavalcare la ripresa dei listini (che in Cina hanno toccato il picco a luglio) e di ottenere, cos\u00ec, una fonte integrativa di reddito.Anche i fondi comuni\u00a0 azionario di nuova emissione hanno registrato forti adesioni, avendo raccolto, secondo Z-Ben Advisors, 1.000 miliardi di yuan da parte di 22 milioni di investitori.<br \/>\n<br \/>\n<!--noindex--><br \/>\n<a href=\"https:\/\/www.wallstreetitalia.com\/trading-cina\/\" rel=\"nofollow\">Source link <\/a><br \/>\n<!--\/noindex--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La febbre del trading non ha contagiato solo gli Stati Uniti: anche in Cina il recupero dei mercati azionari, unito al calo dei tassi d\u2019interesse ha spinto sempre pi\u00f9 risparmiatori a buttarsi sulle piattaforme.Non solo: ha anche messo il turbo alle valutazioni delle varie societ\u00e0 cinesi attive nel business del trading. Boom del trading in [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1491,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1490","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-finanziarie"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>In Cina dilaga il trading online, quotazioni di Borsa record per i broker - Super News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/super-news.info\/it\/in-cina-dilaga-il-trading-online-quotazioni-di-borsa-record-per-i-broker\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"In Cina dilaga il trading online, quotazioni di Borsa record per i broker - Super News\" \/>\n<meta property=\"og:description\" content=\"La febbre del trading non ha contagiato solo gli Stati Uniti: anche in Cina il recupero dei mercati azionari, unito al calo dei tassi d\u2019interesse ha spinto sempre pi\u00f9 risparmiatori a buttarsi sulle piattaforme.Non solo: ha anche messo il turbo alle valutazioni delle varie societ\u00e0 cinesi attive nel business del trading. Boom del trading in [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/super-news.info\/it\/in-cina-dilaga-il-trading-online-quotazioni-di-borsa-record-per-i-broker\/\" \/>\n<meta property=\"og:site_name\" content=\"Super News\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-24T15:36:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-24T15:36:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/super-news.info\/it\/wp-content\/uploads\/sites\/9\/2020\/09\/In-Cina-dilaga-il-trading-online-quotazioni-di-Borsa-record.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"617\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"super-news\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"super-news\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/in-cina-dilaga-il-trading-online-quotazioni-di-borsa-record-per-i-broker\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/in-cina-dilaga-il-trading-online-quotazioni-di-borsa-record-per-i-broker\\\/\"},\"author\":{\"name\":\"super-news\",\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/#\\\/schema\\\/person\\\/2d4068cb2f39cd10008c2fce578a7356\"},\"headline\":\"In Cina dilaga il trading online, quotazioni di Borsa record per i broker\",\"datePublished\":\"2020-09-24T15:36:28+00:00\",\"dateModified\":\"2020-09-24T15:36:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/in-cina-dilaga-il-trading-online-quotazioni-di-borsa-record-per-i-broker\\\/\"},\"wordCount\":300,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/in-cina-dilaga-il-trading-online-quotazioni-di-borsa-record-per-i-broker\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/super-news.info\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2020\\\/09\\\/In-Cina-dilaga-il-trading-online-quotazioni-di-Borsa-record.jpg\",\"articleSection\":[\"NOTIZIE FINANZIARIE\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/super-news.info\\\/it\\\/in-cina-dilaga-il-trading-online-quotazioni-di-borsa-record-per-i-broker\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/in-cina-dilaga-il-trading-online-quotazioni-di-borsa-record-per-i-broker\\\/\",\"url\":\"https:\\\/\\\/super-news.info\\\/it\\\/in-cina-dilaga-il-trading-online-quotazioni-di-borsa-record-per-i-broker\\\/\",\"name\":\"In Cina dilaga il trading online, quotazioni di Borsa record per i broker - Super News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/in-cina-dilaga-il-trading-online-quotazioni-di-borsa-record-per-i-broker\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/in-cina-dilaga-il-trading-online-quotazioni-di-borsa-record-per-i-broker\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/super-news.info\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2020\\\/09\\\/In-Cina-dilaga-il-trading-online-quotazioni-di-Borsa-record.jpg\",\"datePublished\":\"2020-09-24T15:36:28+00:00\",\"dateModified\":\"2020-09-24T15:36:30+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/#\\\/schema\\\/person\\\/2d4068cb2f39cd10008c2fce578a7356\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/in-cina-dilaga-il-trading-online-quotazioni-di-borsa-record-per-i-broker\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/super-news.info\\\/it\\\/in-cina-dilaga-il-trading-online-quotazioni-di-borsa-record-per-i-broker\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/in-cina-dilaga-il-trading-online-quotazioni-di-borsa-record-per-i-broker\\\/#primaryimage\",\"url\":\"https:\\\/\\\/super-news.info\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2020\\\/09\\\/In-Cina-dilaga-il-trading-online-quotazioni-di-Borsa-record.jpg\",\"contentUrl\":\"https:\\\/\\\/super-news.info\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2020\\\/09\\\/In-Cina-dilaga-il-trading-online-quotazioni-di-Borsa-record.jpg\",\"width\":1024,\"height\":617,\"caption\":\"In Cina dilaga il trading online, quotazioni di Borsa record per i broker\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/in-cina-dilaga-il-trading-online-quotazioni-di-borsa-record-per-i-broker\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/super-news.info\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"In Cina dilaga il trading online, quotazioni di Borsa record per i broker\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/super-news.info\\\/it\\\/\",\"name\":\"Super News\",\"description\":\"Super News from Italy\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/super-news.info\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/#\\\/schema\\\/person\\\/2d4068cb2f39cd10008c2fce578a7356\",\"name\":\"super-news\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g\",\"caption\":\"super-news\"},\"url\":\"https:\\\/\\\/super-news.info\\\/it\\\/author\\\/pt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"In Cina dilaga il trading online, quotazioni di Borsa record per i broker - Super News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/super-news.info\/it\/in-cina-dilaga-il-trading-online-quotazioni-di-borsa-record-per-i-broker\/","og_locale":"it_IT","og_type":"article","og_title":"In Cina dilaga il trading online, quotazioni di Borsa record per i broker - Super News","og_description":"La febbre del trading non ha contagiato solo gli Stati Uniti: anche in Cina il recupero dei mercati azionari, unito al calo dei tassi d\u2019interesse ha spinto sempre pi\u00f9 risparmiatori a buttarsi sulle piattaforme.Non solo: ha anche messo il turbo alle valutazioni delle varie societ\u00e0 cinesi attive nel business del trading. Boom del trading in [&hellip;]","og_url":"https:\/\/super-news.info\/it\/in-cina-dilaga-il-trading-online-quotazioni-di-borsa-record-per-i-broker\/","og_site_name":"Super News","article_published_time":"2020-09-24T15:36:28+00:00","article_modified_time":"2020-09-24T15:36:30+00:00","og_image":[{"width":1024,"height":617,"url":"https:\/\/super-news.info\/it\/wp-content\/uploads\/sites\/9\/2020\/09\/In-Cina-dilaga-il-trading-online-quotazioni-di-Borsa-record.jpg","type":"image\/jpeg"}],"author":"super-news","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"super-news","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/super-news.info\/it\/in-cina-dilaga-il-trading-online-quotazioni-di-borsa-record-per-i-broker\/#article","isPartOf":{"@id":"https:\/\/super-news.info\/it\/in-cina-dilaga-il-trading-online-quotazioni-di-borsa-record-per-i-broker\/"},"author":{"name":"super-news","@id":"https:\/\/super-news.info\/it\/#\/schema\/person\/2d4068cb2f39cd10008c2fce578a7356"},"headline":"In Cina dilaga il trading online, quotazioni di Borsa record per i broker","datePublished":"2020-09-24T15:36:28+00:00","dateModified":"2020-09-24T15:36:30+00:00","mainEntityOfPage":{"@id":"https:\/\/super-news.info\/it\/in-cina-dilaga-il-trading-online-quotazioni-di-borsa-record-per-i-broker\/"},"wordCount":300,"commentCount":0,"image":{"@id":"https:\/\/super-news.info\/it\/in-cina-dilaga-il-trading-online-quotazioni-di-borsa-record-per-i-broker\/#primaryimage"},"thumbnailUrl":"https:\/\/super-news.info\/it\/wp-content\/uploads\/sites\/9\/2020\/09\/In-Cina-dilaga-il-trading-online-quotazioni-di-Borsa-record.jpg","articleSection":["NOTIZIE FINANZIARIE"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/super-news.info\/it\/in-cina-dilaga-il-trading-online-quotazioni-di-borsa-record-per-i-broker\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/super-news.info\/it\/in-cina-dilaga-il-trading-online-quotazioni-di-borsa-record-per-i-broker\/","url":"https:\/\/super-news.info\/it\/in-cina-dilaga-il-trading-online-quotazioni-di-borsa-record-per-i-broker\/","name":"In Cina dilaga il trading online, quotazioni di Borsa record per i broker - Super News","isPartOf":{"@id":"https:\/\/super-news.info\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/super-news.info\/it\/in-cina-dilaga-il-trading-online-quotazioni-di-borsa-record-per-i-broker\/#primaryimage"},"image":{"@id":"https:\/\/super-news.info\/it\/in-cina-dilaga-il-trading-online-quotazioni-di-borsa-record-per-i-broker\/#primaryimage"},"thumbnailUrl":"https:\/\/super-news.info\/it\/wp-content\/uploads\/sites\/9\/2020\/09\/In-Cina-dilaga-il-trading-online-quotazioni-di-Borsa-record.jpg","datePublished":"2020-09-24T15:36:28+00:00","dateModified":"2020-09-24T15:36:30+00:00","author":{"@id":"https:\/\/super-news.info\/it\/#\/schema\/person\/2d4068cb2f39cd10008c2fce578a7356"},"breadcrumb":{"@id":"https:\/\/super-news.info\/it\/in-cina-dilaga-il-trading-online-quotazioni-di-borsa-record-per-i-broker\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/super-news.info\/it\/in-cina-dilaga-il-trading-online-quotazioni-di-borsa-record-per-i-broker\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/super-news.info\/it\/in-cina-dilaga-il-trading-online-quotazioni-di-borsa-record-per-i-broker\/#primaryimage","url":"https:\/\/super-news.info\/it\/wp-content\/uploads\/sites\/9\/2020\/09\/In-Cina-dilaga-il-trading-online-quotazioni-di-Borsa-record.jpg","contentUrl":"https:\/\/super-news.info\/it\/wp-content\/uploads\/sites\/9\/2020\/09\/In-Cina-dilaga-il-trading-online-quotazioni-di-Borsa-record.jpg","width":1024,"height":617,"caption":"In Cina dilaga il trading online, quotazioni di Borsa record per i broker"},{"@type":"BreadcrumbList","@id":"https:\/\/super-news.info\/it\/in-cina-dilaga-il-trading-online-quotazioni-di-borsa-record-per-i-broker\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/super-news.info\/it\/"},{"@type":"ListItem","position":2,"name":"In Cina dilaga il trading online, quotazioni di Borsa record per i broker"}]},{"@type":"WebSite","@id":"https:\/\/super-news.info\/it\/#website","url":"https:\/\/super-news.info\/it\/","name":"Super News","description":"Super News from Italy","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/super-news.info\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/super-news.info\/it\/#\/schema\/person\/2d4068cb2f39cd10008c2fce578a7356","name":"super-news","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g","caption":"super-news"},"url":"https:\/\/super-news.info\/it\/author\/pt\/"}]}},"_links":{"self":[{"href":"https:\/\/super-news.info\/it\/wp-json\/wp\/v2\/posts\/1490","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/super-news.info\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/super-news.info\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/super-news.info\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/super-news.info\/it\/wp-json\/wp\/v2\/comments?post=1490"}],"version-history":[{"count":1,"href":"https:\/\/super-news.info\/it\/wp-json\/wp\/v2\/posts\/1490\/revisions"}],"predecessor-version":[{"id":1492,"href":"https:\/\/super-news.info\/it\/wp-json\/wp\/v2\/posts\/1490\/revisions\/1492"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/super-news.info\/it\/wp-json\/wp\/v2\/media\/1491"}],"wp:attachment":[{"href":"https:\/\/super-news.info\/it\/wp-json\/wp\/v2\/media?parent=1490"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/super-news.info\/it\/wp-json\/wp\/v2\/categories?post=1490"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/super-news.info\/it\/wp-json\/wp\/v2\/tags?post=1490"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}