{"id":1472,"date":"2020-09-16T00:17:37","date_gmt":"2020-09-16T00:17:37","guid":{"rendered":"https:\/\/super-news.info\/it\/volano-fca-ed-exor-dopo-il-nuovo-accordo-sulla-fusione-con-psa\/"},"modified":"2020-09-16T00:17:39","modified_gmt":"2020-09-16T00:17:39","slug":"volano-fca-ed-exor-dopo-il-nuovo-accordo-sulla-fusione-con-psa","status":"publish","type":"post","link":"https:\/\/super-news.info\/it\/volano-fca-ed-exor-dopo-il-nuovo-accordo-sulla-fusione-con-psa\/","title":{"rendered":"Volano Fca ed Exor dopo il nuovo accordo sulla fusione con Psa"},"content":{"rendered":"<p>Gli investitori hanno premiato nella seduta di oggi, 15 settembre, le modifiche apportate all\u2019accordo sulla fusione fra i gruppi automobilistici Fca e Psa nel nuovo gruppo Stellantis, il quarto produttore mondiale di auto.<br \/>\nFiat Chrysler ha chiuso le contrattazioni in rialzo del 9,01%, mentre la holding della famiglia Agnelli, Exor, ha guadagnato il 5,91%.<br \/>\nSalta subito all\u2019occhio, fra le modifiche comunicate dai due gruppi, la decisa riduzione del dividendo che sar\u00e0 distribuito agli azionisti di Fca prima del closing dell\u2019operazione: si \u00e8 passati da 5,5 miliardi a 2,9 miliardi di euro.L\u2019altra differenza sostanziale riguarda la propriet\u00e0 del produttore di componentistica Faurecia nell\u2019assetto societario post-fusione.<br \/>\nAttualmente la societ\u00e0 \u00e8 detenuta al 46% da Psa; al termine del merger gli azionisti dei due gruppi riceveranno una quota paritaria del 23%. Resta invariato, invece, lo schema che vedr\u00e0 una fusione alla pari fra Fca e Psa.I due consigli di amministrazione, inoltre, si riservano la possibilit\u00e0 di distribuire 500 milioni ai rispettivi azionisti prima della fusione, oppure, in seguito a quest\u2019ultima, 1 miliardo a tutti gli azionisti di Stellantis, la societ\u00e0 risultante dall\u2019integrazione.<br \/>\nSalgono le stime sulle sinergie<br \/>\nAl di l\u00e0 degli aspetti strettamente legati alla remunerazione degli azionisti, le due societ\u00e0 hanno aggiornato il valore delle sinergie che la fusione apporterebbe ai due gruppi dalle quali deriva la valenza strategica per la competitivit\u00e0 della nuova societ\u00e0: si passa dai 3,7 miliardi inizialmente annunciati a oltre 5 miliardi di euro.<br \/>\n\u201cCon questo nuovo decisivo passo\u201d, ha commentato Carlos Tavares, presidente di Psa, \u201cci stiamo avvicinando al nostro obiettivo nelle migliori condizioni possibili con prospettive ancora migliori\u201d.<br \/>\nLa holding\u00a0Exor, da parte sua, \u201cconferma il proprio continuo sostegno e impegno a favore della combinazione. In particolare,\u00a0Exor\u00a0supporta con forza le azioni che le societ\u00e0 hanno compiuto per mantenere il valore economico e l\u2019equilibrio presenti nel combination agreement iniziale, rafforzando al contempo la solidit\u00e0 della struttura del capitale iniziale di Stellantis. Stellantis potr\u00e0 cos\u00ec cogliere appieno la straordinaria opportunit\u00e0 di creare valore di lungo termine per tutti i suoi azionisti, come evidenziato dal significativo aumento delle sinergie attese dalla fusione che sono state annunciate oggi\u201d.<br \/>\n<br \/>\n<!--noindex--><br \/>\n<a href=\"https:\/\/www.wallstreetitalia.com\/volano-fca-ed-exor-dopo-il-nuovo-accordo-sulla-fusione-con-psa\/\" rel=\"nofollow\">Source link <\/a><br \/>\n<!--\/noindex--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gli investitori hanno premiato nella seduta di oggi, 15 settembre, le modifiche apportate all\u2019accordo sulla fusione fra i gruppi automobilistici Fca e Psa nel nuovo gruppo Stellantis, il quarto produttore mondiale di auto. Fiat Chrysler ha chiuso le contrattazioni in rialzo del 9,01%, mentre la holding della famiglia Agnelli, Exor, ha guadagnato il 5,91%. Salta [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1473,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1472","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-finanziarie"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Volano Fca ed Exor dopo il nuovo accordo sulla fusione con Psa - Super News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/super-news.info\/it\/volano-fca-ed-exor-dopo-il-nuovo-accordo-sulla-fusione-con-psa\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Volano Fca ed Exor dopo il nuovo accordo sulla fusione con Psa - Super News\" \/>\n<meta property=\"og:description\" content=\"Gli investitori hanno premiato nella seduta di oggi, 15 settembre, le modifiche apportate all\u2019accordo sulla fusione fra i gruppi automobilistici Fca e Psa nel nuovo gruppo Stellantis, il quarto produttore mondiale di auto. Fiat Chrysler ha chiuso le contrattazioni in rialzo del 9,01%, mentre la holding della famiglia Agnelli, Exor, ha guadagnato il 5,91%. Salta [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/super-news.info\/it\/volano-fca-ed-exor-dopo-il-nuovo-accordo-sulla-fusione-con-psa\/\" \/>\n<meta property=\"og:site_name\" content=\"Super News\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-16T00:17:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-16T00:17:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/super-news.info\/it\/wp-content\/uploads\/sites\/9\/2020\/09\/Volano-Fca-ed-Exor-dopo-il-nuovo-accordo-sulla-fusione.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"super-news\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"super-news\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/volano-fca-ed-exor-dopo-il-nuovo-accordo-sulla-fusione-con-psa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/volano-fca-ed-exor-dopo-il-nuovo-accordo-sulla-fusione-con-psa\\\/\"},\"author\":{\"name\":\"super-news\",\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/#\\\/schema\\\/person\\\/2d4068cb2f39cd10008c2fce578a7356\"},\"headline\":\"Volano Fca ed Exor dopo il nuovo accordo sulla fusione con Psa\",\"datePublished\":\"2020-09-16T00:17:37+00:00\",\"dateModified\":\"2020-09-16T00:17:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/volano-fca-ed-exor-dopo-il-nuovo-accordo-sulla-fusione-con-psa\\\/\"},\"wordCount\":361,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/volano-fca-ed-exor-dopo-il-nuovo-accordo-sulla-fusione-con-psa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/super-news.info\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2020\\\/09\\\/Volano-Fca-ed-Exor-dopo-il-nuovo-accordo-sulla-fusione.jpg\",\"articleSection\":[\"NOTIZIE FINANZIARIE\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/super-news.info\\\/it\\\/volano-fca-ed-exor-dopo-il-nuovo-accordo-sulla-fusione-con-psa\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/volano-fca-ed-exor-dopo-il-nuovo-accordo-sulla-fusione-con-psa\\\/\",\"url\":\"https:\\\/\\\/super-news.info\\\/it\\\/volano-fca-ed-exor-dopo-il-nuovo-accordo-sulla-fusione-con-psa\\\/\",\"name\":\"Volano Fca ed Exor dopo il nuovo accordo sulla fusione con Psa - Super News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/volano-fca-ed-exor-dopo-il-nuovo-accordo-sulla-fusione-con-psa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/volano-fca-ed-exor-dopo-il-nuovo-accordo-sulla-fusione-con-psa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/super-news.info\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2020\\\/09\\\/Volano-Fca-ed-Exor-dopo-il-nuovo-accordo-sulla-fusione.jpg\",\"datePublished\":\"2020-09-16T00:17:37+00:00\",\"dateModified\":\"2020-09-16T00:17:39+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/#\\\/schema\\\/person\\\/2d4068cb2f39cd10008c2fce578a7356\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/volano-fca-ed-exor-dopo-il-nuovo-accordo-sulla-fusione-con-psa\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/super-news.info\\\/it\\\/volano-fca-ed-exor-dopo-il-nuovo-accordo-sulla-fusione-con-psa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/volano-fca-ed-exor-dopo-il-nuovo-accordo-sulla-fusione-con-psa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/super-news.info\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2020\\\/09\\\/Volano-Fca-ed-Exor-dopo-il-nuovo-accordo-sulla-fusione.jpg\",\"contentUrl\":\"https:\\\/\\\/super-news.info\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2020\\\/09\\\/Volano-Fca-ed-Exor-dopo-il-nuovo-accordo-sulla-fusione.jpg\",\"width\":640,\"height\":450,\"caption\":\"Volano Fca ed Exor dopo il nuovo accordo sulla fusione con Psa\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/volano-fca-ed-exor-dopo-il-nuovo-accordo-sulla-fusione-con-psa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/super-news.info\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Volano Fca ed Exor dopo il nuovo accordo sulla fusione con Psa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/super-news.info\\\/it\\\/\",\"name\":\"Super News\",\"description\":\"Super News from Italy\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/super-news.info\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/#\\\/schema\\\/person\\\/2d4068cb2f39cd10008c2fce578a7356\",\"name\":\"super-news\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g\",\"caption\":\"super-news\"},\"url\":\"https:\\\/\\\/super-news.info\\\/it\\\/author\\\/pt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Volano Fca ed Exor dopo il nuovo accordo sulla fusione con Psa - Super News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/super-news.info\/it\/volano-fca-ed-exor-dopo-il-nuovo-accordo-sulla-fusione-con-psa\/","og_locale":"it_IT","og_type":"article","og_title":"Volano Fca ed Exor dopo il nuovo accordo sulla fusione con Psa - Super News","og_description":"Gli investitori hanno premiato nella seduta di oggi, 15 settembre, le modifiche apportate all\u2019accordo sulla fusione fra i gruppi automobilistici Fca e Psa nel nuovo gruppo Stellantis, il quarto produttore mondiale di auto. Fiat Chrysler ha chiuso le contrattazioni in rialzo del 9,01%, mentre la holding della famiglia Agnelli, Exor, ha guadagnato il 5,91%. Salta [&hellip;]","og_url":"https:\/\/super-news.info\/it\/volano-fca-ed-exor-dopo-il-nuovo-accordo-sulla-fusione-con-psa\/","og_site_name":"Super News","article_published_time":"2020-09-16T00:17:37+00:00","article_modified_time":"2020-09-16T00:17:39+00:00","og_image":[{"width":640,"height":450,"url":"https:\/\/super-news.info\/it\/wp-content\/uploads\/sites\/9\/2020\/09\/Volano-Fca-ed-Exor-dopo-il-nuovo-accordo-sulla-fusione.jpg","type":"image\/jpeg"}],"author":"super-news","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"super-news","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/super-news.info\/it\/volano-fca-ed-exor-dopo-il-nuovo-accordo-sulla-fusione-con-psa\/#article","isPartOf":{"@id":"https:\/\/super-news.info\/it\/volano-fca-ed-exor-dopo-il-nuovo-accordo-sulla-fusione-con-psa\/"},"author":{"name":"super-news","@id":"https:\/\/super-news.info\/it\/#\/schema\/person\/2d4068cb2f39cd10008c2fce578a7356"},"headline":"Volano Fca ed Exor dopo il nuovo accordo sulla fusione con Psa","datePublished":"2020-09-16T00:17:37+00:00","dateModified":"2020-09-16T00:17:39+00:00","mainEntityOfPage":{"@id":"https:\/\/super-news.info\/it\/volano-fca-ed-exor-dopo-il-nuovo-accordo-sulla-fusione-con-psa\/"},"wordCount":361,"commentCount":0,"image":{"@id":"https:\/\/super-news.info\/it\/volano-fca-ed-exor-dopo-il-nuovo-accordo-sulla-fusione-con-psa\/#primaryimage"},"thumbnailUrl":"https:\/\/super-news.info\/it\/wp-content\/uploads\/sites\/9\/2020\/09\/Volano-Fca-ed-Exor-dopo-il-nuovo-accordo-sulla-fusione.jpg","articleSection":["NOTIZIE FINANZIARIE"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/super-news.info\/it\/volano-fca-ed-exor-dopo-il-nuovo-accordo-sulla-fusione-con-psa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/super-news.info\/it\/volano-fca-ed-exor-dopo-il-nuovo-accordo-sulla-fusione-con-psa\/","url":"https:\/\/super-news.info\/it\/volano-fca-ed-exor-dopo-il-nuovo-accordo-sulla-fusione-con-psa\/","name":"Volano Fca ed Exor dopo il nuovo accordo sulla fusione con Psa - Super News","isPartOf":{"@id":"https:\/\/super-news.info\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/super-news.info\/it\/volano-fca-ed-exor-dopo-il-nuovo-accordo-sulla-fusione-con-psa\/#primaryimage"},"image":{"@id":"https:\/\/super-news.info\/it\/volano-fca-ed-exor-dopo-il-nuovo-accordo-sulla-fusione-con-psa\/#primaryimage"},"thumbnailUrl":"https:\/\/super-news.info\/it\/wp-content\/uploads\/sites\/9\/2020\/09\/Volano-Fca-ed-Exor-dopo-il-nuovo-accordo-sulla-fusione.jpg","datePublished":"2020-09-16T00:17:37+00:00","dateModified":"2020-09-16T00:17:39+00:00","author":{"@id":"https:\/\/super-news.info\/it\/#\/schema\/person\/2d4068cb2f39cd10008c2fce578a7356"},"breadcrumb":{"@id":"https:\/\/super-news.info\/it\/volano-fca-ed-exor-dopo-il-nuovo-accordo-sulla-fusione-con-psa\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/super-news.info\/it\/volano-fca-ed-exor-dopo-il-nuovo-accordo-sulla-fusione-con-psa\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/super-news.info\/it\/volano-fca-ed-exor-dopo-il-nuovo-accordo-sulla-fusione-con-psa\/#primaryimage","url":"https:\/\/super-news.info\/it\/wp-content\/uploads\/sites\/9\/2020\/09\/Volano-Fca-ed-Exor-dopo-il-nuovo-accordo-sulla-fusione.jpg","contentUrl":"https:\/\/super-news.info\/it\/wp-content\/uploads\/sites\/9\/2020\/09\/Volano-Fca-ed-Exor-dopo-il-nuovo-accordo-sulla-fusione.jpg","width":640,"height":450,"caption":"Volano Fca ed Exor dopo il nuovo accordo sulla fusione con Psa"},{"@type":"BreadcrumbList","@id":"https:\/\/super-news.info\/it\/volano-fca-ed-exor-dopo-il-nuovo-accordo-sulla-fusione-con-psa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/super-news.info\/it\/"},{"@type":"ListItem","position":2,"name":"Volano Fca ed Exor dopo il nuovo accordo sulla fusione con Psa"}]},{"@type":"WebSite","@id":"https:\/\/super-news.info\/it\/#website","url":"https:\/\/super-news.info\/it\/","name":"Super News","description":"Super News from Italy","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/super-news.info\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/super-news.info\/it\/#\/schema\/person\/2d4068cb2f39cd10008c2fce578a7356","name":"super-news","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g","caption":"super-news"},"url":"https:\/\/super-news.info\/it\/author\/pt\/"}]}},"_links":{"self":[{"href":"https:\/\/super-news.info\/it\/wp-json\/wp\/v2\/posts\/1472","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/super-news.info\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/super-news.info\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/super-news.info\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/super-news.info\/it\/wp-json\/wp\/v2\/comments?post=1472"}],"version-history":[{"count":1,"href":"https:\/\/super-news.info\/it\/wp-json\/wp\/v2\/posts\/1472\/revisions"}],"predecessor-version":[{"id":1474,"href":"https:\/\/super-news.info\/it\/wp-json\/wp\/v2\/posts\/1472\/revisions\/1474"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/super-news.info\/it\/wp-json\/wp\/v2\/media\/1473"}],"wp:attachment":[{"href":"https:\/\/super-news.info\/it\/wp-json\/wp\/v2\/media?parent=1472"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/super-news.info\/it\/wp-json\/wp\/v2\/categories?post=1472"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/super-news.info\/it\/wp-json\/wp\/v2\/tags?post=1472"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}