{"id":1169,"date":"2019-09-19T10:05:05","date_gmt":"2019-09-19T10:05:05","guid":{"rendered":"https:\/\/super-news.info\/it\/pensionati-italia-sorpassata-dal-portogallo-per-qualita-della-vita\/"},"modified":"2019-09-19T10:05:06","modified_gmt":"2019-09-19T10:05:06","slug":"pensionati-italia-sorpassata-dal-portogallo-per-qualita-della-vita","status":"publish","type":"post","link":"https:\/\/super-news.info\/it\/pensionati-italia-sorpassata-dal-portogallo-per-qualita-della-vita\/","title":{"rendered":"Pensionati: Italia sorpassata dal Portogallo per qualit\u00e0 della vita"},"content":{"rendered":"<p>\t\t\t\t\t\tIn Italia migliora la qualit\u00e0 della vita dei pensionati italiani,\u00a0tuttavia l\u2019invecchiamento demografico e l\u2019alto livello di indebitamento rappresentano sfide inevitabili per il futuro. Sono alcuni dei risultati emersi dalla settima edizione del\u00a0Global Retirement Index (GRI) elaborato da Natixis Investment Managers,\u00a0uno strumento grazie al quale \u00e8 possibile comparare le best practice delle politiche pubbliche pensionistiche di 44 paesi.<br \/>\nDall\u2019indice emerge che l\u2019Italia mostra lo stesso punteggio complessivo degli ultimi due anni, 63%, ma perde una posizione, classificandosi al trentesimo posto, a causa del sorpasso del Portogallo.<br \/>\nLanciato nel 2013, il Global Retirement Index assegna un punteggio generale ai paesi nelle aree di sostenibilit\u00e0 del sistema pensionistico, basato su quattro sottoindici, corrispondenti ai diversi fattori di benessere che impattano sulla vita dei pensionati: il benessere materiale che consente di vivere comodamente (Material Wellbeing), il benessere finanziario, legato all\u2019accesso ai servizi finanziari di qualit\u00e0 al fine di preservare i risparmi e massimizzare i rendimenti (Finances in Retirement), la salute, legata l\u2019accesso a servizi sanitari di qualit\u00e0 (Health) e, la qualit\u00e0 della vita, legata alla possibilit\u00e0 di vivere un ambiente pi\u00f9 pulito e sicuro (Quality of Life).<br \/>\nEsaminando le singole aree, \u00e8 stato registrato un miglioramento nel sottoindice sulla qualit\u00e0 della vita, che passa dal 70 al 73% consentendo all\u2019Italia di guadagnare due posizioni nella classifica di settore (dal 26\u00b0 al 24\u00b0 posto), cos\u00ec come nel benessere finanziario in pensione che ha segnato un lieve miglioramento dal 52 al 53%. Il sottoindice sul benessere materiale \u00e8 stabile al 51%. D\u2019altro canto, il sottoindice sulla salute \u00e8 diminuito dall\u201983 al 81%.<br \/>\nL\u2019aumento della qualit\u00e0 della vita \u00e8 stato favorito da un miglioramento dell\u2019indicatore di felicit\u00e0 della popolazione. L\u2019indice sul benessere finanziario in et\u00e0 pensionabile \u00e8 migliorato lievemente, grazie ad un significativo miglioramento nella gestione dei NPL (da 20 a 32%).<br \/>\nTuttavia l\u2019invecchiamento della popolazione, il debito pubblico, la pressione fiscale e la governance stessa rappresentano ancora le principali sfide che l\u2019Italia deve affrontare guardando al futuro.<br \/>\nRisultati contrastanti nel fronte salute (unico sottoindice in cui il paese ha registrato un punteggio inferiore rispetto allo scorso anno), laddove a un miglioramento del punteggio della spesa pro-capite corrisponde un peggioramento delle aspettative di vita e spese per assicurazioni sanitaria.<br \/>\n\u201cNonostante le buone notizie relative al miglioramento della Qualit\u00e0 della Vita, i nodi da sciogliere per l\u2019Italia sono ancora molti, tra cui l\u2019invecchiamento della popolazione, debito pubblico e pressione fiscale\u201d dichiara Antonio Bottillo, Country Head ed Executive Managing Director per l\u2019Italia di Natixis Investment Managers. \u201c\u201dE\u2019 necessario che tra politici, fondi pensione, lavoratori e industria finanziaria ci sia una maggiore condivisione del duplice obiettivo di soddisfare le esigenze della popolazione in et\u00e0 pensionabile e preservare la sicurezza pensionistica dei pensionati del domani, all\u2019insegna di un costante dialogo tra tutte le parti\u201d..<br \/>\nGRI 2019: chi vince e chi perde<br \/>\nA posizionarsi in vetta alla classifica della settima edizione del Global Retirement Index \u00e8 l\u2019Islanda che riesce a superare la Svizzera, in discesa al secondo posto. Al terzo posto si conferma la Norvegia. Al quarto si piazza l\u2019Irlanda che continua cos\u00ec la sua ascesa dopo essere stata al 7\u00b0 posto nel 2018, al 14\u00b0 posto nel 2017 e al 16\u00b0 posto nel 2016. Tra i paesi Nordici, nella Top Ten figurano anche Svezia (al sesto posto, in calo di una posizione rispetto allo scorso anno) e Danimarca (al settimo posto). Il Canada guadagna una posizione, piazzandosi all\u2019ottavo posto, seguita dall\u2019Australia. A chiudere la Top Ten il Lussemburgo che per la prima volta si piazza nelle prime dieci posizioni, confermando il punteggio pi\u00f9 alto nell\u2019ambito delle sottoindice della salute (91).<br \/>\nIslanda, Svizzera e Norvegia figurano sul podio grazie alla spinta dei sottoindici legati alla salute e alla qualit\u00e0 della vita. Inoltre, l\u2019Islanda conquista la vetta grazie all\u2019indice del benessere materiale che raggiunge quota 91%, il pi\u00f9 altro tra tutti i 44 Paesi. La tigre celtica, invece, continua la sua ascesa grazie al miglioramento del punteggio ottenuto dal sottoindice della salute (pari all\u201987%, passando dal 19\u00b0 al 9\u00b0 posto) e confermando l\u2019elevato livello della qualit\u00e0 della vita, con il sottoindice relativo pari all\u201983%.<br \/>\nRispetto all\u2019edizione 2018, fuori dalle prime dieci posizioni i Paesi Bassi, che scendono dal 10\u00b0 al 13\u00b0 posto, mentre la Germania si conferma al 13\u00b0 posto, dopo avere militato negli anni precedenti nella Top Ten.<br \/>\n\u00a0<\/p>\n<p>\n<!--noindex--><br \/>\n<a href=\"https:\/\/www.wallstreetitalia.com\/pensionati-italia-sorpassata-dal-portogallo-per-qualita-della-vita\/\" rel=\"nofollow\">Source link <\/a><br \/>\n<!--\/noindex--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>In Italia migliora la qualit\u00e0 della vita dei pensionati italiani,\u00a0tuttavia l\u2019invecchiamento demografico e l\u2019alto livello di indebitamento rappresentano sfide inevitabili per il futuro. Sono alcuni dei risultati emersi dalla settima edizione del\u00a0Global Retirement Index (GRI) elaborato da Natixis Investment Managers,\u00a0uno strumento grazie al quale \u00e8 possibile comparare le best practice delle politiche pubbliche pensionistiche di [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":323,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1169","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-finanziarie"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pensionati: Italia sorpassata dal Portogallo per qualit\u00e0 della vita - Super News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/super-news.info\/it\/pensionati-italia-sorpassata-dal-portogallo-per-qualita-della-vita\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pensionati: Italia sorpassata dal Portogallo per qualit\u00e0 della vita - Super News\" \/>\n<meta property=\"og:description\" content=\"In Italia migliora la qualit\u00e0 della vita dei pensionati italiani,\u00a0tuttavia l\u2019invecchiamento demografico e l\u2019alto livello di indebitamento rappresentano sfide inevitabili per il futuro. Sono alcuni dei risultati emersi dalla settima edizione del\u00a0Global Retirement Index (GRI) elaborato da Natixis Investment Managers,\u00a0uno strumento grazie al quale \u00e8 possibile comparare le best practice delle politiche pubbliche pensionistiche di [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/super-news.info\/it\/pensionati-italia-sorpassata-dal-portogallo-per-qualita-della-vita\/\" \/>\n<meta property=\"og:site_name\" content=\"Super News\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-19T10:05:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-09-19T10:05:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/super-news.info\/it\/wp-content\/uploads\/sites\/9\/2019\/08\/In-buona-salute-e-autonomi-nella-gestione-finanziaria-lidentikit-degli.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"450\" \/>\n\t<meta property=\"og:image:height\" content=\"370\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"super-news\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"super-news\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/pensionati-italia-sorpassata-dal-portogallo-per-qualita-della-vita\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/pensionati-italia-sorpassata-dal-portogallo-per-qualita-della-vita\\\/\"},\"author\":{\"name\":\"super-news\",\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/#\\\/schema\\\/person\\\/2d4068cb2f39cd10008c2fce578a7356\"},\"headline\":\"Pensionati: Italia sorpassata dal Portogallo per qualit\u00e0 della vita\",\"datePublished\":\"2019-09-19T10:05:05+00:00\",\"dateModified\":\"2019-09-19T10:05:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/pensionati-italia-sorpassata-dal-portogallo-per-qualita-della-vita\\\/\"},\"wordCount\":710,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/pensionati-italia-sorpassata-dal-portogallo-per-qualita-della-vita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/super-news.info\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2019\\\/08\\\/In-buona-salute-e-autonomi-nella-gestione-finanziaria-lidentikit-degli.jpg\",\"articleSection\":[\"NOTIZIE FINANZIARIE\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/super-news.info\\\/it\\\/pensionati-italia-sorpassata-dal-portogallo-per-qualita-della-vita\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/pensionati-italia-sorpassata-dal-portogallo-per-qualita-della-vita\\\/\",\"url\":\"https:\\\/\\\/super-news.info\\\/it\\\/pensionati-italia-sorpassata-dal-portogallo-per-qualita-della-vita\\\/\",\"name\":\"Pensionati: Italia sorpassata dal Portogallo per qualit\u00e0 della vita - Super News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/pensionati-italia-sorpassata-dal-portogallo-per-qualita-della-vita\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/pensionati-italia-sorpassata-dal-portogallo-per-qualita-della-vita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/super-news.info\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2019\\\/08\\\/In-buona-salute-e-autonomi-nella-gestione-finanziaria-lidentikit-degli.jpg\",\"datePublished\":\"2019-09-19T10:05:05+00:00\",\"dateModified\":\"2019-09-19T10:05:06+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/#\\\/schema\\\/person\\\/2d4068cb2f39cd10008c2fce578a7356\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/pensionati-italia-sorpassata-dal-portogallo-per-qualita-della-vita\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/super-news.info\\\/it\\\/pensionati-italia-sorpassata-dal-portogallo-per-qualita-della-vita\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/pensionati-italia-sorpassata-dal-portogallo-per-qualita-della-vita\\\/#primaryimage\",\"url\":\"https:\\\/\\\/super-news.info\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2019\\\/08\\\/In-buona-salute-e-autonomi-nella-gestione-finanziaria-lidentikit-degli.jpg\",\"contentUrl\":\"https:\\\/\\\/super-news.info\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2019\\\/08\\\/In-buona-salute-e-autonomi-nella-gestione-finanziaria-lidentikit-degli.jpg\",\"width\":450,\"height\":370,\"caption\":\"test\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/pensionati-italia-sorpassata-dal-portogallo-per-qualita-della-vita\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/super-news.info\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pensionati: Italia sorpassata dal Portogallo per qualit\u00e0 della vita\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/super-news.info\\\/it\\\/\",\"name\":\"Super News\",\"description\":\"Super News from Italy\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/super-news.info\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/super-news.info\\\/it\\\/#\\\/schema\\\/person\\\/2d4068cb2f39cd10008c2fce578a7356\",\"name\":\"super-news\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g\",\"caption\":\"super-news\"},\"url\":\"https:\\\/\\\/super-news.info\\\/it\\\/author\\\/pt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pensionati: Italia sorpassata dal Portogallo per qualit\u00e0 della vita - Super News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/super-news.info\/it\/pensionati-italia-sorpassata-dal-portogallo-per-qualita-della-vita\/","og_locale":"it_IT","og_type":"article","og_title":"Pensionati: Italia sorpassata dal Portogallo per qualit\u00e0 della vita - Super News","og_description":"In Italia migliora la qualit\u00e0 della vita dei pensionati italiani,\u00a0tuttavia l\u2019invecchiamento demografico e l\u2019alto livello di indebitamento rappresentano sfide inevitabili per il futuro. Sono alcuni dei risultati emersi dalla settima edizione del\u00a0Global Retirement Index (GRI) elaborato da Natixis Investment Managers,\u00a0uno strumento grazie al quale \u00e8 possibile comparare le best practice delle politiche pubbliche pensionistiche di [&hellip;]","og_url":"https:\/\/super-news.info\/it\/pensionati-italia-sorpassata-dal-portogallo-per-qualita-della-vita\/","og_site_name":"Super News","article_published_time":"2019-09-19T10:05:05+00:00","article_modified_time":"2019-09-19T10:05:06+00:00","og_image":[{"width":450,"height":370,"url":"https:\/\/super-news.info\/it\/wp-content\/uploads\/sites\/9\/2019\/08\/In-buona-salute-e-autonomi-nella-gestione-finanziaria-lidentikit-degli.jpg","type":"image\/jpeg"}],"author":"super-news","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"super-news","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/super-news.info\/it\/pensionati-italia-sorpassata-dal-portogallo-per-qualita-della-vita\/#article","isPartOf":{"@id":"https:\/\/super-news.info\/it\/pensionati-italia-sorpassata-dal-portogallo-per-qualita-della-vita\/"},"author":{"name":"super-news","@id":"https:\/\/super-news.info\/it\/#\/schema\/person\/2d4068cb2f39cd10008c2fce578a7356"},"headline":"Pensionati: Italia sorpassata dal Portogallo per qualit\u00e0 della vita","datePublished":"2019-09-19T10:05:05+00:00","dateModified":"2019-09-19T10:05:06+00:00","mainEntityOfPage":{"@id":"https:\/\/super-news.info\/it\/pensionati-italia-sorpassata-dal-portogallo-per-qualita-della-vita\/"},"wordCount":710,"commentCount":0,"image":{"@id":"https:\/\/super-news.info\/it\/pensionati-italia-sorpassata-dal-portogallo-per-qualita-della-vita\/#primaryimage"},"thumbnailUrl":"https:\/\/super-news.info\/it\/wp-content\/uploads\/sites\/9\/2019\/08\/In-buona-salute-e-autonomi-nella-gestione-finanziaria-lidentikit-degli.jpg","articleSection":["NOTIZIE FINANZIARIE"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/super-news.info\/it\/pensionati-italia-sorpassata-dal-portogallo-per-qualita-della-vita\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/super-news.info\/it\/pensionati-italia-sorpassata-dal-portogallo-per-qualita-della-vita\/","url":"https:\/\/super-news.info\/it\/pensionati-italia-sorpassata-dal-portogallo-per-qualita-della-vita\/","name":"Pensionati: Italia sorpassata dal Portogallo per qualit\u00e0 della vita - Super News","isPartOf":{"@id":"https:\/\/super-news.info\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/super-news.info\/it\/pensionati-italia-sorpassata-dal-portogallo-per-qualita-della-vita\/#primaryimage"},"image":{"@id":"https:\/\/super-news.info\/it\/pensionati-italia-sorpassata-dal-portogallo-per-qualita-della-vita\/#primaryimage"},"thumbnailUrl":"https:\/\/super-news.info\/it\/wp-content\/uploads\/sites\/9\/2019\/08\/In-buona-salute-e-autonomi-nella-gestione-finanziaria-lidentikit-degli.jpg","datePublished":"2019-09-19T10:05:05+00:00","dateModified":"2019-09-19T10:05:06+00:00","author":{"@id":"https:\/\/super-news.info\/it\/#\/schema\/person\/2d4068cb2f39cd10008c2fce578a7356"},"breadcrumb":{"@id":"https:\/\/super-news.info\/it\/pensionati-italia-sorpassata-dal-portogallo-per-qualita-della-vita\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/super-news.info\/it\/pensionati-italia-sorpassata-dal-portogallo-per-qualita-della-vita\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/super-news.info\/it\/pensionati-italia-sorpassata-dal-portogallo-per-qualita-della-vita\/#primaryimage","url":"https:\/\/super-news.info\/it\/wp-content\/uploads\/sites\/9\/2019\/08\/In-buona-salute-e-autonomi-nella-gestione-finanziaria-lidentikit-degli.jpg","contentUrl":"https:\/\/super-news.info\/it\/wp-content\/uploads\/sites\/9\/2019\/08\/In-buona-salute-e-autonomi-nella-gestione-finanziaria-lidentikit-degli.jpg","width":450,"height":370,"caption":"test"},{"@type":"BreadcrumbList","@id":"https:\/\/super-news.info\/it\/pensionati-italia-sorpassata-dal-portogallo-per-qualita-della-vita\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/super-news.info\/it\/"},{"@type":"ListItem","position":2,"name":"Pensionati: Italia sorpassata dal Portogallo per qualit\u00e0 della vita"}]},{"@type":"WebSite","@id":"https:\/\/super-news.info\/it\/#website","url":"https:\/\/super-news.info\/it\/","name":"Super News","description":"Super News from Italy","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/super-news.info\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/super-news.info\/it\/#\/schema\/person\/2d4068cb2f39cd10008c2fce578a7356","name":"super-news","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g","caption":"super-news"},"url":"https:\/\/super-news.info\/it\/author\/pt\/"}]}},"_links":{"self":[{"href":"https:\/\/super-news.info\/it\/wp-json\/wp\/v2\/posts\/1169","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/super-news.info\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/super-news.info\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/super-news.info\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/super-news.info\/it\/wp-json\/wp\/v2\/comments?post=1169"}],"version-history":[{"count":1,"href":"https:\/\/super-news.info\/it\/wp-json\/wp\/v2\/posts\/1169\/revisions"}],"predecessor-version":[{"id":1170,"href":"https:\/\/super-news.info\/it\/wp-json\/wp\/v2\/posts\/1169\/revisions\/1170"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/super-news.info\/it\/wp-json\/wp\/v2\/media\/323"}],"wp:attachment":[{"href":"https:\/\/super-news.info\/it\/wp-json\/wp\/v2\/media?parent=1169"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/super-news.info\/it\/wp-json\/wp\/v2\/categories?post=1169"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/super-news.info\/it\/wp-json\/wp\/v2\/tags?post=1169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}