{"id":7679,"date":"2019-07-31T21:07:01","date_gmt":"2019-07-31T18:07:01","guid":{"rendered":"https:\/\/super-news.info\/es\/el-pib-modera-su-avance-trimestral-al-05-y-recorta-una-decima-su-tasa-anual-hasta-el-23\/"},"modified":"2019-07-31T21:07:02","modified_gmt":"2019-07-31T18:07:02","slug":"el-pib-modera-su-avance-trimestral-al-05-y-recorta-una-decima-su-tasa-anual-hasta-el-23","status":"publish","type":"post","link":"https:\/\/super-news.info\/es\/el-pib-modera-su-avance-trimestral-al-05-y-recorta-una-decima-su-tasa-anual-hasta-el-23\/","title":{"rendered":"El PIB modera su avance trimestral al 0,5% y recorta una d\u00e9cima su tasa anual hasta el 2,3%"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div><!-- inicio video embed --><\/p>\n<p>447702.1.500.286.20190731090037<\/p>\n<div id=\"VisiblePlayerPubliIncrustado\" class=\"VisiblePlayerPubliIncrustado_20190731090037 relativo\">\n<\/div>\n<p><!-- fin video embed --> <!-- fin multimedia --><\/p>\n<p>MADRID, 31 Jul. (EUROPA PRESS) &#8211;<\/p>\n<p itemprop=\"description\">La econom\u00eda espa\u00f1ola creci\u00f3 un 0,5% en el segundo trimestre de este a\u00f1o, dos d\u00e9cimas menos que en el primer trimestre, al tiempo que recort\u00f3 una d\u00e9cima su tasa interanual, hasta el 2,3%, seg\u00fan el avance trimestral de la Contabilidad Nacional publicado este mi\u00e9rcoles por el Instituto Nacional de Estad\u00edstica (INE).<\/p>\n<p>Con el repunte interanual del 2,3% registrado en el segundo trimestre del ejercicio, la econom\u00eda espa\u00f1ola acumula 22 trimestres consecutivos de tasas interanuales positivas, mientras que con el avance trimestral del 0,5% se acumulan 23 trimestres consecutivos de alzas.<\/p>\n<p><iframe id=\"ep-chart-e51e1ac1-0130-49e0-b820-c8f188a38d92\" src=\"https:\/\/www.epdata.es\/embed\/e51e1ac1-0130-49e0-b820-c8f188a38d92\/450\" style=\"width: 100%; min-height: 450px; overflow: hidden;\" frameborder=\"0\" scrolling=\"no\" height=\"450\"><\/iframe><\/p>\n<p>La ministra de Econom\u00eda y Empresa en funciones, Nadia Calvi\u00f1o, ya ha anunciado que el Gobierno revisar\u00e1 al alza la previsi\u00f3n de crecimiento del PIB para este a\u00f1o, situada actualmente en el 2,2%, en el pr\u00f3ximo cuadro macroecon\u00f3mico.<\/p>\n<p>Aunque no precis\u00f3 en cu\u00e1ntas d\u00e9cimas se elevar\u00e1 la estimaci\u00f3n, s\u00ed dijo que estar\u00e1 &#8220;en l\u00ednea&#8221; con las revisiones realizadas por otros organismos. La Comisi\u00f3n Europea ha revisado dos d\u00e9cimas al alza la estimaci\u00f3n de Espa\u00f1a para este a\u00f1o, hasta el 2,3%, mientras que el Banco de Espa\u00f1a la elev\u00f3 hace unas semanas hasta el 2,4%.<\/p>\n<p>Seg\u00fan los datos del INE, la contribuci\u00f3n de la demanda nacional al crecimiento interanual del PIB es de 1,6 puntos, seis d\u00e9cimas inferior a la del primer trimestre, mientras que la demanda externa present\u00f3 una aportaci\u00f3n de 0,7 puntos, cinco d\u00e9cimas superior a la del trimestre pasado.<\/p>\n<p><iframe id=\"ep-chart-c560967a-b1f7-40ef-b7b2-42f84a8f1088\" src=\"https:\/\/www.epdata.es\/embed\/c560967a-b1f7-40ef-b7b2-42f84a8f1088\/450\" style=\"width: 100%; min-height: 450px; overflow: hidden;\" frameborder=\"0\" scrolling=\"no\" height=\"450\"><\/iframe><\/p>\n<p>El gasto en consumo final se increment\u00f3 un 1,7% respecto al mismo trimestre de 2018, tasa una d\u00e9cima superior a la del primer trimestre.<\/p>\n<p>En concreto, el gasto en consumo final de los hogares experiment\u00f3 un crecimiento interanual del 1,7%, dos d\u00e9cimas m\u00e1s que en el trimestre pasado, mientras que el gasto en consumo final de las administraciones p\u00fablicas present\u00f3 una variaci\u00f3n interanual del 1,9%, una d\u00e9cima inferior a la del trimestre precedente.<\/p>\n<p>La formaci\u00f3n bruta de capital registr\u00f3 un crecimiento del 1,2%, inferior en 3,5 puntos al del trimestre anterior, al tiempo que la inversi\u00f3n en activos fijos materiales creci\u00f3 a una tasa interanual del 1,4%, lo que supone cuatro puntos menos que en el trimestre precedente.<\/p>\n<p>Por componentes, la inversi\u00f3n en viviendas y otros edificios y construcciones disminuy\u00f3 0,9 puntos, pasando del 4,3% al 3,4%, mientras que la inversi\u00f3n en maquinaria, bienes de equipo y sistemas de armamento baja 8,8 puntos al presentar una variaci\u00f3n del -1,5%, frente al 7,3% del trimestre anterior.<\/p>\n<p>Por otro lado, la inversi\u00f3n en productos de la propiedad intelectual experiment\u00f3 un crecimiento del 0,1%, con un incremento de una d\u00e9cima respecto al trimestre pasado.<\/p>\n<p>Asimismo, las exportaciones de bienes y servicios crecieron un 1,7% respecto al segundo trimestre de 2018, lo que supone 1,7 puntos m\u00e1s que en el trimestre anterior, impulsadas por un incremento en las tasas interanuales de las exportaciones de bienes (pasan del -2,1 al 1,6%), mientras que las exportaciones de servicios disminuyeron 2,7 puntos (del 4,8% al 2,1%).<\/p>\n<p>Dentro de \u00e9stas, el gasto de no residentes en el territorio econ\u00f3mico baja dos puntos (del 4,2% al 2,2%).<\/p>\n<p>Por su parte, las importaciones de bienes y servicios presentaron una variaci\u00f3n del -0,3% respecto al mismo trimestre del a\u00f1o anterior, dos d\u00e9cimas m\u00e1s que en el primer trimestre.<\/p>\n<p>Esta menor bajada, seg\u00fan el INE, es el resultado de una menor variaci\u00f3n interanual de las importaciones de servicios (pasa del 6,6% al 5,1%) y de las importaciones de bienes (del -2,1% al -1,5%).<\/p>\n<p>Asimismo, el gasto de residentes en el resto del mundo aceler\u00f3 nueve d\u00e9cimas su crecimiento interanual este trimestre, al pasar del 8,7% al 9,6%.<\/p>\n<p>El PIB a precios corrientes aument\u00f3 a una tasa interanual del 3,3%, crecimiento similar al registrado en el primer trimestre, al tiempo que el deflactor impl\u00edcito del PIB aument\u00f3 un 1% respecto al mismo trimestre de 2018, una d\u00e9cima m\u00e1s que en el trimestre pasado.<\/p>\n<p>INCREMENTO DE 459.000 EMPLEOS EN UN A\u00d1O.<\/p>\n<p>Por su parte, el empleo de la econom\u00eda, en t\u00e9rminos de puestos de trabajo equivalentes a tiempo completo, registr\u00f3 una variaci\u00f3n intertrimestral del 0,4%, tres d\u00e9cimas inferior a la registrada en el primer trimestre.<\/p>\n<p>En t\u00e9rminos interanuales, el empleo aument\u00f3 a un ritmo del 2,5%, tasa tres d\u00e9cimas inferior a la del primer trimestre, lo que supone un incremento de 459.000 puestos de trabajo equivalentes a tiempo completo en un a\u00f1o.<\/p>\n<p>Seg\u00fan el INE, la variaci\u00f3n interanual del coste laboral unitario se situ\u00f3 en el segundo trimestre en el 2,1%.<\/p>\n<p>Asimismo, la remuneraci\u00f3n de los asalariados present\u00f3 un crecimiento interanual del 4,8% en el segundo trimestre, dos d\u00e9cimas inferior al del trimestre anterior.<\/p>\n<p>Estad\u00edstica atribuye este resultado al aumento del 2,9% del n\u00famero de asalariados, cuatro d\u00e9cimas inferior al del trimestre precedente, combinado con una remuneraci\u00f3n media por asalariado que se incrementa un 1,8%, frente al 1,6% del primer trimestre.<\/p>\n<p>Por su parte, el excedente de explotaci\u00f3n bruto\/renta mixta bruta generado en la econom\u00eda creci\u00f3 un 1,5% en tasa interanual, siete d\u00e9cimas m\u00e1s que en el primer trimestre.<\/p>\n<p>Finalmente, la cuant\u00eda devengada en impuestos sobre la producci\u00f3n y las importaciones netos de subvenciones registr\u00f3 un crecimiento del 4,4%, frente al 5,9% del trimestre anterior.<\/p>\n<p>Los datos publicados por Estad\u00edstica son a\u00fan provisionales y se conocer\u00e1n a nivel desagregado el pr\u00f3ximo 30 de septiembre.<\/p>\n<\/div>\n<p>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.europapress.es\/economia\/macroeconomia-00338\/noticia-pib-modera-avance-trimestral-05-recorta-decima-tasa-anual-23-20190731090037.html\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] 447702.1.500.286.20190731090037 MADRID, 31 Jul. (EUROPA PRESS) &#8211; La econom\u00eda espa\u00f1ola creci\u00f3 un 0,5% en el segundo trimestre de este a\u00f1o, dos d\u00e9cimas menos que en el primer trimestre, al tiempo que recort\u00f3 una d\u00e9cima su tasa interanual, hasta el 2,3%, seg\u00fan el avance trimestral de la Contabilidad Nacional publicado este mi\u00e9rcoles por el Instituto [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":7680,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-7679","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-financieras"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El PIB modera su avance trimestral al 0,5% y recorta una d\u00e9cima su tasa anual hasta el 2,3% - Super News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/super-news.info\/es\/el-pib-modera-su-avance-trimestral-al-05-y-recorta-una-decima-su-tasa-anual-hasta-el-23\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El PIB modera su avance trimestral al 0,5% y recorta una d\u00e9cima su tasa anual hasta el 2,3% - Super News\" \/>\n<meta property=\"og:description\" content=\"[ad_1] 447702.1.500.286.20190731090037 MADRID, 31 Jul. (EUROPA PRESS) &#8211; La econom\u00eda espa\u00f1ola creci\u00f3 un 0,5% en el segundo trimestre de este a\u00f1o, dos d\u00e9cimas menos que en el primer trimestre, al tiempo que recort\u00f3 una d\u00e9cima su tasa interanual, hasta el 2,3%, seg\u00fan el avance trimestral de la Contabilidad Nacional publicado este mi\u00e9rcoles por el Instituto [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/super-news.info\/es\/el-pib-modera-su-avance-trimestral-al-05-y-recorta-una-decima-su-tasa-anual-hasta-el-23\/\" \/>\n<meta property=\"og:site_name\" content=\"Super News\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-31T18:07:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-07-31T18:07:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/super-news.info\/es\/wp-content\/uploads\/sites\/4\/2019\/07\/El-PIB-modera-su-avance-trimestral-al-05-y-recorta.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"281\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"super-news\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"super-news\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/el-pib-modera-su-avance-trimestral-al-05-y-recorta-una-decima-su-tasa-anual-hasta-el-23\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/el-pib-modera-su-avance-trimestral-al-05-y-recorta-una-decima-su-tasa-anual-hasta-el-23\\\/\"},\"author\":{\"name\":\"super-news\",\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/#\\\/schema\\\/person\\\/2d4068cb2f39cd10008c2fce578a7356\"},\"headline\":\"El PIB modera su avance trimestral al 0,5% y recorta una d\u00e9cima su tasa anual hasta el 2,3%\",\"datePublished\":\"2019-07-31T18:07:01+00:00\",\"dateModified\":\"2019-07-31T18:07:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/el-pib-modera-su-avance-trimestral-al-05-y-recorta-una-decima-su-tasa-anual-hasta-el-23\\\/\"},\"wordCount\":917,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/el-pib-modera-su-avance-trimestral-al-05-y-recorta-una-decima-su-tasa-anual-hasta-el-23\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/super-news.info\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2019\\\/07\\\/El-PIB-modera-su-avance-trimestral-al-05-y-recorta.jpg\",\"articleSection\":[\"NOTICIAS FINANCIERAS\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/super-news.info\\\/es\\\/el-pib-modera-su-avance-trimestral-al-05-y-recorta-una-decima-su-tasa-anual-hasta-el-23\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/el-pib-modera-su-avance-trimestral-al-05-y-recorta-una-decima-su-tasa-anual-hasta-el-23\\\/\",\"url\":\"https:\\\/\\\/super-news.info\\\/es\\\/el-pib-modera-su-avance-trimestral-al-05-y-recorta-una-decima-su-tasa-anual-hasta-el-23\\\/\",\"name\":\"El PIB modera su avance trimestral al 0,5% y recorta una d\u00e9cima su tasa anual hasta el 2,3% - Super News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/el-pib-modera-su-avance-trimestral-al-05-y-recorta-una-decima-su-tasa-anual-hasta-el-23\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/el-pib-modera-su-avance-trimestral-al-05-y-recorta-una-decima-su-tasa-anual-hasta-el-23\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/super-news.info\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2019\\\/07\\\/El-PIB-modera-su-avance-trimestral-al-05-y-recorta.jpg\",\"datePublished\":\"2019-07-31T18:07:01+00:00\",\"dateModified\":\"2019-07-31T18:07:02+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/#\\\/schema\\\/person\\\/2d4068cb2f39cd10008c2fce578a7356\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/el-pib-modera-su-avance-trimestral-al-05-y-recorta-una-decima-su-tasa-anual-hasta-el-23\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/super-news.info\\\/es\\\/el-pib-modera-su-avance-trimestral-al-05-y-recorta-una-decima-su-tasa-anual-hasta-el-23\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/el-pib-modera-su-avance-trimestral-al-05-y-recorta-una-decima-su-tasa-anual-hasta-el-23\\\/#primaryimage\",\"url\":\"https:\\\/\\\/super-news.info\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2019\\\/07\\\/El-PIB-modera-su-avance-trimestral-al-05-y-recorta.jpg\",\"contentUrl\":\"https:\\\/\\\/super-news.info\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2019\\\/07\\\/El-PIB-modera-su-avance-trimestral-al-05-y-recorta.jpg\",\"width\":500,\"height\":281,\"caption\":\"V\u00eddeo de la noticia\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/el-pib-modera-su-avance-trimestral-al-05-y-recorta-una-decima-su-tasa-anual-hasta-el-23\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430\",\"item\":\"https:\\\/\\\/super-news.info\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El PIB modera su avance trimestral al 0,5% y recorta una d\u00e9cima su tasa anual hasta el 2,3%\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/super-news.info\\\/es\\\/\",\"name\":\"Super News\",\"description\":\"Super News Espa\u00f1a\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/super-news.info\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/#\\\/schema\\\/person\\\/2d4068cb2f39cd10008c2fce578a7356\",\"name\":\"super-news\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g\",\"caption\":\"super-news\"},\"url\":\"https:\\\/\\\/super-news.info\\\/es\\\/author\\\/pt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El PIB modera su avance trimestral al 0,5% y recorta una d\u00e9cima su tasa anual hasta el 2,3% - Super News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/super-news.info\/es\/el-pib-modera-su-avance-trimestral-al-05-y-recorta-una-decima-su-tasa-anual-hasta-el-23\/","og_locale":"en_US","og_type":"article","og_title":"El PIB modera su avance trimestral al 0,5% y recorta una d\u00e9cima su tasa anual hasta el 2,3% - Super News","og_description":"[ad_1] 447702.1.500.286.20190731090037 MADRID, 31 Jul. (EUROPA PRESS) &#8211; La econom\u00eda espa\u00f1ola creci\u00f3 un 0,5% en el segundo trimestre de este a\u00f1o, dos d\u00e9cimas menos que en el primer trimestre, al tiempo que recort\u00f3 una d\u00e9cima su tasa interanual, hasta el 2,3%, seg\u00fan el avance trimestral de la Contabilidad Nacional publicado este mi\u00e9rcoles por el Instituto [&hellip;]","og_url":"https:\/\/super-news.info\/es\/el-pib-modera-su-avance-trimestral-al-05-y-recorta-una-decima-su-tasa-anual-hasta-el-23\/","og_site_name":"Super News","article_published_time":"2019-07-31T18:07:01+00:00","article_modified_time":"2019-07-31T18:07:02+00:00","og_image":[{"width":500,"height":281,"url":"https:\/\/super-news.info\/es\/wp-content\/uploads\/sites\/4\/2019\/07\/El-PIB-modera-su-avance-trimestral-al-05-y-recorta.jpg","type":"image\/jpeg"}],"author":"super-news","twitter_card":"summary_large_image","twitter_misc":{"Written by":"super-news","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/super-news.info\/es\/el-pib-modera-su-avance-trimestral-al-05-y-recorta-una-decima-su-tasa-anual-hasta-el-23\/#article","isPartOf":{"@id":"https:\/\/super-news.info\/es\/el-pib-modera-su-avance-trimestral-al-05-y-recorta-una-decima-su-tasa-anual-hasta-el-23\/"},"author":{"name":"super-news","@id":"https:\/\/super-news.info\/es\/#\/schema\/person\/2d4068cb2f39cd10008c2fce578a7356"},"headline":"El PIB modera su avance trimestral al 0,5% y recorta una d\u00e9cima su tasa anual hasta el 2,3%","datePublished":"2019-07-31T18:07:01+00:00","dateModified":"2019-07-31T18:07:02+00:00","mainEntityOfPage":{"@id":"https:\/\/super-news.info\/es\/el-pib-modera-su-avance-trimestral-al-05-y-recorta-una-decima-su-tasa-anual-hasta-el-23\/"},"wordCount":917,"commentCount":0,"image":{"@id":"https:\/\/super-news.info\/es\/el-pib-modera-su-avance-trimestral-al-05-y-recorta-una-decima-su-tasa-anual-hasta-el-23\/#primaryimage"},"thumbnailUrl":"https:\/\/super-news.info\/es\/wp-content\/uploads\/sites\/4\/2019\/07\/El-PIB-modera-su-avance-trimestral-al-05-y-recorta.jpg","articleSection":["NOTICIAS FINANCIERAS"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/super-news.info\/es\/el-pib-modera-su-avance-trimestral-al-05-y-recorta-una-decima-su-tasa-anual-hasta-el-23\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/super-news.info\/es\/el-pib-modera-su-avance-trimestral-al-05-y-recorta-una-decima-su-tasa-anual-hasta-el-23\/","url":"https:\/\/super-news.info\/es\/el-pib-modera-su-avance-trimestral-al-05-y-recorta-una-decima-su-tasa-anual-hasta-el-23\/","name":"El PIB modera su avance trimestral al 0,5% y recorta una d\u00e9cima su tasa anual hasta el 2,3% - Super News","isPartOf":{"@id":"https:\/\/super-news.info\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/super-news.info\/es\/el-pib-modera-su-avance-trimestral-al-05-y-recorta-una-decima-su-tasa-anual-hasta-el-23\/#primaryimage"},"image":{"@id":"https:\/\/super-news.info\/es\/el-pib-modera-su-avance-trimestral-al-05-y-recorta-una-decima-su-tasa-anual-hasta-el-23\/#primaryimage"},"thumbnailUrl":"https:\/\/super-news.info\/es\/wp-content\/uploads\/sites\/4\/2019\/07\/El-PIB-modera-su-avance-trimestral-al-05-y-recorta.jpg","datePublished":"2019-07-31T18:07:01+00:00","dateModified":"2019-07-31T18:07:02+00:00","author":{"@id":"https:\/\/super-news.info\/es\/#\/schema\/person\/2d4068cb2f39cd10008c2fce578a7356"},"breadcrumb":{"@id":"https:\/\/super-news.info\/es\/el-pib-modera-su-avance-trimestral-al-05-y-recorta-una-decima-su-tasa-anual-hasta-el-23\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/super-news.info\/es\/el-pib-modera-su-avance-trimestral-al-05-y-recorta-una-decima-su-tasa-anual-hasta-el-23\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/super-news.info\/es\/el-pib-modera-su-avance-trimestral-al-05-y-recorta-una-decima-su-tasa-anual-hasta-el-23\/#primaryimage","url":"https:\/\/super-news.info\/es\/wp-content\/uploads\/sites\/4\/2019\/07\/El-PIB-modera-su-avance-trimestral-al-05-y-recorta.jpg","contentUrl":"https:\/\/super-news.info\/es\/wp-content\/uploads\/sites\/4\/2019\/07\/El-PIB-modera-su-avance-trimestral-al-05-y-recorta.jpg","width":500,"height":281,"caption":"V\u00eddeo de la noticia"},{"@type":"BreadcrumbList","@id":"https:\/\/super-news.info\/es\/el-pib-modera-su-avance-trimestral-al-05-y-recorta-una-decima-su-tasa-anual-hasta-el-23\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430","item":"https:\/\/super-news.info\/es\/"},{"@type":"ListItem","position":2,"name":"El PIB modera su avance trimestral al 0,5% y recorta una d\u00e9cima su tasa anual hasta el 2,3%"}]},{"@type":"WebSite","@id":"https:\/\/super-news.info\/es\/#website","url":"https:\/\/super-news.info\/es\/","name":"Super News","description":"Super News Espa\u00f1a","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/super-news.info\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/super-news.info\/es\/#\/schema\/person\/2d4068cb2f39cd10008c2fce578a7356","name":"super-news","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g","caption":"super-news"},"url":"https:\/\/super-news.info\/es\/author\/pt\/"}]}},"_links":{"self":[{"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/posts\/7679","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/comments?post=7679"}],"version-history":[{"count":1,"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/posts\/7679\/revisions"}],"predecessor-version":[{"id":7681,"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/posts\/7679\/revisions\/7681"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/media\/7680"}],"wp:attachment":[{"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/media?parent=7679"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/categories?post=7679"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/tags?post=7679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}