{"id":4118,"date":"2019-06-17T12:01:42","date_gmt":"2019-06-17T09:01:42","guid":{"rendered":"https:\/\/super-news.info\/es\/espana-no-debe-tener-miedo-a-su-deuda-segun-candriam\/"},"modified":"2019-06-17T12:01:43","modified_gmt":"2019-06-17T09:01:43","slug":"espana-no-debe-tener-miedo-a-su-deuda-segun-candriam","status":"publish","type":"post","link":"https:\/\/super-news.info\/es\/espana-no-debe-tener-miedo-a-su-deuda-segun-candriam\/","title":{"rendered":"Espa\u00f1a &#8220;no debe tener miedo a su deuda&#8221;, seg\u00fan Candriam"},"content":{"rendered":"<p> [ad_1]<\/p>\n<div id=\"CuerpoNoticiav2\" itemprop=\"articleBody\">\n<!--inicio FechaNoticia--><\/p>\n<div class=\"FechaPublicacionNoticia\">Publicado 17\/06\/2019 10:24:12<abbr title=\"Central European Time\">CET<\/abbr><\/div>\n<p><!--fin FechaNoticia--><\/p>\n<h3 class=\"subsubhead\">La gestora destaca la &#8220;resiliencia&#8221; de la econom\u00eda espa\u00f1ola<\/h3>\n<p>   MADRID, 17 Jun. (EUROPA PRESS) &#8211; <\/p>\n<p itemprop=\"description\">   El alto endeudamiento de la econom\u00eda espa\u00f1ola &#8220;no debe ser un problema&#8221; en un contexto de bajos tipos de inter\u00e9s y ofertas de financiaci\u00f3n del mercado a un pa\u00eds que consideran &#8220;buen pagador&#8221;, por lo que &#8220;no hay que temer una crisis de cr\u00e9dito&#8221;, ha asegurado el economista jefe de Candriam, Anton Brender.<\/p>\n<p>   &#8220;Espa\u00f1a no debe que tener miedo a su deuda&#8221;, ha afirmado Brender en declaraciones a Europa Press, tras la presentaci\u00f3n semestral de los perspectivas econ\u00f3micas de la gestora, celebrada el pasado viernes en Madrid.<\/p>\n<p>    A pesar de que la deuda p\u00fablica espa\u00f1ola ha superado los 1,2 billones de euros por primera vez, un nuevo r\u00e9cord marcado en el primer trimestre del a\u00f1o, seg\u00fan el \u00faltimo dato publicado por el Banco de Espa\u00f1a, el economista jefe de Candriam ha apostado por &#8220;derribar el antiguo paradigma que limita el endeudamiento, si se trata de invertir en el futuro&#8221; ante el nuevo contexto.<\/p>\n<p>   El contexto pasa por una reducci\u00f3n de la deuda p\u00fablica espa\u00f1ola a menos de la mitad del coste de financiaci\u00f3n a diez a\u00f1os en apenas mes y medio. En concreto, el pasado viernes la rentabilidad del bono a diez a\u00f1os bajaba por primera vez en toda la serie de la barrera del 0,5% con una dr\u00e1stica mejora respecto al 1,4% con el que inici\u00f3 2019.<\/p>\n<p>   En este sentido, la responsable de investigaci\u00f3n econ\u00f3mica de la firma, Florence Pisani, ha coincidido en la &#8220;oportunidad&#8221; que supone esta financiaci\u00f3n f\u00e1cil para apostar por pol\u00edticas p\u00fablicas que refuercen la educaci\u00f3n, la investigaci\u00f3n y el desarrollo tecnol\u00f3gico.<\/p>\n<p>   &#8220;En el contexto actual, reducir a\u00fan m\u00e1s las inversiones p\u00fablicas responde a una pol\u00edtica cortoplacista&#8221; ha subrayado Pisani. Sin embargo, ha reconocido que no es positivo endeudarse para pagar pensiones o desempleo, en tanto que &#8220;no contribuye al futuro&#8221;.<\/p>\n<p>   Para Brender, la creaci\u00f3n de empleo, el incremento continuado de la productividad y el crecimiento en el ritmo de las exportaciones son algunos factores que demuestran el buen desempe\u00f1o de la econom\u00eda espa\u00f1ola, &#8220;m\u00e1s s\u00f3lida de lo que muchos esperaban&#8221;, tras la \u00faltima crisis econ\u00f3mica.<\/p>\n<p>   En esta l\u00ednea, Pisani ha recalcado en la &#8220;potencia exportadora&#8221; de Espa\u00f1a, solo por detr\u00e1s de Alemania en la zona euro, y ha subrayado la menor exposici\u00f3n al sector automovil\u00edstico, que se est\u00e1 viendo afectado por los aranceles estadounidenses.<\/p>\n<h2 class=\"ladillo\">ESPA\u00d1A TAMBI\u00c9N SUFRIR\u00c1 SI HAY RECESI\u00d3N EUROPEA<\/h2>\n<p>   No obstante, la economista de Candriam ha reconocido que en el &#8220;posible escenario&#8221; de una pr\u00f3xima recesi\u00f3n en Europa, Espa\u00f1a tambi\u00e9n se ver\u00e1 afectada, si bien, sufrir\u00e1 menos que otras econom\u00edas como Italia.<\/p>\n<p>   &#8220;Espa\u00f1a y Portugal son dos pa\u00edses que han demostrado que pueden aplicar pol\u00edticas fiscales agresivas e incrementar sus exportaciones&#8221;, ha explicado Pisani. Asimismo, la pol\u00edtica fiscal ha ayudado al crecimiento econ\u00f3mico en Espa\u00f1a, Francia, Alemania e Italia, ha a\u00f1adido.<\/p>\n<p>    No obstante, &#8220;la zona euro sigue siendo vulnerable y la diferencia en el nivel de ingresos entre los distintos pa\u00edses es cada vez mayor&#8221;, ha destacado la economista.<\/p>\n<p>   &#8220;En Francia e Italia, la erosi\u00f3n de los empleos &#8216;intermedios&#8217; explica, en parte, las tensiones sociales y nutre el populismo&#8221;, ha advertido Pisani, que no considera que la aparici\u00f3n de Podemos o Vox sea un problema muy preocupante en Espa\u00f1a, ya que se est\u00e1n creando empleos &#8216;intermedios&#8217;.<\/p>\n<\/div>\n<p>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.europapress.es\/economia\/finanzas-00340\/noticia-espana-no-debe-tener-miedo-deuda-candriam-20190617102412.html\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Publicado 17\/06\/2019 10:24:12CET La gestora destaca la &#8220;resiliencia&#8221; de la econom\u00eda espa\u00f1ola MADRID, 17 Jun. (EUROPA PRESS) &#8211; El alto endeudamiento de la econom\u00eda espa\u00f1ola &#8220;no debe ser un problema&#8221; en un contexto de bajos tipos de inter\u00e9s y ofertas de financiaci\u00f3n del mercado a un pa\u00eds que consideran &#8220;buen pagador&#8221;, por lo que [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":4119,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4118","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-financieras"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Espa\u00f1a &quot;no debe tener miedo a su deuda&quot;, seg\u00fan Candriam - Super News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/super-news.info\/es\/espana-no-debe-tener-miedo-a-su-deuda-segun-candriam\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Espa\u00f1a &quot;no debe tener miedo a su deuda&quot;, seg\u00fan Candriam - Super News\" \/>\n<meta property=\"og:description\" content=\"[ad_1] Publicado 17\/06\/2019 10:24:12CET La gestora destaca la &#8220;resiliencia&#8221; de la econom\u00eda espa\u00f1ola MADRID, 17 Jun. (EUROPA PRESS) &#8211; El alto endeudamiento de la econom\u00eda espa\u00f1ola &#8220;no debe ser un problema&#8221; en un contexto de bajos tipos de inter\u00e9s y ofertas de financiaci\u00f3n del mercado a un pa\u00eds que consideran &#8220;buen pagador&#8221;, por lo que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/super-news.info\/es\/espana-no-debe-tener-miedo-a-su-deuda-segun-candriam\/\" \/>\n<meta property=\"og:site_name\" content=\"Super News\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-17T09:01:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-06-17T09:01:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/super-news.info\/es\/wp-content\/uploads\/sites\/4\/2019\/06\/Espa\u00f1a-no-debe-tener-miedo-a-su-deuda-seg\u00fan-Candriam.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"120\" \/>\n\t<meta property=\"og:image:height\" content=\"90\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"super-news\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"super-news\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/espana-no-debe-tener-miedo-a-su-deuda-segun-candriam\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/espana-no-debe-tener-miedo-a-su-deuda-segun-candriam\\\/\"},\"author\":{\"name\":\"super-news\",\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/#\\\/schema\\\/person\\\/2d4068cb2f39cd10008c2fce578a7356\"},\"headline\":\"Espa\u00f1a &#8220;no debe tener miedo a su deuda&#8221;, seg\u00fan Candriam\",\"datePublished\":\"2019-06-17T09:01:42+00:00\",\"dateModified\":\"2019-06-17T09:01:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/espana-no-debe-tener-miedo-a-su-deuda-segun-candriam\\\/\"},\"wordCount\":630,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/espana-no-debe-tener-miedo-a-su-deuda-segun-candriam\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/super-news.info\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2019\\\/06\\\/Espa\u00f1a-no-debe-tener-miedo-a-su-deuda-seg\u00fan-Candriam.jpg\",\"articleSection\":[\"NOTICIAS FINANCIERAS\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/super-news.info\\\/es\\\/espana-no-debe-tener-miedo-a-su-deuda-segun-candriam\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/espana-no-debe-tener-miedo-a-su-deuda-segun-candriam\\\/\",\"url\":\"https:\\\/\\\/super-news.info\\\/es\\\/espana-no-debe-tener-miedo-a-su-deuda-segun-candriam\\\/\",\"name\":\"Espa\u00f1a \\\"no debe tener miedo a su deuda\\\", seg\u00fan Candriam - Super News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/espana-no-debe-tener-miedo-a-su-deuda-segun-candriam\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/espana-no-debe-tener-miedo-a-su-deuda-segun-candriam\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/super-news.info\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2019\\\/06\\\/Espa\u00f1a-no-debe-tener-miedo-a-su-deuda-seg\u00fan-Candriam.jpg\",\"datePublished\":\"2019-06-17T09:01:42+00:00\",\"dateModified\":\"2019-06-17T09:01:43+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/#\\\/schema\\\/person\\\/2d4068cb2f39cd10008c2fce578a7356\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/espana-no-debe-tener-miedo-a-su-deuda-segun-candriam\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/super-news.info\\\/es\\\/espana-no-debe-tener-miedo-a-su-deuda-segun-candriam\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/espana-no-debe-tener-miedo-a-su-deuda-segun-candriam\\\/#primaryimage\",\"url\":\"https:\\\/\\\/super-news.info\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2019\\\/06\\\/Espa\u00f1a-no-debe-tener-miedo-a-su-deuda-seg\u00fan-Candriam.jpg\",\"contentUrl\":\"https:\\\/\\\/super-news.info\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2019\\\/06\\\/Espa\u00f1a-no-debe-tener-miedo-a-su-deuda-seg\u00fan-Candriam.jpg\",\"width\":120,\"height\":90,\"caption\":\"Espa\u00f1a \\\"no debe tener miedo a su deuda\\\", seg\u00fan Candriam\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/espana-no-debe-tener-miedo-a-su-deuda-segun-candriam\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430\",\"item\":\"https:\\\/\\\/super-news.info\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Espa\u00f1a &#8220;no debe tener miedo a su deuda&#8221;, seg\u00fan Candriam\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/super-news.info\\\/es\\\/\",\"name\":\"Super News\",\"description\":\"Super News Espa\u00f1a\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/super-news.info\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/#\\\/schema\\\/person\\\/2d4068cb2f39cd10008c2fce578a7356\",\"name\":\"super-news\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g\",\"caption\":\"super-news\"},\"url\":\"https:\\\/\\\/super-news.info\\\/es\\\/author\\\/pt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Espa\u00f1a \"no debe tener miedo a su deuda\", seg\u00fan Candriam - Super News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/super-news.info\/es\/espana-no-debe-tener-miedo-a-su-deuda-segun-candriam\/","og_locale":"en_US","og_type":"article","og_title":"Espa\u00f1a \"no debe tener miedo a su deuda\", seg\u00fan Candriam - Super News","og_description":"[ad_1] Publicado 17\/06\/2019 10:24:12CET La gestora destaca la &#8220;resiliencia&#8221; de la econom\u00eda espa\u00f1ola MADRID, 17 Jun. (EUROPA PRESS) &#8211; El alto endeudamiento de la econom\u00eda espa\u00f1ola &#8220;no debe ser un problema&#8221; en un contexto de bajos tipos de inter\u00e9s y ofertas de financiaci\u00f3n del mercado a un pa\u00eds que consideran &#8220;buen pagador&#8221;, por lo que [&hellip;]","og_url":"https:\/\/super-news.info\/es\/espana-no-debe-tener-miedo-a-su-deuda-segun-candriam\/","og_site_name":"Super News","article_published_time":"2019-06-17T09:01:42+00:00","article_modified_time":"2019-06-17T09:01:43+00:00","og_image":[{"width":120,"height":90,"url":"https:\/\/super-news.info\/es\/wp-content\/uploads\/sites\/4\/2019\/06\/Espa\u00f1a-no-debe-tener-miedo-a-su-deuda-seg\u00fan-Candriam.jpg","type":"image\/jpeg"}],"author":"super-news","twitter_card":"summary_large_image","twitter_misc":{"Written by":"super-news","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/super-news.info\/es\/espana-no-debe-tener-miedo-a-su-deuda-segun-candriam\/#article","isPartOf":{"@id":"https:\/\/super-news.info\/es\/espana-no-debe-tener-miedo-a-su-deuda-segun-candriam\/"},"author":{"name":"super-news","@id":"https:\/\/super-news.info\/es\/#\/schema\/person\/2d4068cb2f39cd10008c2fce578a7356"},"headline":"Espa\u00f1a &#8220;no debe tener miedo a su deuda&#8221;, seg\u00fan Candriam","datePublished":"2019-06-17T09:01:42+00:00","dateModified":"2019-06-17T09:01:43+00:00","mainEntityOfPage":{"@id":"https:\/\/super-news.info\/es\/espana-no-debe-tener-miedo-a-su-deuda-segun-candriam\/"},"wordCount":630,"commentCount":0,"image":{"@id":"https:\/\/super-news.info\/es\/espana-no-debe-tener-miedo-a-su-deuda-segun-candriam\/#primaryimage"},"thumbnailUrl":"https:\/\/super-news.info\/es\/wp-content\/uploads\/sites\/4\/2019\/06\/Espa\u00f1a-no-debe-tener-miedo-a-su-deuda-seg\u00fan-Candriam.jpg","articleSection":["NOTICIAS FINANCIERAS"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/super-news.info\/es\/espana-no-debe-tener-miedo-a-su-deuda-segun-candriam\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/super-news.info\/es\/espana-no-debe-tener-miedo-a-su-deuda-segun-candriam\/","url":"https:\/\/super-news.info\/es\/espana-no-debe-tener-miedo-a-su-deuda-segun-candriam\/","name":"Espa\u00f1a \"no debe tener miedo a su deuda\", seg\u00fan Candriam - Super News","isPartOf":{"@id":"https:\/\/super-news.info\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/super-news.info\/es\/espana-no-debe-tener-miedo-a-su-deuda-segun-candriam\/#primaryimage"},"image":{"@id":"https:\/\/super-news.info\/es\/espana-no-debe-tener-miedo-a-su-deuda-segun-candriam\/#primaryimage"},"thumbnailUrl":"https:\/\/super-news.info\/es\/wp-content\/uploads\/sites\/4\/2019\/06\/Espa\u00f1a-no-debe-tener-miedo-a-su-deuda-seg\u00fan-Candriam.jpg","datePublished":"2019-06-17T09:01:42+00:00","dateModified":"2019-06-17T09:01:43+00:00","author":{"@id":"https:\/\/super-news.info\/es\/#\/schema\/person\/2d4068cb2f39cd10008c2fce578a7356"},"breadcrumb":{"@id":"https:\/\/super-news.info\/es\/espana-no-debe-tener-miedo-a-su-deuda-segun-candriam\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/super-news.info\/es\/espana-no-debe-tener-miedo-a-su-deuda-segun-candriam\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/super-news.info\/es\/espana-no-debe-tener-miedo-a-su-deuda-segun-candriam\/#primaryimage","url":"https:\/\/super-news.info\/es\/wp-content\/uploads\/sites\/4\/2019\/06\/Espa\u00f1a-no-debe-tener-miedo-a-su-deuda-seg\u00fan-Candriam.jpg","contentUrl":"https:\/\/super-news.info\/es\/wp-content\/uploads\/sites\/4\/2019\/06\/Espa\u00f1a-no-debe-tener-miedo-a-su-deuda-seg\u00fan-Candriam.jpg","width":120,"height":90,"caption":"Espa\u00f1a \"no debe tener miedo a su deuda\", seg\u00fan Candriam"},{"@type":"BreadcrumbList","@id":"https:\/\/super-news.info\/es\/espana-no-debe-tener-miedo-a-su-deuda-segun-candriam\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430","item":"https:\/\/super-news.info\/es\/"},{"@type":"ListItem","position":2,"name":"Espa\u00f1a &#8220;no debe tener miedo a su deuda&#8221;, seg\u00fan Candriam"}]},{"@type":"WebSite","@id":"https:\/\/super-news.info\/es\/#website","url":"https:\/\/super-news.info\/es\/","name":"Super News","description":"Super News Espa\u00f1a","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/super-news.info\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/super-news.info\/es\/#\/schema\/person\/2d4068cb2f39cd10008c2fce578a7356","name":"super-news","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g","caption":"super-news"},"url":"https:\/\/super-news.info\/es\/author\/pt\/"}]}},"_links":{"self":[{"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/posts\/4118","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/comments?post=4118"}],"version-history":[{"count":1,"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/posts\/4118\/revisions"}],"predecessor-version":[{"id":4120,"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/posts\/4118\/revisions\/4120"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/media\/4119"}],"wp:attachment":[{"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/media?parent=4118"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/categories?post=4118"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/tags?post=4118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}