{"id":15955,"date":"2021-09-05T01:46:51","date_gmt":"2021-09-04T22:46:51","guid":{"rendered":"https:\/\/super-news.info\/es\/las-visualizaciones-de-video-en-pinterest-aumentan-mas-del-240\/"},"modified":"2021-09-05T01:47:17","modified_gmt":"2021-09-04T22:47:17","slug":"las-visualizaciones-de-video-en-pinterest-aumentan-mas-del-240","status":"publish","type":"post","link":"https:\/\/super-news.info\/es\/las-visualizaciones-de-video-en-pinterest-aumentan-mas-del-240\/","title":{"rendered":"Las visualizaciones de v\u00eddeo en Pinterest aumentan m\u00e1s del 240%"},"content":{"rendered":"<p>El 82% de los usuarios recurre a Pinterest para decidir por qu\u00e9 producto decantarse en el \u00e1mbito de la alimentaci\u00f3n y la bebida.<br \/>\nFrente a la aparici\u00f3n de nuevas plataformas sociales, Pinterest contin\u00faa manteni\u00e9ndose en el mercado pese al paso de los a\u00f1os. TikTok o Twitch acaparan las conversaciones, pero lo cierto es que la mencionada red constituye una mina de oro para todo tipo de marcas, tambi\u00e9n las de alimentaci\u00f3n y bebida.<br \/>\nDe hecho, m\u00e1s de 70 millones de usuarios activos interact\u00faan cada mes con el contenido de esta clase de firmas. Pinterest es muy \u00fatil para alcanzar a la Generaci\u00f3n Z y a los millennials y proporcionarles ideas para sus dietas. Es m\u00e1s, el 82% de los usuarios recurre a ella para decidir por qu\u00e9 producto decantarse en el \u00e1mbito de la alimentaci\u00f3n y la bebida. Por otro lado, un 93% lo utiliza para descubrir productos durante el recorrido de compra.<br \/>\nEn 2020, las visualizaciones de v\u00eddeos en Pinterest se triplicaron con respecto al a\u00f1o anterior. Para ser m\u00e1s espec\u00edficos, la cantidad de visualizaciones ha aumentado m\u00e1s del 240% si lo comparamos con 2019. Los v\u00eddeos de la plataforma tienen el doble de oportunidades de ser vistos en comparaci\u00f3n con los de otras.<br \/>\nEl caso de \u00e9xito de Heineken en su primera campa\u00f1a en Pinterest en Espa\u00f1a<br \/>\nQuiz\u00e1s son todos estos motivos los que llevaron a Heineken a poner en marcha su primera campa\u00f1a de reconocimiento de la marca en Pinterest para Ladr\u00f3n de Manzanas en Espa\u00f1a. El objetivo era el de interactuar con los consumidores que buscaban formas de divertirse y celebrar el inicio del verano.<br \/>\nDurante las cuatro semanas que dur\u00f3, sus anuncios de v\u00eddeo generaron m\u00e1s de 10 millones de impresiones y casi 6 millones de visualizaciones, con 2,5 de ellas completas. Adem\u00e1s, Heineken aument\u00f3 el reconocimiento de sus pines en m\u00e1s de 7,8 puntos de media y m\u00e1s de 15,4 puntos en la franja de 35 a 49 a\u00f1os, seg\u00fan datos extra\u00eddos por el estudio de Brand Lift de Pinterest.<br \/>\nLa acci\u00f3n consigui\u00f3 un alcance de visualizaciones del 98%, lo cual demuestra la eficacia con la que las marcas pueden llegar a su p\u00fablico objetivo en Pinterest. \u00abNos alegra mucho compartir los grandes resultados que hemos conseguido con nuestra campa\u00f1a de Ladr\u00f3n de Manzanas en Pinterest\u00bb, destaca Alberto Tucci, director de medios y aceleraci\u00f3n digital en Heineken Espa\u00f1a.<br \/>\n\u00abOptamos por anunciarnos aqu\u00ed para llegar a nuevos p\u00fablicos en un entorno positivo e inspirador, cuando los consumidores empezaban a prepararse para el verano\u00bb, puntualiza. Cabe destacar que esta campa\u00f1a es fruto de una colaboraci\u00f3n entre Heineken Espa\u00f1a y su agencia asociada Detsu.<\/p>\n<p>No te pierdas nada de MarketingDirecto.com y \u00fanete a nuestro Telegram t.me\/MarketingDirecto<\/p>\n<p>\n<!--noindex--><br \/>\n<a href=\"https:\/\/www.marketingdirecto.com\/digital-general\/social-media-marketing\/boom-pinterest-marcas-alimentacion-bebidas-caso-exito-heineken\" rel=\"nofollow\">Source link <\/a><br \/>\n<!--\/noindex--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El 82% de los usuarios recurre a Pinterest para decidir por qu\u00e9 producto decantarse en el \u00e1mbito de la alimentaci\u00f3n y la bebida. Frente a la aparici\u00f3n de nuevas plataformas sociales, Pinterest contin\u00faa manteni\u00e9ndose en el mercado pese al paso de los a\u00f1os. TikTok o Twitch acaparan las conversaciones, pero lo cierto es que la [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":15956,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-15955","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-marketing-digital"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Las visualizaciones de v\u00eddeo en Pinterest aumentan m\u00e1s del 240% - Super News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/super-news.info\/es\/las-visualizaciones-de-video-en-pinterest-aumentan-mas-del-240\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las visualizaciones de v\u00eddeo en Pinterest aumentan m\u00e1s del 240% - Super News\" \/>\n<meta property=\"og:description\" content=\"El 82% de los usuarios recurre a Pinterest para decidir por qu\u00e9 producto decantarse en el \u00e1mbito de la alimentaci\u00f3n y la bebida. Frente a la aparici\u00f3n de nuevas plataformas sociales, Pinterest contin\u00faa manteni\u00e9ndose en el mercado pese al paso de los a\u00f1os. TikTok o Twitch acaparan las conversaciones, pero lo cierto es que la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/super-news.info\/es\/las-visualizaciones-de-video-en-pinterest-aumentan-mas-del-240\/\" \/>\n<meta property=\"og:site_name\" content=\"Super News\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-04T22:46:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-04T22:47:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/super-news.info\/es\/wp-content\/uploads\/sites\/4\/2021\/09\/Las-visualizaciones-de-video-en-Pinterest-aumentan-mas-del-240.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"super-news\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"super-news\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/las-visualizaciones-de-video-en-pinterest-aumentan-mas-del-240\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/las-visualizaciones-de-video-en-pinterest-aumentan-mas-del-240\\\/\"},\"author\":{\"name\":\"super-news\",\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/#\\\/schema\\\/person\\\/2d4068cb2f39cd10008c2fce578a7356\"},\"headline\":\"Las visualizaciones de v\u00eddeo en Pinterest aumentan m\u00e1s del 240%\",\"datePublished\":\"2021-09-04T22:46:51+00:00\",\"dateModified\":\"2021-09-04T22:47:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/las-visualizaciones-de-video-en-pinterest-aumentan-mas-del-240\\\/\"},\"wordCount\":493,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/las-visualizaciones-de-video-en-pinterest-aumentan-mas-del-240\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/super-news.info\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/09\\\/Las-visualizaciones-de-video-en-Pinterest-aumentan-mas-del-240.jpg\",\"articleSection\":[\"NOTICIAS DE MARKETING DIGITAL\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/super-news.info\\\/es\\\/las-visualizaciones-de-video-en-pinterest-aumentan-mas-del-240\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/las-visualizaciones-de-video-en-pinterest-aumentan-mas-del-240\\\/\",\"url\":\"https:\\\/\\\/super-news.info\\\/es\\\/las-visualizaciones-de-video-en-pinterest-aumentan-mas-del-240\\\/\",\"name\":\"Las visualizaciones de v\u00eddeo en Pinterest aumentan m\u00e1s del 240% - Super News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/las-visualizaciones-de-video-en-pinterest-aumentan-mas-del-240\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/las-visualizaciones-de-video-en-pinterest-aumentan-mas-del-240\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/super-news.info\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/09\\\/Las-visualizaciones-de-video-en-Pinterest-aumentan-mas-del-240.jpg\",\"datePublished\":\"2021-09-04T22:46:51+00:00\",\"dateModified\":\"2021-09-04T22:47:17+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/#\\\/schema\\\/person\\\/2d4068cb2f39cd10008c2fce578a7356\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/las-visualizaciones-de-video-en-pinterest-aumentan-mas-del-240\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/super-news.info\\\/es\\\/las-visualizaciones-de-video-en-pinterest-aumentan-mas-del-240\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/las-visualizaciones-de-video-en-pinterest-aumentan-mas-del-240\\\/#primaryimage\",\"url\":\"https:\\\/\\\/super-news.info\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/09\\\/Las-visualizaciones-de-video-en-Pinterest-aumentan-mas-del-240.jpg\",\"contentUrl\":\"https:\\\/\\\/super-news.info\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/09\\\/Las-visualizaciones-de-video-en-Pinterest-aumentan-mas-del-240.jpg\",\"width\":1200,\"height\":675,\"caption\":\"Las visualizaciones de v\u00eddeo en Pinterest aumentan m\u00e1s del 240%\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/las-visualizaciones-de-video-en-pinterest-aumentan-mas-del-240\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430\",\"item\":\"https:\\\/\\\/super-news.info\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las visualizaciones de v\u00eddeo en Pinterest aumentan m\u00e1s del 240%\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/super-news.info\\\/es\\\/\",\"name\":\"Super News\",\"description\":\"Super News Espa\u00f1a\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/super-news.info\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/#\\\/schema\\\/person\\\/2d4068cb2f39cd10008c2fce578a7356\",\"name\":\"super-news\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g\",\"caption\":\"super-news\"},\"url\":\"https:\\\/\\\/super-news.info\\\/es\\\/author\\\/pt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las visualizaciones de v\u00eddeo en Pinterest aumentan m\u00e1s del 240% - Super News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/super-news.info\/es\/las-visualizaciones-de-video-en-pinterest-aumentan-mas-del-240\/","og_locale":"en_US","og_type":"article","og_title":"Las visualizaciones de v\u00eddeo en Pinterest aumentan m\u00e1s del 240% - Super News","og_description":"El 82% de los usuarios recurre a Pinterest para decidir por qu\u00e9 producto decantarse en el \u00e1mbito de la alimentaci\u00f3n y la bebida. Frente a la aparici\u00f3n de nuevas plataformas sociales, Pinterest contin\u00faa manteni\u00e9ndose en el mercado pese al paso de los a\u00f1os. TikTok o Twitch acaparan las conversaciones, pero lo cierto es que la [&hellip;]","og_url":"https:\/\/super-news.info\/es\/las-visualizaciones-de-video-en-pinterest-aumentan-mas-del-240\/","og_site_name":"Super News","article_published_time":"2021-09-04T22:46:51+00:00","article_modified_time":"2021-09-04T22:47:17+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/super-news.info\/es\/wp-content\/uploads\/sites\/4\/2021\/09\/Las-visualizaciones-de-video-en-Pinterest-aumentan-mas-del-240.jpg","type":"image\/jpeg"}],"author":"super-news","twitter_card":"summary_large_image","twitter_misc":{"Written by":"super-news","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/super-news.info\/es\/las-visualizaciones-de-video-en-pinterest-aumentan-mas-del-240\/#article","isPartOf":{"@id":"https:\/\/super-news.info\/es\/las-visualizaciones-de-video-en-pinterest-aumentan-mas-del-240\/"},"author":{"name":"super-news","@id":"https:\/\/super-news.info\/es\/#\/schema\/person\/2d4068cb2f39cd10008c2fce578a7356"},"headline":"Las visualizaciones de v\u00eddeo en Pinterest aumentan m\u00e1s del 240%","datePublished":"2021-09-04T22:46:51+00:00","dateModified":"2021-09-04T22:47:17+00:00","mainEntityOfPage":{"@id":"https:\/\/super-news.info\/es\/las-visualizaciones-de-video-en-pinterest-aumentan-mas-del-240\/"},"wordCount":493,"commentCount":0,"image":{"@id":"https:\/\/super-news.info\/es\/las-visualizaciones-de-video-en-pinterest-aumentan-mas-del-240\/#primaryimage"},"thumbnailUrl":"https:\/\/super-news.info\/es\/wp-content\/uploads\/sites\/4\/2021\/09\/Las-visualizaciones-de-video-en-Pinterest-aumentan-mas-del-240.jpg","articleSection":["NOTICIAS DE MARKETING DIGITAL"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/super-news.info\/es\/las-visualizaciones-de-video-en-pinterest-aumentan-mas-del-240\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/super-news.info\/es\/las-visualizaciones-de-video-en-pinterest-aumentan-mas-del-240\/","url":"https:\/\/super-news.info\/es\/las-visualizaciones-de-video-en-pinterest-aumentan-mas-del-240\/","name":"Las visualizaciones de v\u00eddeo en Pinterest aumentan m\u00e1s del 240% - Super News","isPartOf":{"@id":"https:\/\/super-news.info\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/super-news.info\/es\/las-visualizaciones-de-video-en-pinterest-aumentan-mas-del-240\/#primaryimage"},"image":{"@id":"https:\/\/super-news.info\/es\/las-visualizaciones-de-video-en-pinterest-aumentan-mas-del-240\/#primaryimage"},"thumbnailUrl":"https:\/\/super-news.info\/es\/wp-content\/uploads\/sites\/4\/2021\/09\/Las-visualizaciones-de-video-en-Pinterest-aumentan-mas-del-240.jpg","datePublished":"2021-09-04T22:46:51+00:00","dateModified":"2021-09-04T22:47:17+00:00","author":{"@id":"https:\/\/super-news.info\/es\/#\/schema\/person\/2d4068cb2f39cd10008c2fce578a7356"},"breadcrumb":{"@id":"https:\/\/super-news.info\/es\/las-visualizaciones-de-video-en-pinterest-aumentan-mas-del-240\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/super-news.info\/es\/las-visualizaciones-de-video-en-pinterest-aumentan-mas-del-240\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/super-news.info\/es\/las-visualizaciones-de-video-en-pinterest-aumentan-mas-del-240\/#primaryimage","url":"https:\/\/super-news.info\/es\/wp-content\/uploads\/sites\/4\/2021\/09\/Las-visualizaciones-de-video-en-Pinterest-aumentan-mas-del-240.jpg","contentUrl":"https:\/\/super-news.info\/es\/wp-content\/uploads\/sites\/4\/2021\/09\/Las-visualizaciones-de-video-en-Pinterest-aumentan-mas-del-240.jpg","width":1200,"height":675,"caption":"Las visualizaciones de v\u00eddeo en Pinterest aumentan m\u00e1s del 240%"},{"@type":"BreadcrumbList","@id":"https:\/\/super-news.info\/es\/las-visualizaciones-de-video-en-pinterest-aumentan-mas-del-240\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430","item":"https:\/\/super-news.info\/es\/"},{"@type":"ListItem","position":2,"name":"Las visualizaciones de v\u00eddeo en Pinterest aumentan m\u00e1s del 240%"}]},{"@type":"WebSite","@id":"https:\/\/super-news.info\/es\/#website","url":"https:\/\/super-news.info\/es\/","name":"Super News","description":"Super News Espa\u00f1a","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/super-news.info\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/super-news.info\/es\/#\/schema\/person\/2d4068cb2f39cd10008c2fce578a7356","name":"super-news","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g","caption":"super-news"},"url":"https:\/\/super-news.info\/es\/author\/pt\/"}]}},"_links":{"self":[{"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/posts\/15955","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/comments?post=15955"}],"version-history":[{"count":1,"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/posts\/15955\/revisions"}],"predecessor-version":[{"id":15957,"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/posts\/15955\/revisions\/15957"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/media\/15956"}],"wp:attachment":[{"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/media?parent=15955"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/categories?post=15955"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/tags?post=15955"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}