{"id":15940,"date":"2021-09-04T01:34:54","date_gmt":"2021-09-03T22:34:54","guid":{"rendered":"https:\/\/super-news.info\/es\/el-ibex-pierde-los-8-900-puntos-y-cae-un-0-6-en-la-semana-tras-el-dato-del-paro-en-ee-uu\/"},"modified":"2021-09-04T01:34:58","modified_gmt":"2021-09-03T22:34:58","slug":"el-ibex-pierde-los-8-900-puntos-y-cae-un-0-6-en-la-semana-tras-el-dato-del-paro-en-ee-uu","status":"publish","type":"post","link":"https:\/\/super-news.info\/es\/el-ibex-pierde-los-8-900-puntos-y-cae-un-0-6-en-la-semana-tras-el-dato-del-paro-en-ee-uu\/","title":{"rendered":"El Ibex pierde los 8.900 puntos y cae un 0,6% en la semana, tras el dato del paro en EE.UU."},"content":{"rendered":"<p>\nMADRID, 3 Sep. (EUROPA PRESS) &#8211;<br \/>\n   El Ibex 35 ha retrocedido un 0,65% en la semana y ha perdido los 8.900 puntos en una jornada marcada por la publicaci\u00f3n del dato de paro mensual en Estados Unidos, que ha decepcionado a los inversores, seg\u00fan se\u00f1ala el analista de XTB, Dar\u00edo Garc\u00eda.<br \/>\n   En concreto, la tasa de desempleo de Estados Unidos se situ\u00f3 en el 5,2% el pasado mes de agosto, dos d\u00e9cimas menos que el dato registrado en el mes precedente. La recuperaci\u00f3n econ\u00f3mica del pa\u00eds se ralentiz\u00f3 en el octavo mes del a\u00f1o al crearse \u00fanicamente 235.000 empleos no agr\u00edcolas. Entre junio y julio se crearon algo m\u00e1s de dos millones de puestos de trabajo.<br \/>\n   Desde que comenz\u00f3 la recuperaci\u00f3n en mayo de 2020, Estados Unidos ha recuperado 17 millones de empleos no agr\u00edcolas, tres cuartas partas de los puestos de trabajo destruidos con la crisis. Estados Unidos todav\u00eda tiene que recuperar 5,3 millones de empleos para recuperar por completo el mercado de trabajo que hab\u00eda antes de que recibiera el impacto del Covid-19.<br \/>\n   El analista de XTB se\u00f1ala que este dato ha acabado &#8220;decepcionando&#8221; a los inversores al ser una cifra &#8220;sustancialmente inferior&#8221; a la esperada por el mercado. Adem\u00e1s, los datos de PMI de servicios de algunos pa\u00edses europeos, incluyendo Espa\u00f1a, &#8220;tambi\u00e9n decepcionan al publicarse cifras peores a las esperadas&#8221;, afirma Garc\u00eda.<br \/>\n   Este contexto le habr\u00eda pasado factura al Ibex 35, impidi\u00e9ndole alcanzar la cota de los 9.000 puntos. El Dax alem\u00e1n tambi\u00e9n habr\u00eda retrocedido un 0,2% en la semana, mientras que el Eurostoxx 50 sumar\u00eda un 0,5%, junto a los \u00edndices de Francia e Italia.<br \/>\n   En EE.UU., el Nasdaq consigue una revalorizaci\u00f3n semanal cercana al 1,3%, el S&amp;P 500 del 0,6% y el Dow Jones se mantendr\u00eda plano.<br \/>\n   El dato de empleo en Estados Unidos tambi\u00e9n afecta al d\u00f3lar, que pierde terreno &#8220;con bastante intensidad&#8221; frente al euro y roza los 1,19 d\u00f3lares. &#8220;Este comportamiento de la divisa permite que las materias primas energ\u00e9ticas se anoten interesantes subidas&#8221;, sostiene el experto de XTB.<br \/>\n   En concreto, el gas natural remonta un 7,4% en la semana, el barril de West Texas consigue un alza del 2,2%, mientras el de Brent sube un 1%.<br \/>\n   Dentro del Ibex 35, el valor que m\u00e1s ha destacado en la semana ha sido Pharma Mar, con una subida de m\u00e1s del 10%, seguido por Endesa, con un 4,6%, Indra (+4,3%), Acciona (+4%) y Ferrovial (+3,7%). La banca se anota una &#8220;t\u00edmida&#8221; subida media del 1% en la semana.<br \/>\n   Por el lado contrario, el sector tur\u00edstico ha sufrido esta semana, sobre todo IAG, que retrocede un 3,3% en la semana, si bien el &#8216;farolillo rojo&#8217; ha sido Cellnex, que ha registrado una ca\u00edda del 4,9%.<br \/>\n   Para la semana que viene, los inversores estar\u00e1n pendientes del dato de la producci\u00f3n industrial de Alemania y el \u00edndice ZEW de sentimiento econ\u00f3mico.<br \/>\n   Adem\u00e1s, respecto a los bancos centrales, se conocer\u00e1n la decisi\u00f3n de tipos del Banco de Canad\u00e1 y del Banco Central Europeo.<br \/>\nUNA CA\u00cdDA DEL 1,3% EN LA SESI\u00d3N<br \/>\n   Con respecto a la sesi\u00f3n de ayer, el \u00edndice madrile\u00f1o ha retrocedido un 1,3%, hasta situarse en los 8.864 enteros, con pr\u00e1cticamente todos los valores en rojo, salvo Pharma Mar (+2,06%) y Solaria (+1,72%).<br \/>\n   Por el contrario, en el terreno negativo, destaca la ca\u00edda registrada por el sector tur\u00edstico. As\u00ed, Aena (-3,32%), Meli\u00e1 (-3,37%), Colonial (-2,93%), Amadeus (-2,73%), IAG (-2,39) y Banco Sabadell (-2,29) han sido los valores m\u00e1s penalizados en la sesi\u00f3n de hoy.<br \/>\n   El resto de bolsas europeas tambi\u00e9n han cerrado en negativo, con una correcci\u00f3n del 0,35% en Londres, del 1,08% en Par\u00eds, del 0,37% en Fr\u00e1ncfort y del 0,64% en Mil\u00e1n.<br \/>\n   En este contexto, el barril de petr\u00f3leo West Texas Intermediate (WTI), de referencia para Estados Unidos, cotizaba en 69,72 d\u00f3lares, mientras que el crudo Brent, de referencia para Europa, marcaba un precio de 72,97 d\u00f3lares.<br \/>\n   Por \u00faltimo, la cotizaci\u00f3n del euro frente al d\u00f3lar se colocaba en 1,1885 &#8216;billetes verdes&#8217;, mientras que la prima de riesgo espa\u00f1ola se situaba en 70,47 puntos b\u00e1sicos, con el inter\u00e9s exigido al bono a diez a\u00f1os en el 0,333%.<br \/>\n<br \/>\n<!--noindex--><br \/>\n<a href=\"https:\/\/www.europapress.es\/economia\/bolsa-00348\/noticia-ibex-pierde-8900-puntos-cae-06-semana-dato-paro-eeuu-20210903180029.html\" rel=\"nofollow\">Source link <\/a><br \/>\n<!--\/noindex--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>MADRID, 3 Sep. (EUROPA PRESS) &#8211; El Ibex 35 ha retrocedido un 0,65% en la semana y ha perdido los 8.900 puntos en una jornada marcada por la publicaci\u00f3n del dato de paro mensual en Estados Unidos, que ha decepcionado a los inversores, seg\u00fan se\u00f1ala el analista de XTB, Dar\u00edo Garc\u00eda. En concreto, la tasa [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":15941,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-15940","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-financieras"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Ibex pierde los 8.900 puntos y cae un 0,6% en la semana, tras el dato del paro en EE.UU. - Super News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/super-news.info\/es\/el-ibex-pierde-los-8-900-puntos-y-cae-un-0-6-en-la-semana-tras-el-dato-del-paro-en-ee-uu\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Ibex pierde los 8.900 puntos y cae un 0,6% en la semana, tras el dato del paro en EE.UU. - Super News\" \/>\n<meta property=\"og:description\" content=\"MADRID, 3 Sep. (EUROPA PRESS) &#8211; El Ibex 35 ha retrocedido un 0,65% en la semana y ha perdido los 8.900 puntos en una jornada marcada por la publicaci\u00f3n del dato de paro mensual en Estados Unidos, que ha decepcionado a los inversores, seg\u00fan se\u00f1ala el analista de XTB, Dar\u00edo Garc\u00eda. En concreto, la tasa [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/super-news.info\/es\/el-ibex-pierde-los-8-900-puntos-y-cae-un-0-6-en-la-semana-tras-el-dato-del-paro-en-ee-uu\/\" \/>\n<meta property=\"og:site_name\" content=\"Super News\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-03T22:34:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-03T22:34:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/super-news.info\/es\/wp-content\/uploads\/sites\/4\/2021\/09\/El-Ibex-pierde-los-8900-puntos-y-cae-un-06.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"120\" \/>\n\t<meta property=\"og:image:height\" content=\"79\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"super-news\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"super-news\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/el-ibex-pierde-los-8-900-puntos-y-cae-un-0-6-en-la-semana-tras-el-dato-del-paro-en-ee-uu\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/el-ibex-pierde-los-8-900-puntos-y-cae-un-0-6-en-la-semana-tras-el-dato-del-paro-en-ee-uu\\\/\"},\"author\":{\"name\":\"super-news\",\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/#\\\/schema\\\/person\\\/2d4068cb2f39cd10008c2fce578a7356\"},\"headline\":\"El Ibex pierde los 8.900 puntos y cae un 0,6% en la semana, tras el dato del paro en EE.UU.\",\"datePublished\":\"2021-09-03T22:34:54+00:00\",\"dateModified\":\"2021-09-03T22:34:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/el-ibex-pierde-los-8-900-puntos-y-cae-un-0-6-en-la-semana-tras-el-dato-del-paro-en-ee-uu\\\/\"},\"wordCount\":731,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/el-ibex-pierde-los-8-900-puntos-y-cae-un-0-6-en-la-semana-tras-el-dato-del-paro-en-ee-uu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/super-news.info\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/09\\\/El-Ibex-pierde-los-8900-puntos-y-cae-un-06.jpg\",\"articleSection\":[\"NOTICIAS FINANCIERAS\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/super-news.info\\\/es\\\/el-ibex-pierde-los-8-900-puntos-y-cae-un-0-6-en-la-semana-tras-el-dato-del-paro-en-ee-uu\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/el-ibex-pierde-los-8-900-puntos-y-cae-un-0-6-en-la-semana-tras-el-dato-del-paro-en-ee-uu\\\/\",\"url\":\"https:\\\/\\\/super-news.info\\\/es\\\/el-ibex-pierde-los-8-900-puntos-y-cae-un-0-6-en-la-semana-tras-el-dato-del-paro-en-ee-uu\\\/\",\"name\":\"El Ibex pierde los 8.900 puntos y cae un 0,6% en la semana, tras el dato del paro en EE.UU. - Super News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/el-ibex-pierde-los-8-900-puntos-y-cae-un-0-6-en-la-semana-tras-el-dato-del-paro-en-ee-uu\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/el-ibex-pierde-los-8-900-puntos-y-cae-un-0-6-en-la-semana-tras-el-dato-del-paro-en-ee-uu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/super-news.info\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/09\\\/El-Ibex-pierde-los-8900-puntos-y-cae-un-06.jpg\",\"datePublished\":\"2021-09-03T22:34:54+00:00\",\"dateModified\":\"2021-09-03T22:34:58+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/#\\\/schema\\\/person\\\/2d4068cb2f39cd10008c2fce578a7356\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/el-ibex-pierde-los-8-900-puntos-y-cae-un-0-6-en-la-semana-tras-el-dato-del-paro-en-ee-uu\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/super-news.info\\\/es\\\/el-ibex-pierde-los-8-900-puntos-y-cae-un-0-6-en-la-semana-tras-el-dato-del-paro-en-ee-uu\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/el-ibex-pierde-los-8-900-puntos-y-cae-un-0-6-en-la-semana-tras-el-dato-del-paro-en-ee-uu\\\/#primaryimage\",\"url\":\"https:\\\/\\\/super-news.info\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/09\\\/El-Ibex-pierde-los-8900-puntos-y-cae-un-06.jpg\",\"contentUrl\":\"https:\\\/\\\/super-news.info\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/09\\\/El-Ibex-pierde-los-8900-puntos-y-cae-un-06.jpg\",\"width\":120,\"height\":79,\"caption\":\"El Ibex pierde los 8.900 puntos y cae un 0,6% en la semana, tras el dato del paro en EE.UU.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/el-ibex-pierde-los-8-900-puntos-y-cae-un-0-6-en-la-semana-tras-el-dato-del-paro-en-ee-uu\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430\",\"item\":\"https:\\\/\\\/super-news.info\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Ibex pierde los 8.900 puntos y cae un 0,6% en la semana, tras el dato del paro en EE.UU.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/super-news.info\\\/es\\\/\",\"name\":\"Super News\",\"description\":\"Super News Espa\u00f1a\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/super-news.info\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/#\\\/schema\\\/person\\\/2d4068cb2f39cd10008c2fce578a7356\",\"name\":\"super-news\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g\",\"caption\":\"super-news\"},\"url\":\"https:\\\/\\\/super-news.info\\\/es\\\/author\\\/pt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Ibex pierde los 8.900 puntos y cae un 0,6% en la semana, tras el dato del paro en EE.UU. - Super News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/super-news.info\/es\/el-ibex-pierde-los-8-900-puntos-y-cae-un-0-6-en-la-semana-tras-el-dato-del-paro-en-ee-uu\/","og_locale":"en_US","og_type":"article","og_title":"El Ibex pierde los 8.900 puntos y cae un 0,6% en la semana, tras el dato del paro en EE.UU. - Super News","og_description":"MADRID, 3 Sep. (EUROPA PRESS) &#8211; El Ibex 35 ha retrocedido un 0,65% en la semana y ha perdido los 8.900 puntos en una jornada marcada por la publicaci\u00f3n del dato de paro mensual en Estados Unidos, que ha decepcionado a los inversores, seg\u00fan se\u00f1ala el analista de XTB, Dar\u00edo Garc\u00eda. En concreto, la tasa [&hellip;]","og_url":"https:\/\/super-news.info\/es\/el-ibex-pierde-los-8-900-puntos-y-cae-un-0-6-en-la-semana-tras-el-dato-del-paro-en-ee-uu\/","og_site_name":"Super News","article_published_time":"2021-09-03T22:34:54+00:00","article_modified_time":"2021-09-03T22:34:58+00:00","og_image":[{"width":120,"height":79,"url":"https:\/\/super-news.info\/es\/wp-content\/uploads\/sites\/4\/2021\/09\/El-Ibex-pierde-los-8900-puntos-y-cae-un-06.jpg","type":"image\/jpeg"}],"author":"super-news","twitter_card":"summary_large_image","twitter_misc":{"Written by":"super-news","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/super-news.info\/es\/el-ibex-pierde-los-8-900-puntos-y-cae-un-0-6-en-la-semana-tras-el-dato-del-paro-en-ee-uu\/#article","isPartOf":{"@id":"https:\/\/super-news.info\/es\/el-ibex-pierde-los-8-900-puntos-y-cae-un-0-6-en-la-semana-tras-el-dato-del-paro-en-ee-uu\/"},"author":{"name":"super-news","@id":"https:\/\/super-news.info\/es\/#\/schema\/person\/2d4068cb2f39cd10008c2fce578a7356"},"headline":"El Ibex pierde los 8.900 puntos y cae un 0,6% en la semana, tras el dato del paro en EE.UU.","datePublished":"2021-09-03T22:34:54+00:00","dateModified":"2021-09-03T22:34:58+00:00","mainEntityOfPage":{"@id":"https:\/\/super-news.info\/es\/el-ibex-pierde-los-8-900-puntos-y-cae-un-0-6-en-la-semana-tras-el-dato-del-paro-en-ee-uu\/"},"wordCount":731,"commentCount":0,"image":{"@id":"https:\/\/super-news.info\/es\/el-ibex-pierde-los-8-900-puntos-y-cae-un-0-6-en-la-semana-tras-el-dato-del-paro-en-ee-uu\/#primaryimage"},"thumbnailUrl":"https:\/\/super-news.info\/es\/wp-content\/uploads\/sites\/4\/2021\/09\/El-Ibex-pierde-los-8900-puntos-y-cae-un-06.jpg","articleSection":["NOTICIAS FINANCIERAS"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/super-news.info\/es\/el-ibex-pierde-los-8-900-puntos-y-cae-un-0-6-en-la-semana-tras-el-dato-del-paro-en-ee-uu\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/super-news.info\/es\/el-ibex-pierde-los-8-900-puntos-y-cae-un-0-6-en-la-semana-tras-el-dato-del-paro-en-ee-uu\/","url":"https:\/\/super-news.info\/es\/el-ibex-pierde-los-8-900-puntos-y-cae-un-0-6-en-la-semana-tras-el-dato-del-paro-en-ee-uu\/","name":"El Ibex pierde los 8.900 puntos y cae un 0,6% en la semana, tras el dato del paro en EE.UU. - Super News","isPartOf":{"@id":"https:\/\/super-news.info\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/super-news.info\/es\/el-ibex-pierde-los-8-900-puntos-y-cae-un-0-6-en-la-semana-tras-el-dato-del-paro-en-ee-uu\/#primaryimage"},"image":{"@id":"https:\/\/super-news.info\/es\/el-ibex-pierde-los-8-900-puntos-y-cae-un-0-6-en-la-semana-tras-el-dato-del-paro-en-ee-uu\/#primaryimage"},"thumbnailUrl":"https:\/\/super-news.info\/es\/wp-content\/uploads\/sites\/4\/2021\/09\/El-Ibex-pierde-los-8900-puntos-y-cae-un-06.jpg","datePublished":"2021-09-03T22:34:54+00:00","dateModified":"2021-09-03T22:34:58+00:00","author":{"@id":"https:\/\/super-news.info\/es\/#\/schema\/person\/2d4068cb2f39cd10008c2fce578a7356"},"breadcrumb":{"@id":"https:\/\/super-news.info\/es\/el-ibex-pierde-los-8-900-puntos-y-cae-un-0-6-en-la-semana-tras-el-dato-del-paro-en-ee-uu\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/super-news.info\/es\/el-ibex-pierde-los-8-900-puntos-y-cae-un-0-6-en-la-semana-tras-el-dato-del-paro-en-ee-uu\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/super-news.info\/es\/el-ibex-pierde-los-8-900-puntos-y-cae-un-0-6-en-la-semana-tras-el-dato-del-paro-en-ee-uu\/#primaryimage","url":"https:\/\/super-news.info\/es\/wp-content\/uploads\/sites\/4\/2021\/09\/El-Ibex-pierde-los-8900-puntos-y-cae-un-06.jpg","contentUrl":"https:\/\/super-news.info\/es\/wp-content\/uploads\/sites\/4\/2021\/09\/El-Ibex-pierde-los-8900-puntos-y-cae-un-06.jpg","width":120,"height":79,"caption":"El Ibex pierde los 8.900 puntos y cae un 0,6% en la semana, tras el dato del paro en EE.UU."},{"@type":"BreadcrumbList","@id":"https:\/\/super-news.info\/es\/el-ibex-pierde-los-8-900-puntos-y-cae-un-0-6-en-la-semana-tras-el-dato-del-paro-en-ee-uu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430","item":"https:\/\/super-news.info\/es\/"},{"@type":"ListItem","position":2,"name":"El Ibex pierde los 8.900 puntos y cae un 0,6% en la semana, tras el dato del paro en EE.UU."}]},{"@type":"WebSite","@id":"https:\/\/super-news.info\/es\/#website","url":"https:\/\/super-news.info\/es\/","name":"Super News","description":"Super News Espa\u00f1a","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/super-news.info\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/super-news.info\/es\/#\/schema\/person\/2d4068cb2f39cd10008c2fce578a7356","name":"super-news","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g","caption":"super-news"},"url":"https:\/\/super-news.info\/es\/author\/pt\/"}]}},"_links":{"self":[{"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/posts\/15940","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/comments?post=15940"}],"version-history":[{"count":1,"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/posts\/15940\/revisions"}],"predecessor-version":[{"id":15942,"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/posts\/15940\/revisions\/15942"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/media\/15941"}],"wp:attachment":[{"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/media?parent=15940"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/categories?post=15940"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/tags?post=15940"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}