{"id":15934,"date":"2021-09-03T13:34:16","date_gmt":"2021-09-03T10:34:16","guid":{"rendered":"https:\/\/super-news.info\/es\/la-cnmc-inicia-el-analisis-de-competencia-ante-la-integracion-de-bankia-mapfre-vida-en-caixabank\/"},"modified":"2021-09-03T13:34:23","modified_gmt":"2021-09-03T10:34:23","slug":"la-cnmc-inicia-el-analisis-de-competencia-ante-la-integracion-de-bankia-mapfre-vida-en-caixabank","status":"publish","type":"post","link":"https:\/\/super-news.info\/es\/la-cnmc-inicia-el-analisis-de-competencia-ante-la-integracion-de-bankia-mapfre-vida-en-caixabank\/","title":{"rendered":"La CNMC inicia el an\u00e1lisis de competencia ante la integraci\u00f3n de Bankia Mapfre Vida en CaixaBank"},"content":{"rendered":"<p>\nMADRID, 3 Sep. (EUROPA PRESS) &#8211;<br \/>\n   La Comisi\u00f3n Nacional de los Mercados y de la Competencia (CNMC) ha dado inicio al an\u00e1lisis en primera fase de la adquisici\u00f3n y control exclusivo de Bankia Mapfre Vida por parte de CaixaBank, seg\u00fan los registros del supervisor.<br \/>\n   Tal y como han indicado fuentes de la entidad presidida por Ignacio Goirigolzarri a Europa Press, se trata de un tr\u00e1mite habitual solicitado por la propia CaixaBank con el objetivo de aligerar el proceso de integraci\u00f3n de la aseguradora en el negocio de seguros del banco, tras la fusi\u00f3n con Bankia y que ha implicado, a su vez, la ruptura entre Bankia y Mapfre en el negocio de los seguros.<br \/>\n   En concreto, el 25 de agosto el banco remiti\u00f3 la informaci\u00f3n necesaria a la CNMC para iniciar este an\u00e1lisis de la operaci\u00f3n, tal y como ha adelantado hoy &#8216;La Informaci\u00f3n&#8217;.<br \/>\nUNA RUPTURA PENDIENTE DE LA VALORACI\u00d3N<br \/>\n   La absorci\u00f3n de Bankia Mapfre Vida por CaixaBank todav\u00eda no se ha cerrado, si bien podr\u00eda producirse antes de que finalice el a\u00f1o.<br \/>\n   El \u00faltimo informe financiero de Mapfre, correspondiente al primer semestre de 2021, se\u00f1alaba que un experto independiente nombrado por Mapfre y CaixaBank trabajaba en la valoraci\u00f3n de los negocios compartidos con Bankia ante la ruptura del acuerdo de bancaseguros entre Mapfre y Bankia tras la absorci\u00f3n de la entidad por el banco de origen catal\u00e1n.<br \/>\n   La integraci\u00f3n de Bankia en CaixaBank constituye un cambio de control en Bankia que, en virtud de los contratos suscritos entre Bankia y Mapfre, confiere a la aseguradora un derecho de opci\u00f3n de venta frente a CaixaBank de las acciones representativas de la participaci\u00f3n del 51% en Bankia Mapfre Vida, as\u00ed como la resoluci\u00f3n del contrato de agencia para la distribuci\u00f3n de seguros de vida y un derecho de resoluci\u00f3n del contrato de agencia para la distribuci\u00f3n de seguros no vida suscrito entre ambas.<br \/>\n   Mapfre comunic\u00f3 a CaixaBank y Bankia el ejercicio de tales derechos, de forma que los procedimientos contractualmente previstos a efectos de las valoraciones de los negocios determinantes del precio (120% del valor de mercado de la participaci\u00f3n del 51% de Mapfre Vida en Bankia Mapfre Vida) e indemnizaci\u00f3n (120% del valor del negocio asegurador no vida, sin incluir el valor de la cartera de seguros) a percibir por la resoluci\u00f3n de sus acuerdos de bancaseguros.<br \/>\n<br \/>\n<!--noindex--><br \/>\n<a href=\"https:\/\/www.europapress.es\/economia\/finanzas-00340\/noticia-cnmc-inicia-analisis-competencia-integracion-bankia-mapfre-vida-caixabank-20210903122819.html\" rel=\"nofollow\">Source link <\/a><br \/>\n<!--\/noindex--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>MADRID, 3 Sep. (EUROPA PRESS) &#8211; La Comisi\u00f3n Nacional de los Mercados y de la Competencia (CNMC) ha dado inicio al an\u00e1lisis en primera fase de la adquisici\u00f3n y control exclusivo de Bankia Mapfre Vida por parte de CaixaBank, seg\u00fan los registros del supervisor. Tal y como han indicado fuentes de la entidad presidida por [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":15935,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-15934","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-financieras"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La CNMC inicia el an\u00e1lisis de competencia ante la integraci\u00f3n de Bankia Mapfre Vida en CaixaBank - Super News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/super-news.info\/es\/la-cnmc-inicia-el-analisis-de-competencia-ante-la-integracion-de-bankia-mapfre-vida-en-caixabank\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La CNMC inicia el an\u00e1lisis de competencia ante la integraci\u00f3n de Bankia Mapfre Vida en CaixaBank - Super News\" \/>\n<meta property=\"og:description\" content=\"MADRID, 3 Sep. (EUROPA PRESS) &#8211; La Comisi\u00f3n Nacional de los Mercados y de la Competencia (CNMC) ha dado inicio al an\u00e1lisis en primera fase de la adquisici\u00f3n y control exclusivo de Bankia Mapfre Vida por parte de CaixaBank, seg\u00fan los registros del supervisor. Tal y como han indicado fuentes de la entidad presidida por [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/super-news.info\/es\/la-cnmc-inicia-el-analisis-de-competencia-ante-la-integracion-de-bankia-mapfre-vida-en-caixabank\/\" \/>\n<meta property=\"og:site_name\" content=\"Super News\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-03T10:34:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-03T10:34:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/super-news.info\/es\/wp-content\/uploads\/sites\/4\/2021\/09\/La-CNMC-inicia-el-analisis-de-competencia-ante-la-integracion.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"120\" \/>\n\t<meta property=\"og:image:height\" content=\"80\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"super-news\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"super-news\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/la-cnmc-inicia-el-analisis-de-competencia-ante-la-integracion-de-bankia-mapfre-vida-en-caixabank\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/la-cnmc-inicia-el-analisis-de-competencia-ante-la-integracion-de-bankia-mapfre-vida-en-caixabank\\\/\"},\"author\":{\"name\":\"super-news\",\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/#\\\/schema\\\/person\\\/2d4068cb2f39cd10008c2fce578a7356\"},\"headline\":\"La CNMC inicia el an\u00e1lisis de competencia ante la integraci\u00f3n de Bankia Mapfre Vida en CaixaBank\",\"datePublished\":\"2021-09-03T10:34:16+00:00\",\"dateModified\":\"2021-09-03T10:34:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/la-cnmc-inicia-el-analisis-de-competencia-ante-la-integracion-de-bankia-mapfre-vida-en-caixabank\\\/\"},\"wordCount\":430,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/la-cnmc-inicia-el-analisis-de-competencia-ante-la-integracion-de-bankia-mapfre-vida-en-caixabank\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/super-news.info\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/09\\\/La-CNMC-inicia-el-analisis-de-competencia-ante-la-integracion.jpg\",\"articleSection\":[\"NOTICIAS FINANCIERAS\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/super-news.info\\\/es\\\/la-cnmc-inicia-el-analisis-de-competencia-ante-la-integracion-de-bankia-mapfre-vida-en-caixabank\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/la-cnmc-inicia-el-analisis-de-competencia-ante-la-integracion-de-bankia-mapfre-vida-en-caixabank\\\/\",\"url\":\"https:\\\/\\\/super-news.info\\\/es\\\/la-cnmc-inicia-el-analisis-de-competencia-ante-la-integracion-de-bankia-mapfre-vida-en-caixabank\\\/\",\"name\":\"La CNMC inicia el an\u00e1lisis de competencia ante la integraci\u00f3n de Bankia Mapfre Vida en CaixaBank - Super News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/la-cnmc-inicia-el-analisis-de-competencia-ante-la-integracion-de-bankia-mapfre-vida-en-caixabank\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/la-cnmc-inicia-el-analisis-de-competencia-ante-la-integracion-de-bankia-mapfre-vida-en-caixabank\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/super-news.info\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/09\\\/La-CNMC-inicia-el-analisis-de-competencia-ante-la-integracion.jpg\",\"datePublished\":\"2021-09-03T10:34:16+00:00\",\"dateModified\":\"2021-09-03T10:34:23+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/#\\\/schema\\\/person\\\/2d4068cb2f39cd10008c2fce578a7356\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/la-cnmc-inicia-el-analisis-de-competencia-ante-la-integracion-de-bankia-mapfre-vida-en-caixabank\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/super-news.info\\\/es\\\/la-cnmc-inicia-el-analisis-de-competencia-ante-la-integracion-de-bankia-mapfre-vida-en-caixabank\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/la-cnmc-inicia-el-analisis-de-competencia-ante-la-integracion-de-bankia-mapfre-vida-en-caixabank\\\/#primaryimage\",\"url\":\"https:\\\/\\\/super-news.info\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/09\\\/La-CNMC-inicia-el-analisis-de-competencia-ante-la-integracion.jpg\",\"contentUrl\":\"https:\\\/\\\/super-news.info\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/09\\\/La-CNMC-inicia-el-analisis-de-competencia-ante-la-integracion.jpg\",\"width\":120,\"height\":80,\"caption\":\"La CNMC inicia el an\u00e1lisis de competencia ante la integraci\u00f3n de Bankia Mapfre Vida en CaixaBank\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/la-cnmc-inicia-el-analisis-de-competencia-ante-la-integracion-de-bankia-mapfre-vida-en-caixabank\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430\",\"item\":\"https:\\\/\\\/super-news.info\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La CNMC inicia el an\u00e1lisis de competencia ante la integraci\u00f3n de Bankia Mapfre Vida en CaixaBank\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/super-news.info\\\/es\\\/\",\"name\":\"Super News\",\"description\":\"Super News Espa\u00f1a\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/super-news.info\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/#\\\/schema\\\/person\\\/2d4068cb2f39cd10008c2fce578a7356\",\"name\":\"super-news\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g\",\"caption\":\"super-news\"},\"url\":\"https:\\\/\\\/super-news.info\\\/es\\\/author\\\/pt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La CNMC inicia el an\u00e1lisis de competencia ante la integraci\u00f3n de Bankia Mapfre Vida en CaixaBank - Super News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/super-news.info\/es\/la-cnmc-inicia-el-analisis-de-competencia-ante-la-integracion-de-bankia-mapfre-vida-en-caixabank\/","og_locale":"en_US","og_type":"article","og_title":"La CNMC inicia el an\u00e1lisis de competencia ante la integraci\u00f3n de Bankia Mapfre Vida en CaixaBank - Super News","og_description":"MADRID, 3 Sep. (EUROPA PRESS) &#8211; La Comisi\u00f3n Nacional de los Mercados y de la Competencia (CNMC) ha dado inicio al an\u00e1lisis en primera fase de la adquisici\u00f3n y control exclusivo de Bankia Mapfre Vida por parte de CaixaBank, seg\u00fan los registros del supervisor. Tal y como han indicado fuentes de la entidad presidida por [&hellip;]","og_url":"https:\/\/super-news.info\/es\/la-cnmc-inicia-el-analisis-de-competencia-ante-la-integracion-de-bankia-mapfre-vida-en-caixabank\/","og_site_name":"Super News","article_published_time":"2021-09-03T10:34:16+00:00","article_modified_time":"2021-09-03T10:34:23+00:00","og_image":[{"width":120,"height":80,"url":"https:\/\/super-news.info\/es\/wp-content\/uploads\/sites\/4\/2021\/09\/La-CNMC-inicia-el-analisis-de-competencia-ante-la-integracion.jpg","type":"image\/jpeg"}],"author":"super-news","twitter_card":"summary_large_image","twitter_misc":{"Written by":"super-news","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/super-news.info\/es\/la-cnmc-inicia-el-analisis-de-competencia-ante-la-integracion-de-bankia-mapfre-vida-en-caixabank\/#article","isPartOf":{"@id":"https:\/\/super-news.info\/es\/la-cnmc-inicia-el-analisis-de-competencia-ante-la-integracion-de-bankia-mapfre-vida-en-caixabank\/"},"author":{"name":"super-news","@id":"https:\/\/super-news.info\/es\/#\/schema\/person\/2d4068cb2f39cd10008c2fce578a7356"},"headline":"La CNMC inicia el an\u00e1lisis de competencia ante la integraci\u00f3n de Bankia Mapfre Vida en CaixaBank","datePublished":"2021-09-03T10:34:16+00:00","dateModified":"2021-09-03T10:34:23+00:00","mainEntityOfPage":{"@id":"https:\/\/super-news.info\/es\/la-cnmc-inicia-el-analisis-de-competencia-ante-la-integracion-de-bankia-mapfre-vida-en-caixabank\/"},"wordCount":430,"commentCount":0,"image":{"@id":"https:\/\/super-news.info\/es\/la-cnmc-inicia-el-analisis-de-competencia-ante-la-integracion-de-bankia-mapfre-vida-en-caixabank\/#primaryimage"},"thumbnailUrl":"https:\/\/super-news.info\/es\/wp-content\/uploads\/sites\/4\/2021\/09\/La-CNMC-inicia-el-analisis-de-competencia-ante-la-integracion.jpg","articleSection":["NOTICIAS FINANCIERAS"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/super-news.info\/es\/la-cnmc-inicia-el-analisis-de-competencia-ante-la-integracion-de-bankia-mapfre-vida-en-caixabank\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/super-news.info\/es\/la-cnmc-inicia-el-analisis-de-competencia-ante-la-integracion-de-bankia-mapfre-vida-en-caixabank\/","url":"https:\/\/super-news.info\/es\/la-cnmc-inicia-el-analisis-de-competencia-ante-la-integracion-de-bankia-mapfre-vida-en-caixabank\/","name":"La CNMC inicia el an\u00e1lisis de competencia ante la integraci\u00f3n de Bankia Mapfre Vida en CaixaBank - Super News","isPartOf":{"@id":"https:\/\/super-news.info\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/super-news.info\/es\/la-cnmc-inicia-el-analisis-de-competencia-ante-la-integracion-de-bankia-mapfre-vida-en-caixabank\/#primaryimage"},"image":{"@id":"https:\/\/super-news.info\/es\/la-cnmc-inicia-el-analisis-de-competencia-ante-la-integracion-de-bankia-mapfre-vida-en-caixabank\/#primaryimage"},"thumbnailUrl":"https:\/\/super-news.info\/es\/wp-content\/uploads\/sites\/4\/2021\/09\/La-CNMC-inicia-el-analisis-de-competencia-ante-la-integracion.jpg","datePublished":"2021-09-03T10:34:16+00:00","dateModified":"2021-09-03T10:34:23+00:00","author":{"@id":"https:\/\/super-news.info\/es\/#\/schema\/person\/2d4068cb2f39cd10008c2fce578a7356"},"breadcrumb":{"@id":"https:\/\/super-news.info\/es\/la-cnmc-inicia-el-analisis-de-competencia-ante-la-integracion-de-bankia-mapfre-vida-en-caixabank\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/super-news.info\/es\/la-cnmc-inicia-el-analisis-de-competencia-ante-la-integracion-de-bankia-mapfre-vida-en-caixabank\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/super-news.info\/es\/la-cnmc-inicia-el-analisis-de-competencia-ante-la-integracion-de-bankia-mapfre-vida-en-caixabank\/#primaryimage","url":"https:\/\/super-news.info\/es\/wp-content\/uploads\/sites\/4\/2021\/09\/La-CNMC-inicia-el-analisis-de-competencia-ante-la-integracion.jpg","contentUrl":"https:\/\/super-news.info\/es\/wp-content\/uploads\/sites\/4\/2021\/09\/La-CNMC-inicia-el-analisis-de-competencia-ante-la-integracion.jpg","width":120,"height":80,"caption":"La CNMC inicia el an\u00e1lisis de competencia ante la integraci\u00f3n de Bankia Mapfre Vida en CaixaBank"},{"@type":"BreadcrumbList","@id":"https:\/\/super-news.info\/es\/la-cnmc-inicia-el-analisis-de-competencia-ante-la-integracion-de-bankia-mapfre-vida-en-caixabank\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430","item":"https:\/\/super-news.info\/es\/"},{"@type":"ListItem","position":2,"name":"La CNMC inicia el an\u00e1lisis de competencia ante la integraci\u00f3n de Bankia Mapfre Vida en CaixaBank"}]},{"@type":"WebSite","@id":"https:\/\/super-news.info\/es\/#website","url":"https:\/\/super-news.info\/es\/","name":"Super News","description":"Super News Espa\u00f1a","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/super-news.info\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/super-news.info\/es\/#\/schema\/person\/2d4068cb2f39cd10008c2fce578a7356","name":"super-news","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g","caption":"super-news"},"url":"https:\/\/super-news.info\/es\/author\/pt\/"}]}},"_links":{"self":[{"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/posts\/15934","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/comments?post=15934"}],"version-history":[{"count":1,"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/posts\/15934\/revisions"}],"predecessor-version":[{"id":15936,"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/posts\/15934\/revisions\/15936"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/media\/15935"}],"wp:attachment":[{"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/media?parent=15934"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/categories?post=15934"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/tags?post=15934"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}