{"id":1424,"date":"2019-05-10T19:14:09","date_gmt":"2019-05-10T16:14:09","guid":{"rendered":"https:\/\/super-news.info\/es\/el-ibex-35-cierra-su-peor-semana-del-ano-con-una-caida-del-3-que-lo-coloca-en-los-9-100-puntos\/"},"modified":"2019-05-10T19:14:10","modified_gmt":"2019-05-10T16:14:10","slug":"el-ibex-35-cierra-su-peor-semana-del-ano-con-una-caida-del-3-que-lo-coloca-en-los-9-100-puntos","status":"publish","type":"post","link":"https:\/\/super-news.info\/es\/el-ibex-35-cierra-su-peor-semana-del-ano-con-una-caida-del-3-que-lo-coloca-en-los-9-100-puntos\/","title":{"rendered":"El Ibex 35 cierra su peor semana del a\u00f1o con una ca\u00edda del 3% que lo coloca en los 9.100 puntos"},"content":{"rendered":"<p> [ad_1]<\/p>\n<div id=\"CuerpoNoticiav2\" itemprop=\"articleBody\">\n<!--inicio FechaNoticia--><\/p>\n<div class=\"FechaPublicacionNoticia\">Publicado 10\/05\/2019 18:02:09<abbr title=\"Central European Time\">CET<\/abbr><\/div>\n<p><!--fin FechaNoticia--><\/p>\n<p>MADRID, 10 May. (EUROPA PRESS) &#8211; <\/p>\n<p itemprop=\"description\">   El Ibex 35 ha cerrado su semana con peor comportamiento del a\u00f1o, tras experimentar una correcci\u00f3n del 3,09%. No obstante, este viernes parece haber tomado un respiro y ha concluido con un alza del 0,25%, lo que le ha permitido recuperar la cota de los 9.100 puntos que llegaba a perder a lo largo de la jornada.<\/p>\n<p>   En concreto, el principal selectivo espa\u00f1ol se ha colocado en los 9.117,5 enteros, despu\u00e9s de haber acumulado hasta ayer seis sesiones consecutivas en negativo, la peor racha desde noviembre de 2017.<\/p>\n<p>   Esta marcada volatilidad ha venido precedida de un extenso &#8216;rally&#8217; desde los m\u00ednimos marcados en los 8.200 puntos a finales del pasado mes de diciembre.<\/p>\n<p>   El analista de XTB Francisco S\u00e1nchez-Matamoros ha explicado que los motivos de estas ca\u00eddas se encuentran en la agitaci\u00f3n en los mercados desde la guerra comercial entre Estados Unidos y China, as\u00ed como en la toma de beneficios que ha desencadenado una &#8216;oleada&#8217; de ventas que, como suele suceder, ha arrastrado al resto de principales plazas burs\u00e1tiles a nivel global.<\/p>\n<p>   &#8220;La semana ha sido muy negativa para todos los \u00edndices mundiales sin excepci\u00f3n&#8221;, ha subrayado S\u00e1nchez-Matamoros, apuntando que el incremento de la volatilidad durante la semana se ha puesto incluso de manifiesto en la subida de casi el 50% que ha experimentado el \u00edndice VIX, que mide este sentimiento en el mercado.<\/p>\n<p>   Los valores que m\u00e1s han subido este viernes han sido Meli\u00e1 (+2,23%), CIE Automotive (+2,23%), Ence (+2,18%), Endesa (+2,15%), Mediaset (+2,06%) y Enag\u00e1s (+2,05%), mientras que al otro lado de la balanza se han colocado Acciona (-3,01%), ArcelorMittal (-2,62%), Grifols (-1,78%), T\u00e9cnicas Reunidas (-1,39%) y Aena (-0,75%).<\/p>\n<p>   El resto de principales plazas europeas han concluido la jornada en positivo a excepci\u00f3n del Ftse de Londres, que ha ca\u00eddo un 0,09%. El Cac 40 de Par\u00eds ha ascendido un 0,27% y el Dax de Fr\u00e1ncfort un 0,72%.<\/p>\n<p>   Asimismo, el barril de petr\u00f3leo de calidad Brent, referencia para el Viejo Continente, se situaba en 70,72 d\u00f3lares, mientras que el Texas bajaba ligeramente hasta los 61,91 d\u00f3lares.<\/p>\n<p>   De su lado, la cotizaci\u00f3n del euro frente al d\u00f3lar ascend\u00eda a 1,1243 &#8216;billetes verdes&#8217;, mientras que la prima de riesgo espa\u00f1ola se rebajaba hasta 102 puntos b\u00e1sicos, con el inter\u00e9s exigido al bono a diez a\u00f1os en el 0,978%.<\/p>\n<p>   Para la pr\u00f3xima semana, el analista de XTB espera es un escenario &#8220;incierto&#8221;. El sesgo de las palabras de Donald Trump respecto a los aranceles a China marcar\u00e1, sin duda alguna, el devenir de las bolsas y, por ende, del Ibex 35.<\/p>\n<p>   &#8220;Ser\u00e1 fundamental salvar el soporte de los 9.100 puntos para mantener la t\u00f3nica alcista reinante en el medio plazo. En cualquier caso, entendemos como m\u00e1s probable que, dentro del rango entre los 9.100 y los 9.400 puntos, el Ibex 35 apueste por el verde de cara a la pr\u00f3xima semana&#8221;, ha remarcado S\u00e1nchez-Matamoros.<\/p>\n<\/div>\n<p>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.europapress.es\/economia\/bolsa-00348\/noticia-ibex-35-cierra-peor-semana-ano-caida-coloca-9100-puntos-20190510180209.html\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Publicado 10\/05\/2019 18:02:09CET MADRID, 10 May. (EUROPA PRESS) &#8211; El Ibex 35 ha cerrado su semana con peor comportamiento del a\u00f1o, tras experimentar una correcci\u00f3n del 3,09%. No obstante, este viernes parece haber tomado un respiro y ha concluido con un alza del 0,25%, lo que le ha permitido recuperar la cota de los [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1425,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1424","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-financieras"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Ibex 35 cierra su peor semana del a\u00f1o con una ca\u00edda del 3% que lo coloca en los 9.100 puntos - Super News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/super-news.info\/es\/el-ibex-35-cierra-su-peor-semana-del-ano-con-una-caida-del-3-que-lo-coloca-en-los-9-100-puntos\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Ibex 35 cierra su peor semana del a\u00f1o con una ca\u00edda del 3% que lo coloca en los 9.100 puntos - Super News\" \/>\n<meta property=\"og:description\" content=\"[ad_1] Publicado 10\/05\/2019 18:02:09CET MADRID, 10 May. (EUROPA PRESS) &#8211; El Ibex 35 ha cerrado su semana con peor comportamiento del a\u00f1o, tras experimentar una correcci\u00f3n del 3,09%. No obstante, este viernes parece haber tomado un respiro y ha concluido con un alza del 0,25%, lo que le ha permitido recuperar la cota de los [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/super-news.info\/es\/el-ibex-35-cierra-su-peor-semana-del-ano-con-una-caida-del-3-que-lo-coloca-en-los-9-100-puntos\/\" \/>\n<meta property=\"og:site_name\" content=\"Super News\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-10T16:14:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-10T16:14:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/super-news.info\/es\/wp-content\/uploads\/sites\/4\/2019\/05\/El-Ibex-35-cierra-su-peor-semana-del-a\u00f1o-con.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"120\" \/>\n\t<meta property=\"og:image:height\" content=\"80\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"super-news\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"super-news\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/el-ibex-35-cierra-su-peor-semana-del-ano-con-una-caida-del-3-que-lo-coloca-en-los-9-100-puntos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/el-ibex-35-cierra-su-peor-semana-del-ano-con-una-caida-del-3-que-lo-coloca-en-los-9-100-puntos\\\/\"},\"author\":{\"name\":\"super-news\",\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/#\\\/schema\\\/person\\\/2d4068cb2f39cd10008c2fce578a7356\"},\"headline\":\"El Ibex 35 cierra su peor semana del a\u00f1o con una ca\u00edda del 3% que lo coloca en los 9.100 puntos\",\"datePublished\":\"2019-05-10T16:14:09+00:00\",\"dateModified\":\"2019-05-10T16:14:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/el-ibex-35-cierra-su-peor-semana-del-ano-con-una-caida-del-3-que-lo-coloca-en-los-9-100-puntos\\\/\"},\"wordCount\":510,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/el-ibex-35-cierra-su-peor-semana-del-ano-con-una-caida-del-3-que-lo-coloca-en-los-9-100-puntos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/super-news.info\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2019\\\/05\\\/El-Ibex-35-cierra-su-peor-semana-del-a\u00f1o-con.jpg\",\"articleSection\":[\"NOTICIAS FINANCIERAS\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/super-news.info\\\/es\\\/el-ibex-35-cierra-su-peor-semana-del-ano-con-una-caida-del-3-que-lo-coloca-en-los-9-100-puntos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/el-ibex-35-cierra-su-peor-semana-del-ano-con-una-caida-del-3-que-lo-coloca-en-los-9-100-puntos\\\/\",\"url\":\"https:\\\/\\\/super-news.info\\\/es\\\/el-ibex-35-cierra-su-peor-semana-del-ano-con-una-caida-del-3-que-lo-coloca-en-los-9-100-puntos\\\/\",\"name\":\"El Ibex 35 cierra su peor semana del a\u00f1o con una ca\u00edda del 3% que lo coloca en los 9.100 puntos - Super News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/el-ibex-35-cierra-su-peor-semana-del-ano-con-una-caida-del-3-que-lo-coloca-en-los-9-100-puntos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/el-ibex-35-cierra-su-peor-semana-del-ano-con-una-caida-del-3-que-lo-coloca-en-los-9-100-puntos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/super-news.info\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2019\\\/05\\\/El-Ibex-35-cierra-su-peor-semana-del-a\u00f1o-con.jpg\",\"datePublished\":\"2019-05-10T16:14:09+00:00\",\"dateModified\":\"2019-05-10T16:14:10+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/#\\\/schema\\\/person\\\/2d4068cb2f39cd10008c2fce578a7356\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/el-ibex-35-cierra-su-peor-semana-del-ano-con-una-caida-del-3-que-lo-coloca-en-los-9-100-puntos\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/super-news.info\\\/es\\\/el-ibex-35-cierra-su-peor-semana-del-ano-con-una-caida-del-3-que-lo-coloca-en-los-9-100-puntos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/el-ibex-35-cierra-su-peor-semana-del-ano-con-una-caida-del-3-que-lo-coloca-en-los-9-100-puntos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/super-news.info\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2019\\\/05\\\/El-Ibex-35-cierra-su-peor-semana-del-a\u00f1o-con.jpg\",\"contentUrl\":\"https:\\\/\\\/super-news.info\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2019\\\/05\\\/El-Ibex-35-cierra-su-peor-semana-del-a\u00f1o-con.jpg\",\"width\":120,\"height\":80,\"caption\":\"El Ibex 35 cierra su peor semana del a\u00f1o con una ca\u00edda del 3% que lo coloca en los 9.100 puntos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/el-ibex-35-cierra-su-peor-semana-del-ano-con-una-caida-del-3-que-lo-coloca-en-los-9-100-puntos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430\",\"item\":\"https:\\\/\\\/super-news.info\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Ibex 35 cierra su peor semana del a\u00f1o con una ca\u00edda del 3% que lo coloca en los 9.100 puntos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/super-news.info\\\/es\\\/\",\"name\":\"Super News\",\"description\":\"Super News Espa\u00f1a\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/super-news.info\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/#\\\/schema\\\/person\\\/2d4068cb2f39cd10008c2fce578a7356\",\"name\":\"super-news\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g\",\"caption\":\"super-news\"},\"url\":\"https:\\\/\\\/super-news.info\\\/es\\\/author\\\/pt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Ibex 35 cierra su peor semana del a\u00f1o con una ca\u00edda del 3% que lo coloca en los 9.100 puntos - Super News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/super-news.info\/es\/el-ibex-35-cierra-su-peor-semana-del-ano-con-una-caida-del-3-que-lo-coloca-en-los-9-100-puntos\/","og_locale":"en_US","og_type":"article","og_title":"El Ibex 35 cierra su peor semana del a\u00f1o con una ca\u00edda del 3% que lo coloca en los 9.100 puntos - Super News","og_description":"[ad_1] Publicado 10\/05\/2019 18:02:09CET MADRID, 10 May. (EUROPA PRESS) &#8211; El Ibex 35 ha cerrado su semana con peor comportamiento del a\u00f1o, tras experimentar una correcci\u00f3n del 3,09%. No obstante, este viernes parece haber tomado un respiro y ha concluido con un alza del 0,25%, lo que le ha permitido recuperar la cota de los [&hellip;]","og_url":"https:\/\/super-news.info\/es\/el-ibex-35-cierra-su-peor-semana-del-ano-con-una-caida-del-3-que-lo-coloca-en-los-9-100-puntos\/","og_site_name":"Super News","article_published_time":"2019-05-10T16:14:09+00:00","article_modified_time":"2019-05-10T16:14:10+00:00","og_image":[{"width":120,"height":80,"url":"https:\/\/super-news.info\/es\/wp-content\/uploads\/sites\/4\/2019\/05\/El-Ibex-35-cierra-su-peor-semana-del-a\u00f1o-con.jpg","type":"image\/jpeg"}],"author":"super-news","twitter_card":"summary_large_image","twitter_misc":{"Written by":"super-news","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/super-news.info\/es\/el-ibex-35-cierra-su-peor-semana-del-ano-con-una-caida-del-3-que-lo-coloca-en-los-9-100-puntos\/#article","isPartOf":{"@id":"https:\/\/super-news.info\/es\/el-ibex-35-cierra-su-peor-semana-del-ano-con-una-caida-del-3-que-lo-coloca-en-los-9-100-puntos\/"},"author":{"name":"super-news","@id":"https:\/\/super-news.info\/es\/#\/schema\/person\/2d4068cb2f39cd10008c2fce578a7356"},"headline":"El Ibex 35 cierra su peor semana del a\u00f1o con una ca\u00edda del 3% que lo coloca en los 9.100 puntos","datePublished":"2019-05-10T16:14:09+00:00","dateModified":"2019-05-10T16:14:10+00:00","mainEntityOfPage":{"@id":"https:\/\/super-news.info\/es\/el-ibex-35-cierra-su-peor-semana-del-ano-con-una-caida-del-3-que-lo-coloca-en-los-9-100-puntos\/"},"wordCount":510,"commentCount":0,"image":{"@id":"https:\/\/super-news.info\/es\/el-ibex-35-cierra-su-peor-semana-del-ano-con-una-caida-del-3-que-lo-coloca-en-los-9-100-puntos\/#primaryimage"},"thumbnailUrl":"https:\/\/super-news.info\/es\/wp-content\/uploads\/sites\/4\/2019\/05\/El-Ibex-35-cierra-su-peor-semana-del-a\u00f1o-con.jpg","articleSection":["NOTICIAS FINANCIERAS"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/super-news.info\/es\/el-ibex-35-cierra-su-peor-semana-del-ano-con-una-caida-del-3-que-lo-coloca-en-los-9-100-puntos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/super-news.info\/es\/el-ibex-35-cierra-su-peor-semana-del-ano-con-una-caida-del-3-que-lo-coloca-en-los-9-100-puntos\/","url":"https:\/\/super-news.info\/es\/el-ibex-35-cierra-su-peor-semana-del-ano-con-una-caida-del-3-que-lo-coloca-en-los-9-100-puntos\/","name":"El Ibex 35 cierra su peor semana del a\u00f1o con una ca\u00edda del 3% que lo coloca en los 9.100 puntos - Super News","isPartOf":{"@id":"https:\/\/super-news.info\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/super-news.info\/es\/el-ibex-35-cierra-su-peor-semana-del-ano-con-una-caida-del-3-que-lo-coloca-en-los-9-100-puntos\/#primaryimage"},"image":{"@id":"https:\/\/super-news.info\/es\/el-ibex-35-cierra-su-peor-semana-del-ano-con-una-caida-del-3-que-lo-coloca-en-los-9-100-puntos\/#primaryimage"},"thumbnailUrl":"https:\/\/super-news.info\/es\/wp-content\/uploads\/sites\/4\/2019\/05\/El-Ibex-35-cierra-su-peor-semana-del-a\u00f1o-con.jpg","datePublished":"2019-05-10T16:14:09+00:00","dateModified":"2019-05-10T16:14:10+00:00","author":{"@id":"https:\/\/super-news.info\/es\/#\/schema\/person\/2d4068cb2f39cd10008c2fce578a7356"},"breadcrumb":{"@id":"https:\/\/super-news.info\/es\/el-ibex-35-cierra-su-peor-semana-del-ano-con-una-caida-del-3-que-lo-coloca-en-los-9-100-puntos\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/super-news.info\/es\/el-ibex-35-cierra-su-peor-semana-del-ano-con-una-caida-del-3-que-lo-coloca-en-los-9-100-puntos\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/super-news.info\/es\/el-ibex-35-cierra-su-peor-semana-del-ano-con-una-caida-del-3-que-lo-coloca-en-los-9-100-puntos\/#primaryimage","url":"https:\/\/super-news.info\/es\/wp-content\/uploads\/sites\/4\/2019\/05\/El-Ibex-35-cierra-su-peor-semana-del-a\u00f1o-con.jpg","contentUrl":"https:\/\/super-news.info\/es\/wp-content\/uploads\/sites\/4\/2019\/05\/El-Ibex-35-cierra-su-peor-semana-del-a\u00f1o-con.jpg","width":120,"height":80,"caption":"El Ibex 35 cierra su peor semana del a\u00f1o con una ca\u00edda del 3% que lo coloca en los 9.100 puntos"},{"@type":"BreadcrumbList","@id":"https:\/\/super-news.info\/es\/el-ibex-35-cierra-su-peor-semana-del-ano-con-una-caida-del-3-que-lo-coloca-en-los-9-100-puntos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430","item":"https:\/\/super-news.info\/es\/"},{"@type":"ListItem","position":2,"name":"El Ibex 35 cierra su peor semana del a\u00f1o con una ca\u00edda del 3% que lo coloca en los 9.100 puntos"}]},{"@type":"WebSite","@id":"https:\/\/super-news.info\/es\/#website","url":"https:\/\/super-news.info\/es\/","name":"Super News","description":"Super News Espa\u00f1a","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/super-news.info\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/super-news.info\/es\/#\/schema\/person\/2d4068cb2f39cd10008c2fce578a7356","name":"super-news","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g","caption":"super-news"},"url":"https:\/\/super-news.info\/es\/author\/pt\/"}]}},"_links":{"self":[{"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/posts\/1424","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/comments?post=1424"}],"version-history":[{"count":1,"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/posts\/1424\/revisions"}],"predecessor-version":[{"id":1426,"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/posts\/1424\/revisions\/1426"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/media\/1425"}],"wp:attachment":[{"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/media?parent=1424"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/categories?post=1424"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/tags?post=1424"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}