{"id":13497,"date":"2021-02-10T03:43:37","date_gmt":"2021-02-10T00:43:37","guid":{"rendered":"https:\/\/super-news.info\/es\/o2-lanza-su-nueva-campana-manteniendo-su-magnifico-universo-visual\/"},"modified":"2021-02-10T03:43:39","modified_gmt":"2021-02-10T00:43:39","slug":"o2-lanza-su-nueva-campana-manteniendo-su-magnifico-universo-visual","status":"publish","type":"post","link":"https:\/\/super-news.info\/es\/o2-lanza-su-nueva-campana-manteniendo-su-magnifico-universo-visual\/","title":{"rendered":"O2 lanza su nueva campa\u00f1a manteniendo su magn\u00edfico universo visual"},"content":{"rendered":"<p>Esta nueva campa\u00f1a se centra en comunicar que en O2, al contrario de lo que ocurre en otras compa\u00f1\u00edas, cuando un cliente les necesita siempre estar\u00e1n ah\u00ed para ayudarleLa empresa de telecomunicaciones O2, perteneciente a Telef\u00f3nica, acaba de lanzar su nueva campa\u00f1a bautizada como \u2018Fish: Submarino &amp; Pulpo\u2019. La campa\u00f1a mantiene el universo visual caracter\u00edstico de la compa\u00f1\u00eda y a \u2018Fish\u2019 el pez volador como protagonista, elementos diferenciales que se alejan de los c\u00f3digos de comunicaci\u00f3n propios del sector.<br \/>\nLos encargados de desarrollar esta nueva campa\u00f1a integrada -que podr\u00e1 disfrutarse en televisi\u00f3n, radio, patrocinios, digital y social media, exterior gran formato, centros comerciales y exterior digital- han sido VCCP Spain con el objetivo de reforzar la propuesta de valor diferencial de la marca, esta vez poniendo el foco en el servicio de atenci\u00f3n al cliente, con el objetivo de consolidarse como el operador n\u00famero 1 del sector en este \u00e1rea.<br \/>\n\u00abEn esta nueva campa\u00f1a de O2 seguimos construyendo la marca hacia un lado que nos gusta pero lo que es m\u00e1s importante, le gusta a la gente. Nuestro \u2018fish\u2019 sigue volando demostrando que se puede llegar m\u00e1s lejos\u00bb, ha expresado Juan Cenoz, Director Creativo de VCCP Spain.\u00a0 De este modo, la compa\u00f1\u00eda sigue incrementando la notoriedad y creciendo tanto en reconocimiento de marca como en base de clientes en el mercado espa\u00f1ol, en el cual lleva apenas m\u00e1s de 2 a\u00f1os.<br \/>\nEsta nueva campa\u00f1a se centra en comunicar que en O2, al contrario de lo que ocurre en otras compa\u00f1\u00edas, cuando un cliente les necesita siempre estar\u00e1n ah\u00ed para ayudarle. Y eso lo hace de una forma sencilla y transparente, con un centro de atenci\u00f3n formado por un equipo de personas que responden \u2018desde el primer tono\u2019 a sus clientes, sin utilizar m\u00e1quinas enrutadores de tr\u00e1fico y con agentes cuyo objetivo es resolver la duda, gesti\u00f3n o el problema del cliente en una \u00fanica llamada.<br \/>\n\u00abEstamos muy contentos con la evoluci\u00f3n creativa de la campa\u00f1a. VCCP consigui\u00f3 crear a trav\u00e9s de fish un mundo muy notorio, con muchos recursos, para comunicar una propuesta diferencial centrada en el cliente. Nuestras campa\u00f1as chocan totalmente con la comunicaci\u00f3n de la competencia, que intenta reducir el servicio a una decisi\u00f3n de precio. As\u00ed que fish en este sentido tambi\u00e9n va contra corriente, y vuela, igual que muchas personas que quieren un servicio de comunicaciones en un equilibrio justo de calidad de servicio, atenci\u00f3n y precio. Y eso es O2\u2033, ha declarado Gema Perona, responsable de marketing y comunicaci\u00f3n de O2.<\/p>\n<p>Si no ve correctamente el v\u00eddeo embedded, haga clic aqu\u00ed<br \/>\nFICHA T\u00c9CNICA<\/p>\n<p>Cliente: O2<br \/>\nResponsable Cliente: Gema Perona, Fernando Mart\u00edn, Eva Soto y Juan Jos\u00e9 Mu\u00f1oz.<br \/>\nCEO: Javier Suso<br \/>\nDirector Creativo Ejecutivo: Beto Nahmad<br \/>\nDirector Creativo: Juan Cenoz<br \/>\nCopywriters Seniors: Gabri Fern\u00e1ndez \/ Javi Barreiro<br \/>\nDirectores de Arte Seniors: Jezabel Gonz\u00e1lez \/ Nacho Ara\u00fajo<br \/>\nDirectora de Servicios al Cliente: Eliana Cantonati<br \/>\nDirector de Cuentas: Daniel Crespo<br \/>\nSr. Account Executive: Ylenia Gavela<br \/>\nStrategy Director: \u00c1lvaro Ojeda<br \/>\nHead of Digital: Luis Alberto L\u00f3pez<br \/>\nProducer: Carlos Fern\u00e1ndez-Elipe<br \/>\nProducci\u00f3n: The Frank Barton Company<br \/>\nDirecci\u00f3n: \u00darsula Garc\u00eda y Sergio G. Abad<br \/>\nEstudio de Postproducci\u00f3n: Telson<br \/>\nEstudio de Sonido: Telson<br \/>\nM\u00fasica: Neuman \u2013 The City of Love<\/p>\n<p>No te pierdas nada de MarketingDirecto.com y \u00fanete a nuestro Telegram t.me\/MarketingDirecto<\/p>\n<p>\n<!--noindex--><br \/>\n<a href=\"https:\/\/www.marketingdirecto.com\/marketing-general\/publicidad\/o2-lanza-nueva-campana-manteniendo-universo-visual\" rel=\"nofollow\">Source link <\/a><br \/>\n<!--\/noindex--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta nueva campa\u00f1a se centra en comunicar que en O2, al contrario de lo que ocurre en otras compa\u00f1\u00edas, cuando un cliente les necesita siempre estar\u00e1n ah\u00ed para ayudarleLa empresa de telecomunicaciones O2, perteneciente a Telef\u00f3nica, acaba de lanzar su nueva campa\u00f1a bautizada como \u2018Fish: Submarino &amp; Pulpo\u2019. La campa\u00f1a mantiene el universo visual caracter\u00edstico [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":13498,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-13497","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-marketing-digital"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>O2 lanza su nueva campa\u00f1a manteniendo su magn\u00edfico universo visual - Super News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/super-news.info\/es\/o2-lanza-su-nueva-campana-manteniendo-su-magnifico-universo-visual\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O2 lanza su nueva campa\u00f1a manteniendo su magn\u00edfico universo visual - Super News\" \/>\n<meta property=\"og:description\" content=\"Esta nueva campa\u00f1a se centra en comunicar que en O2, al contrario de lo que ocurre en otras compa\u00f1\u00edas, cuando un cliente les necesita siempre estar\u00e1n ah\u00ed para ayudarleLa empresa de telecomunicaciones O2, perteneciente a Telef\u00f3nica, acaba de lanzar su nueva campa\u00f1a bautizada como \u2018Fish: Submarino &amp; Pulpo\u2019. La campa\u00f1a mantiene el universo visual caracter\u00edstico [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/super-news.info\/es\/o2-lanza-su-nueva-campana-manteniendo-su-magnifico-universo-visual\/\" \/>\n<meta property=\"og:site_name\" content=\"Super News\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-10T00:43:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-10T00:43:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/super-news.info\/es\/wp-content\/uploads\/sites\/4\/2021\/02\/O2-lanza-su-nueva-campa-a-manteniendo-su-magn-fico-universo-visual.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"626\" \/>\n\t<meta property=\"og:image:height\" content=\"361\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"super-news\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"super-news\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/o2-lanza-su-nueva-campana-manteniendo-su-magnifico-universo-visual\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/o2-lanza-su-nueva-campana-manteniendo-su-magnifico-universo-visual\\\/\"},\"author\":{\"name\":\"super-news\",\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/#\\\/schema\\\/person\\\/2d4068cb2f39cd10008c2fce578a7356\"},\"headline\":\"O2 lanza su nueva campa\u00f1a manteniendo su magn\u00edfico universo visual\",\"datePublished\":\"2021-02-10T00:43:37+00:00\",\"dateModified\":\"2021-02-10T00:43:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/o2-lanza-su-nueva-campana-manteniendo-su-magnifico-universo-visual\\\/\"},\"wordCount\":602,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/o2-lanza-su-nueva-campana-manteniendo-su-magnifico-universo-visual\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/super-news.info\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/02\\\/O2-lanza-su-nueva-campa-a-manteniendo-su-magn-fico-universo-visual.jpg\",\"articleSection\":[\"NOTICIAS DE MARKETING DIGITAL\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/super-news.info\\\/es\\\/o2-lanza-su-nueva-campana-manteniendo-su-magnifico-universo-visual\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/o2-lanza-su-nueva-campana-manteniendo-su-magnifico-universo-visual\\\/\",\"url\":\"https:\\\/\\\/super-news.info\\\/es\\\/o2-lanza-su-nueva-campana-manteniendo-su-magnifico-universo-visual\\\/\",\"name\":\"O2 lanza su nueva campa\u00f1a manteniendo su magn\u00edfico universo visual - Super News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/o2-lanza-su-nueva-campana-manteniendo-su-magnifico-universo-visual\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/o2-lanza-su-nueva-campana-manteniendo-su-magnifico-universo-visual\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/super-news.info\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/02\\\/O2-lanza-su-nueva-campa-a-manteniendo-su-magn-fico-universo-visual.jpg\",\"datePublished\":\"2021-02-10T00:43:37+00:00\",\"dateModified\":\"2021-02-10T00:43:39+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/#\\\/schema\\\/person\\\/2d4068cb2f39cd10008c2fce578a7356\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/o2-lanza-su-nueva-campana-manteniendo-su-magnifico-universo-visual\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/super-news.info\\\/es\\\/o2-lanza-su-nueva-campana-manteniendo-su-magnifico-universo-visual\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/o2-lanza-su-nueva-campana-manteniendo-su-magnifico-universo-visual\\\/#primaryimage\",\"url\":\"https:\\\/\\\/super-news.info\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/02\\\/O2-lanza-su-nueva-campa-a-manteniendo-su-magn-fico-universo-visual.jpg\",\"contentUrl\":\"https:\\\/\\\/super-news.info\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/02\\\/O2-lanza-su-nueva-campa-a-manteniendo-su-magn-fico-universo-visual.jpg\",\"width\":626,\"height\":361,\"caption\":\"O2 lanza su nueva campa\u00f1a manteniendo su magn\u00edfico universo visual\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/o2-lanza-su-nueva-campana-manteniendo-su-magnifico-universo-visual\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430\",\"item\":\"https:\\\/\\\/super-news.info\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"O2 lanza su nueva campa\u00f1a manteniendo su magn\u00edfico universo visual\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/super-news.info\\\/es\\\/\",\"name\":\"Super News\",\"description\":\"Super News Espa\u00f1a\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/super-news.info\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/#\\\/schema\\\/person\\\/2d4068cb2f39cd10008c2fce578a7356\",\"name\":\"super-news\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g\",\"caption\":\"super-news\"},\"url\":\"https:\\\/\\\/super-news.info\\\/es\\\/author\\\/pt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O2 lanza su nueva campa\u00f1a manteniendo su magn\u00edfico universo visual - Super News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/super-news.info\/es\/o2-lanza-su-nueva-campana-manteniendo-su-magnifico-universo-visual\/","og_locale":"en_US","og_type":"article","og_title":"O2 lanza su nueva campa\u00f1a manteniendo su magn\u00edfico universo visual - Super News","og_description":"Esta nueva campa\u00f1a se centra en comunicar que en O2, al contrario de lo que ocurre en otras compa\u00f1\u00edas, cuando un cliente les necesita siempre estar\u00e1n ah\u00ed para ayudarleLa empresa de telecomunicaciones O2, perteneciente a Telef\u00f3nica, acaba de lanzar su nueva campa\u00f1a bautizada como \u2018Fish: Submarino &amp; Pulpo\u2019. La campa\u00f1a mantiene el universo visual caracter\u00edstico [&hellip;]","og_url":"https:\/\/super-news.info\/es\/o2-lanza-su-nueva-campana-manteniendo-su-magnifico-universo-visual\/","og_site_name":"Super News","article_published_time":"2021-02-10T00:43:37+00:00","article_modified_time":"2021-02-10T00:43:39+00:00","og_image":[{"width":626,"height":361,"url":"https:\/\/super-news.info\/es\/wp-content\/uploads\/sites\/4\/2021\/02\/O2-lanza-su-nueva-campa-a-manteniendo-su-magn-fico-universo-visual.jpg","type":"image\/jpeg"}],"author":"super-news","twitter_card":"summary_large_image","twitter_misc":{"Written by":"super-news","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/super-news.info\/es\/o2-lanza-su-nueva-campana-manteniendo-su-magnifico-universo-visual\/#article","isPartOf":{"@id":"https:\/\/super-news.info\/es\/o2-lanza-su-nueva-campana-manteniendo-su-magnifico-universo-visual\/"},"author":{"name":"super-news","@id":"https:\/\/super-news.info\/es\/#\/schema\/person\/2d4068cb2f39cd10008c2fce578a7356"},"headline":"O2 lanza su nueva campa\u00f1a manteniendo su magn\u00edfico universo visual","datePublished":"2021-02-10T00:43:37+00:00","dateModified":"2021-02-10T00:43:39+00:00","mainEntityOfPage":{"@id":"https:\/\/super-news.info\/es\/o2-lanza-su-nueva-campana-manteniendo-su-magnifico-universo-visual\/"},"wordCount":602,"commentCount":0,"image":{"@id":"https:\/\/super-news.info\/es\/o2-lanza-su-nueva-campana-manteniendo-su-magnifico-universo-visual\/#primaryimage"},"thumbnailUrl":"https:\/\/super-news.info\/es\/wp-content\/uploads\/sites\/4\/2021\/02\/O2-lanza-su-nueva-campa-a-manteniendo-su-magn-fico-universo-visual.jpg","articleSection":["NOTICIAS DE MARKETING DIGITAL"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/super-news.info\/es\/o2-lanza-su-nueva-campana-manteniendo-su-magnifico-universo-visual\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/super-news.info\/es\/o2-lanza-su-nueva-campana-manteniendo-su-magnifico-universo-visual\/","url":"https:\/\/super-news.info\/es\/o2-lanza-su-nueva-campana-manteniendo-su-magnifico-universo-visual\/","name":"O2 lanza su nueva campa\u00f1a manteniendo su magn\u00edfico universo visual - Super News","isPartOf":{"@id":"https:\/\/super-news.info\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/super-news.info\/es\/o2-lanza-su-nueva-campana-manteniendo-su-magnifico-universo-visual\/#primaryimage"},"image":{"@id":"https:\/\/super-news.info\/es\/o2-lanza-su-nueva-campana-manteniendo-su-magnifico-universo-visual\/#primaryimage"},"thumbnailUrl":"https:\/\/super-news.info\/es\/wp-content\/uploads\/sites\/4\/2021\/02\/O2-lanza-su-nueva-campa-a-manteniendo-su-magn-fico-universo-visual.jpg","datePublished":"2021-02-10T00:43:37+00:00","dateModified":"2021-02-10T00:43:39+00:00","author":{"@id":"https:\/\/super-news.info\/es\/#\/schema\/person\/2d4068cb2f39cd10008c2fce578a7356"},"breadcrumb":{"@id":"https:\/\/super-news.info\/es\/o2-lanza-su-nueva-campana-manteniendo-su-magnifico-universo-visual\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/super-news.info\/es\/o2-lanza-su-nueva-campana-manteniendo-su-magnifico-universo-visual\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/super-news.info\/es\/o2-lanza-su-nueva-campana-manteniendo-su-magnifico-universo-visual\/#primaryimage","url":"https:\/\/super-news.info\/es\/wp-content\/uploads\/sites\/4\/2021\/02\/O2-lanza-su-nueva-campa-a-manteniendo-su-magn-fico-universo-visual.jpg","contentUrl":"https:\/\/super-news.info\/es\/wp-content\/uploads\/sites\/4\/2021\/02\/O2-lanza-su-nueva-campa-a-manteniendo-su-magn-fico-universo-visual.jpg","width":626,"height":361,"caption":"O2 lanza su nueva campa\u00f1a manteniendo su magn\u00edfico universo visual"},{"@type":"BreadcrumbList","@id":"https:\/\/super-news.info\/es\/o2-lanza-su-nueva-campana-manteniendo-su-magnifico-universo-visual\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430","item":"https:\/\/super-news.info\/es\/"},{"@type":"ListItem","position":2,"name":"O2 lanza su nueva campa\u00f1a manteniendo su magn\u00edfico universo visual"}]},{"@type":"WebSite","@id":"https:\/\/super-news.info\/es\/#website","url":"https:\/\/super-news.info\/es\/","name":"Super News","description":"Super News Espa\u00f1a","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/super-news.info\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/super-news.info\/es\/#\/schema\/person\/2d4068cb2f39cd10008c2fce578a7356","name":"super-news","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g","caption":"super-news"},"url":"https:\/\/super-news.info\/es\/author\/pt\/"}]}},"_links":{"self":[{"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/posts\/13497","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/comments?post=13497"}],"version-history":[{"count":1,"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/posts\/13497\/revisions"}],"predecessor-version":[{"id":13499,"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/posts\/13497\/revisions\/13499"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/media\/13498"}],"wp:attachment":[{"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/media?parent=13497"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/categories?post=13497"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/tags?post=13497"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}