{"id":10536,"date":"2019-09-07T14:31:11","date_gmt":"2019-09-07T11:31:11","guid":{"rendered":"https:\/\/super-news.info\/es\/la-estrella-de-instagram-celeste-barber-protagoniza-la-nueva-campana-de-klarna\/"},"modified":"2019-09-07T14:31:12","modified_gmt":"2019-09-07T11:31:12","slug":"la-estrella-de-instagram-celeste-barber-protagoniza-la-nueva-campana-de-klarna","status":"publish","type":"post","link":"https:\/\/super-news.info\/es\/la-estrella-de-instagram-celeste-barber-protagoniza-la-nueva-campana-de-klarna\/","title":{"rendered":"La estrella de Instagram Celeste Barber protagoniza la nueva campa\u00f1a de Klarna"},"content":{"rendered":"<div id=\"textoNoticia\">\n<p class=\"excerpt-single\">El servicio sueco de compras digitales &#8220;Buy Now and Pay Later&#8221; ficha a Celeste Barber para dar voz a las desastrosas compras online en un show de tres episodios.<\/p>\n<\/p>\n<p><strong>Klarna<\/strong>, el banco sueco especializado en servicios de pago online, ha confiado a la agencia <strong>72andSunny Amsterdam<\/strong> su \u00faltima campa\u00f1a de marca internacional. Un proyecto que ha visto la luz bajo el nombre &#8220;<strong>Ojal\u00e1 lo hubiera comprado con Klarna<\/strong>&#8220;, una serie de 3 episodios protagonizados por Celeste Barber, la actriz y estrella de Instagram famosa por parodiar en la red social todo tipo de fotograf\u00edas imposibles subidas por los famosos.<\/p>\n<p>Cada una de las piezas de esta<strong> mini serie<\/strong> presenta una c\u00f3mica y enrevesada situaci\u00f3n motivada por una compra online. Eso s\u00ed acompa\u00f1ada por una puesta en escena de lo m\u00e1s glamurosa y m\u00e1s irreal, si cabe, que las fotos de los famosos a los que imita Barber en su cuenta de Instagram. Un estilo que impera tambi\u00e9n en los dise\u00f1os y creatividades de la compa\u00f1\u00eda. As\u00ed, la presentadora del show expone tres desastrosos casos que tienen que ver con un alisador de pelo, unos diminutos muebles de jard\u00edn y un vestido de novia demasiado transparente. \u00bfLa moraleja? Paga siempre con Klarna.<\/p>\n<p>\n\t\t\t\t<iframe loading=\"lazy\" src=\"http:\/\/www.youtube.com\/embed\/dL3kowOafkg?enablejsapi=1&amp;version=3&amp;rel=0&amp;showinfo=0&amp;controls=0\" id=\"iframePlayer\" width=\"940\" height=\"529\" frameborder=\"0\" webkitallowfullscreen=\"\" mozallowfullscreen=\"\" allowfullscreen=\"\"><\/iframe>\n\t\t\t<\/p>\n<p>Si no visualiza correctamente el v\u00eddeo embedded, haga clic aqu\u00ed.<\/p>\n<p>La original y vistosa campa\u00f1a promueve los <strong>beneficios de la experiencia de compra<\/strong> exenta de problemas que ofrece Klarna, incluida la facilidad de pago, un excelente servicio al cliente y una pol\u00edtica de protecci\u00f3n del comprador, con el objetivo de fomentar las compras inteligentes y empoderar a los usuarios, al mismo tiempo que destaca la seguridad proporcionada por la aplicaci\u00f3n Klarna Pay.<\/p>\n<p>Los <strong>episodios de 60 segundos<\/strong>, y sus versiones reducidas y en formato GIF, se podr\u00e1n ver en las redes sociales de Klarna y Celeste Barber y en medios de pago en pa\u00edses como Estados Unidos, Reino Unido, Pa\u00edses Bajos, Alemania y Suecia. Adem\u00e1s, la compa\u00f1\u00eda se ha asociado con la p\u00e1gina web estadounidense de moda <strong>Refinery29<\/strong> para aumentar el impacto cultural de la campa\u00f1a.<\/p>\n<p>\n\t\t\t\t<iframe loading=\"lazy\" src=\"http:\/\/www.youtube.com\/embed\/GbJYmA-ejlw?enablejsapi=1&amp;version=3&amp;rel=0&amp;showinfo=0&amp;controls=0\" id=\"iframePlayer\" width=\"940\" height=\"529\" frameborder=\"0\" webkitallowfullscreen=\"\" mozallowfullscreen=\"\" allowfullscreen=\"\"><\/iframe>\n\t\t\t<\/p>\n<p>Si no visualiza correctamente el v\u00eddeo embedded, haga clic aqu\u00ed.<\/p>\n<p>&#8220;Klarna se enorgullece de ser innovador y fluido, y nuestra campa\u00f1a con Celeste Barber no podr\u00eda ser una colaboraci\u00f3n m\u00e1s perfecta para presentar el empoderamiento de los pagos y la <strong>conveniencia de nuestros productos &#8216;Pay Later&#8217; para los consumidores<\/strong>. Celeste capta brillantemente el mensaje de &#8216;Pay Later&#8217; y demuestra de manera juguetona c\u00f3mo utilizar\u00a0Klarna puede ayudar a cualquier usuario a comprar con confianza. Es divertido, peculiar, pero sobre todo nos hace sonre\u00edr, y estamos emocionados de ver c\u00f3mo esto se hace eco entre los consumidores&#8221;, ha declarado David Sandstrom, director de marketing de Klarna.<\/p>\n<p>Sarah Hardcastle y Ren\u00e9e Lam, equipo creativo de 72andSunny Amsterdam, han explicado: &#8220;Pagar despu\u00e9s con Klarna es un gran alivio para cualquier comprador que haya sentido el aguij\u00f3n de una compra online que no cumple con sus expectativas. Como la reina de la realidad en Instagram, <strong>Celeste es la compa\u00f1era perfecta<\/strong> para transmitir nuestro mensaje con su hilarante sinceridad&#8221;.<\/p>\n<p>\n\t\t\t\t<iframe loading=\"lazy\" src=\"http:\/\/www.youtube.com\/embed\/7ywXYGufU90?enablejsapi=1&amp;version=3&amp;rel=0&amp;showinfo=0&amp;controls=0\" id=\"iframePlayer\" width=\"940\" height=\"529\" frameborder=\"0\" webkitallowfullscreen=\"\" mozallowfullscreen=\"\" allowfullscreen=\"\"><\/iframe>\n\t\t\t<\/p>\n<p>Si no visualiza correctamente el v\u00eddeo embedded, haga clic aqu\u00ed.<\/p>\n<p><strong>Ficha t\u00e9cnica:<\/strong><\/p>\n<p>Client: Klarna<br \/>Creative Agency: 72andSunny Amsterdam<br \/>Director: Alyssa McClelland<br \/>Production Company: Anonymous Content<br \/>Editorial Company: The Quarry<br \/>Post\/VFX Company: Glassworks Amsterdam<br \/>Sound Design Company: Stainless Sound<\/p>\n<p class=\"link-telegram\">\n\t\t\t\t\t\t\t\t\t\t\tNo te pierdas nada de MarketingDirecto.com y \u00fanete a nuestro Telegram t.me\/MarketingDirecto\n\t\t\t\t\t\t\t\t\t\t<\/p>\n<\/p><\/div>\n<p><script>(function(d, s, id) {\n  var js, fjs = d.getElementsByTagName(s)[0];\n  if (d.getElementById(id)) return;\n  js = d.createElement(s); js.id = id;\n  js.src = \"http:\/\/connect.facebook.net\/es_LA\/sdk.js#xfbml=1&appId=408746052611679&version=v2.3\";\n  fjs.parentNode.insertBefore(js, fjs);\n}(document, 'script', 'facebook-jssdk'));<\/script><script async defer src=\"https:\/\/platform.instagram.com\/en_US\/embeds.js\"><\/script><br \/>\n<br \/>\n<!--noindex--><br \/>\n<a href=\"https:\/\/www.marketingdirecto.com\/marketing-general\/publicidad\/la-estrella-de-instagram-celeste-barber-protagoniza-la-nueva-campana-de-klarna\" rel=\"nofollow\">Source link <\/a><br \/>\n<!--\/noindex--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El servicio sueco de compras digitales &#8220;Buy Now and Pay Later&#8221; ficha a Celeste Barber para dar voz a las desastrosas compras online en un show de tres episodios. Klarna, el banco sueco especializado en servicios de pago online, ha confiado a la agencia 72andSunny Amsterdam su \u00faltima campa\u00f1a de marca internacional. Un proyecto que [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":10537,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-10536","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-marketing-digital"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La estrella de Instagram Celeste Barber protagoniza la nueva campa\u00f1a de Klarna - Super News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/super-news.info\/es\/la-estrella-de-instagram-celeste-barber-protagoniza-la-nueva-campana-de-klarna\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La estrella de Instagram Celeste Barber protagoniza la nueva campa\u00f1a de Klarna - Super News\" \/>\n<meta property=\"og:description\" content=\"El servicio sueco de compras digitales &#8220;Buy Now and Pay Later&#8221; ficha a Celeste Barber para dar voz a las desastrosas compras online en un show de tres episodios. Klarna, el banco sueco especializado en servicios de pago online, ha confiado a la agencia 72andSunny Amsterdam su \u00faltima campa\u00f1a de marca internacional. Un proyecto que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/super-news.info\/es\/la-estrella-de-instagram-celeste-barber-protagoniza-la-nueva-campana-de-klarna\/\" \/>\n<meta property=\"og:site_name\" content=\"Super News\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-07T11:31:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-09-07T11:31:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/super-news.info\/es\/wp-content\/uploads\/sites\/4\/2019\/09\/La-estrella-de-Instagram-Celeste-Barber-protagoniza-la-nueva-campa-a.png\" \/>\n\t<meta property=\"og:image:width\" content=\"626\" \/>\n\t<meta property=\"og:image:height\" content=\"364\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"super-news\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"super-news\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/la-estrella-de-instagram-celeste-barber-protagoniza-la-nueva-campana-de-klarna\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/la-estrella-de-instagram-celeste-barber-protagoniza-la-nueva-campana-de-klarna\\\/\"},\"author\":{\"name\":\"super-news\",\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/#\\\/schema\\\/person\\\/2d4068cb2f39cd10008c2fce578a7356\"},\"headline\":\"La estrella de Instagram Celeste Barber protagoniza la nueva campa\u00f1a de Klarna\",\"datePublished\":\"2019-09-07T11:31:11+00:00\",\"dateModified\":\"2019-09-07T11:31:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/la-estrella-de-instagram-celeste-barber-protagoniza-la-nueva-campana-de-klarna\\\/\"},\"wordCount\":599,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/la-estrella-de-instagram-celeste-barber-protagoniza-la-nueva-campana-de-klarna\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/super-news.info\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2019\\\/09\\\/La-estrella-de-Instagram-Celeste-Barber-protagoniza-la-nueva-campa-a.png\",\"articleSection\":[\"NOTICIAS DE MARKETING DIGITAL\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/super-news.info\\\/es\\\/la-estrella-de-instagram-celeste-barber-protagoniza-la-nueva-campana-de-klarna\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/la-estrella-de-instagram-celeste-barber-protagoniza-la-nueva-campana-de-klarna\\\/\",\"url\":\"https:\\\/\\\/super-news.info\\\/es\\\/la-estrella-de-instagram-celeste-barber-protagoniza-la-nueva-campana-de-klarna\\\/\",\"name\":\"La estrella de Instagram Celeste Barber protagoniza la nueva campa\u00f1a de Klarna - Super News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/la-estrella-de-instagram-celeste-barber-protagoniza-la-nueva-campana-de-klarna\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/la-estrella-de-instagram-celeste-barber-protagoniza-la-nueva-campana-de-klarna\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/super-news.info\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2019\\\/09\\\/La-estrella-de-Instagram-Celeste-Barber-protagoniza-la-nueva-campa-a.png\",\"datePublished\":\"2019-09-07T11:31:11+00:00\",\"dateModified\":\"2019-09-07T11:31:12+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/#\\\/schema\\\/person\\\/2d4068cb2f39cd10008c2fce578a7356\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/la-estrella-de-instagram-celeste-barber-protagoniza-la-nueva-campana-de-klarna\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/super-news.info\\\/es\\\/la-estrella-de-instagram-celeste-barber-protagoniza-la-nueva-campana-de-klarna\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/la-estrella-de-instagram-celeste-barber-protagoniza-la-nueva-campana-de-klarna\\\/#primaryimage\",\"url\":\"https:\\\/\\\/super-news.info\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2019\\\/09\\\/La-estrella-de-Instagram-Celeste-Barber-protagoniza-la-nueva-campa-a.png\",\"contentUrl\":\"https:\\\/\\\/super-news.info\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2019\\\/09\\\/La-estrella-de-Instagram-Celeste-Barber-protagoniza-la-nueva-campa-a.png\",\"width\":626,\"height\":364,\"caption\":\"Klarna\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/la-estrella-de-instagram-celeste-barber-protagoniza-la-nueva-campana-de-klarna\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430\",\"item\":\"https:\\\/\\\/super-news.info\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La estrella de Instagram Celeste Barber protagoniza la nueva campa\u00f1a de Klarna\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/super-news.info\\\/es\\\/\",\"name\":\"Super News\",\"description\":\"Super News Espa\u00f1a\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/super-news.info\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/super-news.info\\\/es\\\/#\\\/schema\\\/person\\\/2d4068cb2f39cd10008c2fce578a7356\",\"name\":\"super-news\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g\",\"caption\":\"super-news\"},\"url\":\"https:\\\/\\\/super-news.info\\\/es\\\/author\\\/pt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La estrella de Instagram Celeste Barber protagoniza la nueva campa\u00f1a de Klarna - Super News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/super-news.info\/es\/la-estrella-de-instagram-celeste-barber-protagoniza-la-nueva-campana-de-klarna\/","og_locale":"en_US","og_type":"article","og_title":"La estrella de Instagram Celeste Barber protagoniza la nueva campa\u00f1a de Klarna - Super News","og_description":"El servicio sueco de compras digitales &#8220;Buy Now and Pay Later&#8221; ficha a Celeste Barber para dar voz a las desastrosas compras online en un show de tres episodios. Klarna, el banco sueco especializado en servicios de pago online, ha confiado a la agencia 72andSunny Amsterdam su \u00faltima campa\u00f1a de marca internacional. Un proyecto que [&hellip;]","og_url":"https:\/\/super-news.info\/es\/la-estrella-de-instagram-celeste-barber-protagoniza-la-nueva-campana-de-klarna\/","og_site_name":"Super News","article_published_time":"2019-09-07T11:31:11+00:00","article_modified_time":"2019-09-07T11:31:12+00:00","og_image":[{"width":626,"height":364,"url":"https:\/\/super-news.info\/es\/wp-content\/uploads\/sites\/4\/2019\/09\/La-estrella-de-Instagram-Celeste-Barber-protagoniza-la-nueva-campa-a.png","type":"image\/png"}],"author":"super-news","twitter_card":"summary_large_image","twitter_misc":{"Written by":"super-news","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/super-news.info\/es\/la-estrella-de-instagram-celeste-barber-protagoniza-la-nueva-campana-de-klarna\/#article","isPartOf":{"@id":"https:\/\/super-news.info\/es\/la-estrella-de-instagram-celeste-barber-protagoniza-la-nueva-campana-de-klarna\/"},"author":{"name":"super-news","@id":"https:\/\/super-news.info\/es\/#\/schema\/person\/2d4068cb2f39cd10008c2fce578a7356"},"headline":"La estrella de Instagram Celeste Barber protagoniza la nueva campa\u00f1a de Klarna","datePublished":"2019-09-07T11:31:11+00:00","dateModified":"2019-09-07T11:31:12+00:00","mainEntityOfPage":{"@id":"https:\/\/super-news.info\/es\/la-estrella-de-instagram-celeste-barber-protagoniza-la-nueva-campana-de-klarna\/"},"wordCount":599,"commentCount":0,"image":{"@id":"https:\/\/super-news.info\/es\/la-estrella-de-instagram-celeste-barber-protagoniza-la-nueva-campana-de-klarna\/#primaryimage"},"thumbnailUrl":"https:\/\/super-news.info\/es\/wp-content\/uploads\/sites\/4\/2019\/09\/La-estrella-de-Instagram-Celeste-Barber-protagoniza-la-nueva-campa-a.png","articleSection":["NOTICIAS DE MARKETING DIGITAL"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/super-news.info\/es\/la-estrella-de-instagram-celeste-barber-protagoniza-la-nueva-campana-de-klarna\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/super-news.info\/es\/la-estrella-de-instagram-celeste-barber-protagoniza-la-nueva-campana-de-klarna\/","url":"https:\/\/super-news.info\/es\/la-estrella-de-instagram-celeste-barber-protagoniza-la-nueva-campana-de-klarna\/","name":"La estrella de Instagram Celeste Barber protagoniza la nueva campa\u00f1a de Klarna - Super News","isPartOf":{"@id":"https:\/\/super-news.info\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/super-news.info\/es\/la-estrella-de-instagram-celeste-barber-protagoniza-la-nueva-campana-de-klarna\/#primaryimage"},"image":{"@id":"https:\/\/super-news.info\/es\/la-estrella-de-instagram-celeste-barber-protagoniza-la-nueva-campana-de-klarna\/#primaryimage"},"thumbnailUrl":"https:\/\/super-news.info\/es\/wp-content\/uploads\/sites\/4\/2019\/09\/La-estrella-de-Instagram-Celeste-Barber-protagoniza-la-nueva-campa-a.png","datePublished":"2019-09-07T11:31:11+00:00","dateModified":"2019-09-07T11:31:12+00:00","author":{"@id":"https:\/\/super-news.info\/es\/#\/schema\/person\/2d4068cb2f39cd10008c2fce578a7356"},"breadcrumb":{"@id":"https:\/\/super-news.info\/es\/la-estrella-de-instagram-celeste-barber-protagoniza-la-nueva-campana-de-klarna\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/super-news.info\/es\/la-estrella-de-instagram-celeste-barber-protagoniza-la-nueva-campana-de-klarna\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/super-news.info\/es\/la-estrella-de-instagram-celeste-barber-protagoniza-la-nueva-campana-de-klarna\/#primaryimage","url":"https:\/\/super-news.info\/es\/wp-content\/uploads\/sites\/4\/2019\/09\/La-estrella-de-Instagram-Celeste-Barber-protagoniza-la-nueva-campa-a.png","contentUrl":"https:\/\/super-news.info\/es\/wp-content\/uploads\/sites\/4\/2019\/09\/La-estrella-de-Instagram-Celeste-Barber-protagoniza-la-nueva-campa-a.png","width":626,"height":364,"caption":"Klarna"},{"@type":"BreadcrumbList","@id":"https:\/\/super-news.info\/es\/la-estrella-de-instagram-celeste-barber-protagoniza-la-nueva-campana-de-klarna\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430","item":"https:\/\/super-news.info\/es\/"},{"@type":"ListItem","position":2,"name":"La estrella de Instagram Celeste Barber protagoniza la nueva campa\u00f1a de Klarna"}]},{"@type":"WebSite","@id":"https:\/\/super-news.info\/es\/#website","url":"https:\/\/super-news.info\/es\/","name":"Super News","description":"Super News Espa\u00f1a","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/super-news.info\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/super-news.info\/es\/#\/schema\/person\/2d4068cb2f39cd10008c2fce578a7356","name":"super-news","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/64ebac40b93f26a154f8a9b5b6fdccfc46f442b26b3dd6756dbff3bf9dc76fd7?s=96&d=mm&r=g","caption":"super-news"},"url":"https:\/\/super-news.info\/es\/author\/pt\/"}]}},"_links":{"self":[{"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/posts\/10536","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/comments?post=10536"}],"version-history":[{"count":1,"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/posts\/10536\/revisions"}],"predecessor-version":[{"id":10538,"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/posts\/10536\/revisions\/10538"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/media\/10537"}],"wp:attachment":[{"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/media?parent=10536"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/categories?post=10536"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/super-news.info\/es\/wp-json\/wp\/v2\/tags?post=10536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}