{"id":2053,"date":"2021-07-22T18:30:50","date_gmt":"2021-07-22T18:30:50","guid":{"rendered":"https:\/\/super-news.info\/de\/dr-oetker-wird-aufgesplittet-absatzwirtschaft\/"},"modified":"2021-07-22T18:30:52","modified_gmt":"2021-07-22T18:30:52","slug":"dr-oetker-wird-aufgesplittet-absatzwirtschaft","status":"publish","type":"post","link":"https:\/\/super-news.info\/de\/dr-oetker-wird-aufgesplittet-absatzwirtschaft\/","title":{"rendered":"Dr. Oetker wird aufgesplittet \u203a absatzwirtschaft"},"content":{"rendered":"<p>\t\t\t\t\t\tSeit Jahren gibt es Ger\u00fcchte um eine Aufsplittung, Streitereien unter den Erben von Rudolf-August Oetker sind kein Geheimnis. Jetzt ist es amtlich. Das Unternehmen wird aufgeteilt.<\/p>\n<p>\t\t\t\t\tNach einem jahrzehntelangen Streit um die Ausrichtung von Dr. Oetker wird der Konzern aufgespalten. Das teilte das Unternehmen am Donnerstag in Bielefeld mit. Die Gesellschafter Alfred, Carl Ferdinand und Julia Johanna Oetker \u00fcbernehmen unter einem gemeinsamen Dach unteren anderen die T\u00f6chter Henkell &amp; Co. Sektkellerei, die Martin Braun Backmittel KG, die Chemiefabrik Budenheim, einige H\u00e4user aus der Hotelsparte sowie die Kunstsammlung August Oetker.<\/p>\n<p>\u201cMit dieser Entscheidung \u00fcberwinden die Gesellschaftergruppen ihre unterschiedlichen Vorstellungen zur F\u00fchrung und Strategie der Oetker-Gruppe. Eine entsprechende Trennungsvereinbarung ist von allen Eigent\u00fcmern unterzeichnet worden\u201d, hei\u00dft es in einer offiziellen Mitteilung der Oetker-Gruppe.<\/p>\n<p>Trennung von Dr. Oetker noch 2021<\/p>\n<p>Die Trennungsvereinbarung soll noch in diesem Jahr vollzogen werden. \u201cDie Entscheidung hat keine Auswirkungen f\u00fcr die Mitarbeiter in den einzelnen Unternehmen der Oetker-Gruppe\u201d, hei\u00dft es in der Mitteilung. Zum Zeitraum der Gespr\u00e4che unter den Beteiligten wollten sich beide Seiten nicht \u00e4u\u00dfern. \u201cSeit geraumer Zeit wurde verhandelt\u201d, lautet die offizielle Aussage.<\/p>\n<p>Der umsatzst\u00e4rkste Teil mit Lebensmitteln (Pizzen, Backmischungen, Tiefk\u00fchltorten und Pudding), die Radeberger Gruppe sowie einige Hotels bleiben in der Hand der Gesellschafterst\u00e4mme von Richard und Philip Oetker, Rudolf Louis Schweizer, Markus von Luttitz sowie Ludwig Graf Douglas. 2020 hatte Dr. Oetker einen Umsatz von 3,7 Milliarden Euro vermeldet.<\/p>\n<p>Aus der Hotelgruppe gehen an die j\u00fcngsten Geschwister Alfred, Carl Ferdinand und Julia Johanna Oetker unter dem Namen Geschwister Oetker Beteiligungs KG die Oetker Hotel Management Company und das Hotel Le Bristol in Paris sowie das Ch\u00e2teau du Domaine St. Martin in Vence. Die anderen Gesellschafter behalten das Brenner\u2018s Park Hotel in Baden-Baden und das H\u00f4tel du Cap-Eden-Roc in Antibes. Auch bleibt der gerade \u00fcbernommene Getr\u00e4nkelieferdienst Flaschenpost bei den Gesellschaftst\u00e4mmen um Richard Oetker.<\/p>\n<p>Streit um Ausrichtung besch\u00e4ftigt Oetker-Familie<\/p>\n<p>Der Streit um die Ausrichtung besch\u00e4ftigt die Familie bereits seit vielen Jahren. 2017 trennte sich Dr. Oetker von der Container-Schifffahrt. F\u00fcr 3,7 Milliarden Euro \u00fcbernahm der d\u00e4nische Marktf\u00fchrer Maersk Hamburg-S\u00fcd von den Ostwestfalen, die mit diesem Schritt rund die H\u00e4lfte ihres damaligen Umsatzes einb\u00fc\u00dften.<\/p>\n<p>Rudolf-August Oetker, der Enkel des Firmengr\u00fcnders, hinterlie\u00df bei seinem Tod 2007 acht Erben aus drei Ehen. Seine Kinder erblickten von 1940 bis 1979 das Licht der Welt. Zwischen den Halbgeschwistern liegen zum Teil fast 40 Jahre.<\/p>\n<p>Richard Oetker als Puffer zwischen den Generationen<\/p>\n<p>Ende 2016 musste Richard Oetker (4. Kind aus der 2. Ehe) die Konzernleitung laut Statut mit 65 Jahren aufgeben. Bereits 2010, als er das Ruder an der Spitze \u00fcbernahm, waren sich die Familienst\u00e4mme nicht einig. Er, in der \u00d6ffentlichkeit seit 1976 bekannt als das Entf\u00fchrungsopfer von Dieter Zlof, galt vor sechs Jahren als Puffer zwischen den Generationen und verhinderte Alfred Oetker (1. Kind aus 3. Ehe) an der Spitze. Carl Ferdinand ist das 2. Kind aus 3. Ehe. Nachfolger von Richard als erster familienfremder Manager an der Konzernspitze wurde Anfang 2017 Albert Christmann.<\/p>\n<p>F\u00fcr Dr. Oetker und seine Tochterfirmen arbeiten weltweit rund 37.000 Besch\u00e4ftigte. Die Gesch\u00e4ftsbereiche waren bisher wie folgt aufgeteilt. Nahrungsmittel (Dr. Oetker, Conditorei Coppenrath &amp; Wiese, Martin-Braun-Gruppe), Bier und alkoholfreie Getr\u00e4nke (Radeberger-Gruppe), Sekt, Wein und Spirituosen (Henkell, Freixenet), Luxushotels, Chemische Industrie und Logistik sowie dem Bankhaus Lampe.<\/p>\n<p>Das Bankhaus steht vorbehaltlich der Zustimmung der Aufsichtsbeh\u00f6rden vor dem Verkauf. Dies war bereits vor der Aufspaltung entschieden worden.<\/p>\n<p>absatzwirtschaft+<\/p>\n<p>Sie wollen t\u00e4gliche Insights f\u00fcr Ihre Arbeit im Marketing? Dann\u00a0abonnieren Sie jetzt hier\u00a0unseren kostenfreien Newsletter.<\/p>\n<p>\n<!--noindex--><br \/>\n<a href=\"https:\/\/www.absatzwirtschaft.de\/nach-streit-um-ausrichtung-dr-oetker-wird-aufgesplittet-180934\/\" rel=\"nofollow\">Source link <\/a><br \/>\n<!--\/noindex--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seit Jahren gibt es Ger\u00fcchte um eine Aufsplittung, Streitereien unter den Erben von Rudolf-August Oetker sind kein Geheimnis. Jetzt ist es amtlich. Das Unternehmen wird aufgeteilt. Nach einem jahrzehntelangen Streit um die Ausrichtung von Dr. Oetker wird der Konzern aufgespalten. Das teilte das Unternehmen am Donnerstag in Bielefeld mit. Die Gesellschafter Alfred, Carl Ferdinand und [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2054,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-2053","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-marketing-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dr. Oetker wird aufgesplittet \u203a absatzwirtschaft - Super News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/super-news.info\/de\/dr-oetker-wird-aufgesplittet-absatzwirtschaft\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dr. Oetker wird aufgesplittet \u203a absatzwirtschaft - Super News\" \/>\n<meta property=\"og:description\" content=\"Seit Jahren gibt es Ger\u00fcchte um eine Aufsplittung, Streitereien unter den Erben von Rudolf-August Oetker sind kein Geheimnis. Jetzt ist es amtlich. Das Unternehmen wird aufgeteilt. Nach einem jahrzehntelangen Streit um die Ausrichtung von Dr. Oetker wird der Konzern aufgespalten. Das teilte das Unternehmen am Donnerstag in Bielefeld mit. Die Gesellschafter Alfred, Carl Ferdinand und [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/super-news.info\/de\/dr-oetker-wird-aufgesplittet-absatzwirtschaft\/\" \/>\n<meta property=\"og:site_name\" content=\"Super News\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-22T18:30:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-22T18:30:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/super-news.info\/de\/wp-content\/uploads\/sites\/13\/2021\/07\/Dr-Oetker-wird-aufgesplittet-absatzwirtschaft.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1439\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"super news\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"super news\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/super-news.info\\\/de\\\/dr-oetker-wird-aufgesplittet-absatzwirtschaft\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/de\\\/dr-oetker-wird-aufgesplittet-absatzwirtschaft\\\/\"},\"author\":{\"name\":\"super news\",\"@id\":\"https:\\\/\\\/super-news.info\\\/de\\\/#\\\/schema\\\/person\\\/2b9ff946d06444e803cb306ffcfd1045\"},\"headline\":\"Dr. Oetker wird aufgesplittet \u203a absatzwirtschaft\",\"datePublished\":\"2021-07-22T18:30:50+00:00\",\"dateModified\":\"2021-07-22T18:30:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/de\\\/dr-oetker-wird-aufgesplittet-absatzwirtschaft\\\/\"},\"wordCount\":589,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/de\\\/dr-oetker-wird-aufgesplittet-absatzwirtschaft\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/super-news.info\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2021\\\/07\\\/Dr-Oetker-wird-aufgesplittet-absatzwirtschaft.jpg\",\"articleSection\":[\"MARKETING NEWS\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/super-news.info\\\/de\\\/dr-oetker-wird-aufgesplittet-absatzwirtschaft\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/super-news.info\\\/de\\\/dr-oetker-wird-aufgesplittet-absatzwirtschaft\\\/\",\"url\":\"https:\\\/\\\/super-news.info\\\/de\\\/dr-oetker-wird-aufgesplittet-absatzwirtschaft\\\/\",\"name\":\"Dr. Oetker wird aufgesplittet \u203a absatzwirtschaft - Super News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/de\\\/dr-oetker-wird-aufgesplittet-absatzwirtschaft\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/de\\\/dr-oetker-wird-aufgesplittet-absatzwirtschaft\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/super-news.info\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2021\\\/07\\\/Dr-Oetker-wird-aufgesplittet-absatzwirtschaft.jpg\",\"datePublished\":\"2021-07-22T18:30:50+00:00\",\"dateModified\":\"2021-07-22T18:30:52+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/de\\\/#\\\/schema\\\/person\\\/2b9ff946d06444e803cb306ffcfd1045\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/super-news.info\\\/de\\\/dr-oetker-wird-aufgesplittet-absatzwirtschaft\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/super-news.info\\\/de\\\/dr-oetker-wird-aufgesplittet-absatzwirtschaft\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/super-news.info\\\/de\\\/dr-oetker-wird-aufgesplittet-absatzwirtschaft\\\/#primaryimage\",\"url\":\"https:\\\/\\\/super-news.info\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2021\\\/07\\\/Dr-Oetker-wird-aufgesplittet-absatzwirtschaft.jpg\",\"contentUrl\":\"https:\\\/\\\/super-news.info\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2021\\\/07\\\/Dr-Oetker-wird-aufgesplittet-absatzwirtschaft.jpg\",\"width\":2560,\"height\":1439,\"caption\":\"Dr. Oetker wird aufgesplittet \u203a absatzwirtschaft\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/super-news.info\\\/de\\\/dr-oetker-wird-aufgesplittet-absatzwirtschaft\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/super-news.info\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dr. Oetker wird aufgesplittet \u203a absatzwirtschaft\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/super-news.info\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/super-news.info\\\/de\\\/\",\"name\":\"Super News\",\"description\":\"Super News Germany\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/super-news.info\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/super-news.info\\\/de\\\/#\\\/schema\\\/person\\\/2b9ff946d06444e803cb306ffcfd1045\",\"name\":\"super news\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/98e0b303f300d45b2a94684c5e4dda8baa4a5e9710b579f7493c8612061d08bf?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/98e0b303f300d45b2a94684c5e4dda8baa4a5e9710b579f7493c8612061d08bf?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/98e0b303f300d45b2a94684c5e4dda8baa4a5e9710b579f7493c8612061d08bf?s=96&d=mm&r=g\",\"caption\":\"super news\"},\"url\":\"https:\\\/\\\/super-news.info\\\/de\\\/author\\\/manuel\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dr. Oetker wird aufgesplittet \u203a absatzwirtschaft - Super News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/super-news.info\/de\/dr-oetker-wird-aufgesplittet-absatzwirtschaft\/","og_locale":"de_DE","og_type":"article","og_title":"Dr. Oetker wird aufgesplittet \u203a absatzwirtschaft - Super News","og_description":"Seit Jahren gibt es Ger\u00fcchte um eine Aufsplittung, Streitereien unter den Erben von Rudolf-August Oetker sind kein Geheimnis. Jetzt ist es amtlich. Das Unternehmen wird aufgeteilt. Nach einem jahrzehntelangen Streit um die Ausrichtung von Dr. Oetker wird der Konzern aufgespalten. Das teilte das Unternehmen am Donnerstag in Bielefeld mit. Die Gesellschafter Alfred, Carl Ferdinand und [&hellip;]","og_url":"https:\/\/super-news.info\/de\/dr-oetker-wird-aufgesplittet-absatzwirtschaft\/","og_site_name":"Super News","article_published_time":"2021-07-22T18:30:50+00:00","article_modified_time":"2021-07-22T18:30:52+00:00","og_image":[{"width":2560,"height":1439,"url":"https:\/\/super-news.info\/de\/wp-content\/uploads\/sites\/13\/2021\/07\/Dr-Oetker-wird-aufgesplittet-absatzwirtschaft.jpg","type":"image\/jpeg"}],"author":"super news","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"super news","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/super-news.info\/de\/dr-oetker-wird-aufgesplittet-absatzwirtschaft\/#article","isPartOf":{"@id":"https:\/\/super-news.info\/de\/dr-oetker-wird-aufgesplittet-absatzwirtschaft\/"},"author":{"name":"super news","@id":"https:\/\/super-news.info\/de\/#\/schema\/person\/2b9ff946d06444e803cb306ffcfd1045"},"headline":"Dr. Oetker wird aufgesplittet \u203a absatzwirtschaft","datePublished":"2021-07-22T18:30:50+00:00","dateModified":"2021-07-22T18:30:52+00:00","mainEntityOfPage":{"@id":"https:\/\/super-news.info\/de\/dr-oetker-wird-aufgesplittet-absatzwirtschaft\/"},"wordCount":589,"commentCount":0,"image":{"@id":"https:\/\/super-news.info\/de\/dr-oetker-wird-aufgesplittet-absatzwirtschaft\/#primaryimage"},"thumbnailUrl":"https:\/\/super-news.info\/de\/wp-content\/uploads\/sites\/13\/2021\/07\/Dr-Oetker-wird-aufgesplittet-absatzwirtschaft.jpg","articleSection":["MARKETING NEWS"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/super-news.info\/de\/dr-oetker-wird-aufgesplittet-absatzwirtschaft\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/super-news.info\/de\/dr-oetker-wird-aufgesplittet-absatzwirtschaft\/","url":"https:\/\/super-news.info\/de\/dr-oetker-wird-aufgesplittet-absatzwirtschaft\/","name":"Dr. Oetker wird aufgesplittet \u203a absatzwirtschaft - Super News","isPartOf":{"@id":"https:\/\/super-news.info\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/super-news.info\/de\/dr-oetker-wird-aufgesplittet-absatzwirtschaft\/#primaryimage"},"image":{"@id":"https:\/\/super-news.info\/de\/dr-oetker-wird-aufgesplittet-absatzwirtschaft\/#primaryimage"},"thumbnailUrl":"https:\/\/super-news.info\/de\/wp-content\/uploads\/sites\/13\/2021\/07\/Dr-Oetker-wird-aufgesplittet-absatzwirtschaft.jpg","datePublished":"2021-07-22T18:30:50+00:00","dateModified":"2021-07-22T18:30:52+00:00","author":{"@id":"https:\/\/super-news.info\/de\/#\/schema\/person\/2b9ff946d06444e803cb306ffcfd1045"},"breadcrumb":{"@id":"https:\/\/super-news.info\/de\/dr-oetker-wird-aufgesplittet-absatzwirtschaft\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/super-news.info\/de\/dr-oetker-wird-aufgesplittet-absatzwirtschaft\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/super-news.info\/de\/dr-oetker-wird-aufgesplittet-absatzwirtschaft\/#primaryimage","url":"https:\/\/super-news.info\/de\/wp-content\/uploads\/sites\/13\/2021\/07\/Dr-Oetker-wird-aufgesplittet-absatzwirtschaft.jpg","contentUrl":"https:\/\/super-news.info\/de\/wp-content\/uploads\/sites\/13\/2021\/07\/Dr-Oetker-wird-aufgesplittet-absatzwirtschaft.jpg","width":2560,"height":1439,"caption":"Dr. Oetker wird aufgesplittet \u203a absatzwirtschaft"},{"@type":"BreadcrumbList","@id":"https:\/\/super-news.info\/de\/dr-oetker-wird-aufgesplittet-absatzwirtschaft\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/super-news.info\/de\/"},{"@type":"ListItem","position":2,"name":"Dr. Oetker wird aufgesplittet \u203a absatzwirtschaft"}]},{"@type":"WebSite","@id":"https:\/\/super-news.info\/de\/#website","url":"https:\/\/super-news.info\/de\/","name":"Super News","description":"Super News Germany","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/super-news.info\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/super-news.info\/de\/#\/schema\/person\/2b9ff946d06444e803cb306ffcfd1045","name":"super news","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/98e0b303f300d45b2a94684c5e4dda8baa4a5e9710b579f7493c8612061d08bf?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/98e0b303f300d45b2a94684c5e4dda8baa4a5e9710b579f7493c8612061d08bf?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/98e0b303f300d45b2a94684c5e4dda8baa4a5e9710b579f7493c8612061d08bf?s=96&d=mm&r=g","caption":"super news"},"url":"https:\/\/super-news.info\/de\/author\/manuel\/"}]}},"_links":{"self":[{"href":"https:\/\/super-news.info\/de\/wp-json\/wp\/v2\/posts\/2053","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/super-news.info\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/super-news.info\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/super-news.info\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/super-news.info\/de\/wp-json\/wp\/v2\/comments?post=2053"}],"version-history":[{"count":1,"href":"https:\/\/super-news.info\/de\/wp-json\/wp\/v2\/posts\/2053\/revisions"}],"predecessor-version":[{"id":2055,"href":"https:\/\/super-news.info\/de\/wp-json\/wp\/v2\/posts\/2053\/revisions\/2055"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/super-news.info\/de\/wp-json\/wp\/v2\/media\/2054"}],"wp:attachment":[{"href":"https:\/\/super-news.info\/de\/wp-json\/wp\/v2\/media?parent=2053"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/super-news.info\/de\/wp-json\/wp\/v2\/categories?post=2053"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/super-news.info\/de\/wp-json\/wp\/v2\/tags?post=2053"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}